{"id":13683,"date":"2011-11-10T19:37:24","date_gmt":"2011-11-10T23:37:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-estres-es-tan-contagioso-como-la-gripe\/"},"modified":"2014-12-02T09:52:57","modified_gmt":"2014-12-02T13:52:57","slug":"el-estres-es-tan-contagioso-como-la-gripe","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-estres-es-tan-contagioso-como-la-gripe\/","title":{"rendered":"El estr\u00e9s es tan contagioso como la gripe."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13682\" style=\"float: left;\" class=\"caption\" alt=\"estres-oficina-alamy456\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/estres-oficina-alamy456.jpg\" width=\"456\" height=\"319\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/estres-oficina-alamy456.jpg 456w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/estres-oficina-alamy456-300x209.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/estres-oficina-alamy456-75x52.jpg 75w\" sizes=\"auto, (max-width: 456px) 100vw, 456px\" \/>Tu jefe est\u00e1 estresado? Pues cuidado, que podr\u00eda contagiarte&#8230; Aunque no lo creas, un nuevo estudio ha revelado que el estr\u00e9s no s\u00f3lo es tan com\u00fan como un resfriado, sino que tambi\u00e9n es igual de contagioso que la gripa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan publica Marie Claire, la psic\u00f3loga Elaine Hatfield de la Universidad de Hawaii, al sentarte en un espacio peque\u00f1o en el trabajo corres el riesgo de contagiarte de estr\u00e9s, ya que este circula r\u00e1pidamente en las oficinas.<\/p>\n<p>\u00abLa gente parece ser capaz de imitar las expresiones faciales, vocales y de postura de otras personas con una rapidez impresionante\u00bb, dijo la experta. \u00abComo consecuencia de ello, son capaces de sentir las emociones de los otros en un grado sorprendente\u00bb.<\/p>\n<p>El estudio sugiere que somos como esponjas que absorbemos las emociones que nos rodean, seg\u00fan publica MC. A medida que absorbemos el estr\u00e9s de los dem\u00e1s, comenzamos a enfocarnos en las cosas que tambi\u00e9n nos causan conflicto o nos preocupan. Esto se debe al flujo de descontento, que act\u00faa como depresivo.<\/p>\n<p>\u00bfY saben qu\u00e9 es lo peor? Que las mujeres estamos en mayor riesgo de contagiarnos del estr\u00e9s de nuestros amigos, familiares o compa\u00f1eros de trabajo, porque seg\u00fan la profesora Hatfield, nosotras tendemos m\u00e1s a estar en sinton\u00eda con los sentimientos de otros.<\/p>\n<p>As\u00ed que ya sabes, evita una actitud negativa en la oficina, y cuando notes tensi\u00f3n en el ambiente, sal a caminar y distraerte un poco. Recuerda tambi\u00e9n que tener tu escritorio limpio te ayudar\u00e1 a tener la cabeza despejada.<\/p>\n<p>fuente: <a href=\"http:\/\/salud.aollatino.com\/2011\/11\/10\/estres-tan-contagioso-como-resfriado\/\">http:\/\/salud.aollatino.com\/2011\/11\/10\/estres-tan-contagioso-como-resfriado\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tu jefe est\u00e1 estresado? Pues cuidado, que podr\u00eda contagiarte&#8230; Aunque no lo creas, un nuevo estudio ha revelado que el estr\u00e9s no s\u00f3lo es tan com\u00fan como un resfriado, sino que tambi\u00e9n es igual de contagioso que la gripa.<\/p>\n","protected":false},"author":3,"featured_media":13682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-13683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13683"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13683\/revisions"}],"predecessor-version":[{"id":33900,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13683\/revisions\/33900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13682"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}