{"id":13860,"date":"2011-11-21T04:00:00","date_gmt":"2011-11-21T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/recomiendan-retrasar-el-corte-del-cordon-umbilical\/"},"modified":"2011-11-21T04:00:00","modified_gmt":"2011-11-21T08:00:00","slug":"recomiendan-retrasar-el-corte-del-cordon-umbilical","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/recomiendan-retrasar-el-corte-del-cordon-umbilical\/","title":{"rendered":"Recomiendan retrasar el corte del cord\u00f3n umbilical"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-13859\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/recien_nacido.jpg\" width=\"304\" height=\"171\" alt=\"recien_nacido\" class=\"caption\" style=\"vertical-align: bottom;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/recien_nacido.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/recien_nacido-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Retrasar unos minutos el corte del cord\u00f3n umbilical cuando nace un beb\u00e9 puede ofrecer beneficios a su salud, afirma una investigaci\u00f3n.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>En reci\u00e9n nacidos sanos, esperar al menos tres minutos antes del corte puede mejorar sus niveles de hierro y evitar el riesgo de una anemia por deficiencia de este mineral, afirma la investigaci\u00f3n publicada en British Medical Jorunal (BMJ) (Revista M\u00e9dica Brit\u00e1nica).<\/div>\n<div><\/div>\n<div>Aunque hasta ahora los estudios han mostrado que el retraso del corte umbilical puede prevenir la deficiencia de hierro, hab\u00eda resultados contradictorios que dec\u00edan que este retraso pod\u00eda elevar el riesgo de ictericia neonatal y de otros problemas de salud.<\/div>\n<div><\/div>\n<div>Pero la nueva investigaci\u00f3n afirma que retrasar el corte no est\u00e1 vinculado a estos efectos adversos en la salud del reci\u00e9n nacido.<\/div>\n<div><\/div>\n<div>La deficiencia de hierro y la anemia causada por esta deficiencia son problemas de salud importantes en muchos ni\u00f1os alrededor del mundo.<\/div>\n<div><\/div>\n<div>Estos trastornos est\u00e1n asociados a un pobre desarrollo del sistema nervioso y problemas de crecimiento.<\/div>\n<div>Hace algunos a\u00f1os la Organizaci\u00f3n Mundial de la Salud retir\u00f3 de sus recomendaciones el corte temprano del cord\u00f3n umbilical.<\/div>\n<div><\/div>\n<div>Pero en muchos pa\u00edses no existen lineamientos formales sobre cu\u00e1ndo debe llevarse a cabo esta separaci\u00f3n.<\/div>\n<div><\/div>\n<div>En el Reino Unido, por ejemplo, se ha encontrado que varios hospitales llevan a cabo el corte inmediatamente despu\u00e9s del parto.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Mejora sangu\u00ednea<\/strong><\/span><\/div>\n<div><\/div>\n<div>Se calcula que en el mundo cerca de 25% de los ni\u00f1os en edad preescolar tienen anemia por deficiencia de hierro, la forma m\u00e1s severa de deficiencia de este mineral.<\/div>\n<div><\/div>\n<div>\u00abEl retraso del corte umbilical debe ser considerado como atenci\u00f3n est\u00e1ndar para los nacimientos a t\u00e9rmino despu\u00e9s de embarazos que no presenten complicaciones\u00bb<\/div>\n<div><\/div>\n<div>Dres. Ola Andersson y Magnus Domell\u00f6f<\/div>\n<div>&nbsp;<\/div>\n<div>Una soluci\u00f3n simple para este trastorno, afirman los expertos, es asegurarse de que los beb\u00e9s comienzan su vida con un abastecimiento m\u00e1ximo de reservas de hierro en la sangre, las cuales pueden obtener de la placenta.<\/div>\n<div><\/div>\n<div>Los cient\u00edficos del Hospital de Halland y la Universidad de Umea en Suecia, estudiaron los efectos de retrasar el corte umbilical en el nivel de hierro en infantes que hab\u00edan cumplido cuatro meses de edad y los compararon con los de infantes que hab\u00edan tenido un corte inmediato tras el parto.<\/div>\n<div><\/div>\n<div>El estudio incluy\u00f3 a 400 beb\u00e9s nacidos a t\u00e9rmino con embarazos de bajo riesgo. Algunos hab\u00edan tenido el corte umbilical despu\u00e9s de al menos tres minutos y otros a menos de diez segundos tras el parto.<\/div>\n<div><\/div>\n<div>Los resultados mostraron que los beb\u00e9s a quienes se retras\u00f3 el corte ten\u00edan mejores niveles de hierro a los cuatro meses de edad y tuvieron menos casos de anemia neonatal.<\/div>\n<div><\/div>\n<div>Los cient\u00edficos calculan que si se deja al neonato unido al cord\u00f3n durante al menos tres minutos despu\u00e9s del parto se puede mejorar el volumen de hierro sangu\u00edneo en 35%.<\/div>\n<div><\/div>\n<div>Adem\u00e1s, el estudio no encontr\u00f3 que el retraso en el corte estuviera asociado con efectos adversos de salud.<\/div>\n<div><\/div>\n<div>Seg\u00fan los autores \u00abel retraso del corte umbilical debe ser considerado como atenci\u00f3n est\u00e1ndar para los nacimientos a t\u00e9rmino despu\u00e9s de embarazos que no presenten complicaciones\u00bb.<\/div>\n<div><\/div>\n<div>El Colegio Real de Obstetras y Ginec\u00f3logos del Reino Unido no tiene recomendaciones espec\u00edficas sobre cu\u00e1ndo debe hacerse el corte umbilical, pero est\u00e1 pidiendo que se lleven a cabo m\u00e1s estudios sobre este tema.<\/div>\n<div><\/div>\n<div>\u00abLa deficiencia de hierro en los primeros meses de vida est\u00e1 asociado al retraso en el neurodesarrollo, que puede ser irreversible\u00bb dice el organismo.<\/div>\n<div><\/div>\n<div>\u00abNo se sabe si incrementando la transfusi\u00f3n placentaria al retrasar el corte umbilical puede mejorar el neurodesarrollo en la primera infancia pero esta hip\u00f3tesis deber\u00eda ser investigada en ensayos aleatorios m\u00e1s amplios\u00bb agrega.<\/div>\n<div><\/div>\n<div>Fuente: BBCSalud<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrasar unos minutos el corte del cord\u00f3n umbilical cuando nace un beb\u00e9 puede ofrecer beneficios a su salud, afirma una investigaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":13859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13860"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13859"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}