{"id":13876,"date":"2011-11-21T13:58:58","date_gmt":"2011-11-21T17:58:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dice-quinito-que-en-las-fiestas-con-casablanca-se-hacian-hasta-un-millon-en-la-puerta\/"},"modified":"2011-11-21T13:58:58","modified_gmt":"2011-11-21T17:58:58","slug":"dice-quinito-que-en-las-fiestas-con-casablanca-se-hacian-hasta-un-millon-en-la-puerta","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dice-quinito-que-en-las-fiestas-con-casablanca-se-hacian-hasta-un-millon-en-la-puerta\/","title":{"rendered":"Dice Quinito que en las fiestas con Casablanca se hac\u00edan hasta un mill\u00f3n en la puerta"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13875\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/Kinito547568.jpeg\" width=\"460\" height=\"309\" alt=\"Kinito547568\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/Kinito547568.jpeg 460w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/Kinito547568-300x201.jpeg 300w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/>El merenguero Kinito M\u00e9ndez revel\u00f3 en el programa M\u00e1s Roberto que en las fiestas junto a Cristian Casablanca se hac\u00edan hasta un mill\u00f3n de pesos en la puerta, \u201ceso era una locura\u201d; pero \u201caunque eran un buen negocio\u201d dej\u00f3 de amenizarlas luego del reportaje en el programa de Nuria Piera y los comentarios de otros reconocidos periodistas.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Aclar\u00f3 que hace m\u00fasica de palos por lo cultural del dominicano y no por lo religioso, ni las creencias de brujer\u00eda\u201d; aunque dijo que \u201cla combinaci\u00f3n en esas fiestas daban muchos resultados; pero era bien solo con \u00e9l\u201d. \u201cLo ha hecho con To\u00f1o Rosario, Sergio Vargas, Juliana y El Sujeto pero la vaina es conmigo, dijo Kinito.<\/div>\n<div><\/div>\n<div><\/div>\n<div>En el estudio se trajo a Cristian Casablanca, qui\u00e9n dijo que la idea de esas fiestas fue suya, la mezcla con Kinito es inigualable, rompiendo record de bailes simult\u00e1neamente y en el centro de diversi\u00f3n Monte Bar de Santiago donde llevaron 2,800 personas. \u201cDepende de Nuria Piera que vuelvan las fiestas con Casablanca\u201d apunt\u00f3 el llamado \u201cHombre Merengue\u201d.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Visto en Ensegundos.net<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El merenguero Kinito M\u00e9ndez revel\u00f3 en el programa M\u00e1s Roberto que en las fiestas junto a Cristian Casablanca se hac\u00edan hasta un mill\u00f3n de pesos en la puerta, \u201ceso era una locura\u201d; pero \u201caunque eran un buen negocio\u201d dej\u00f3 de amenizarlas luego del reportaje en el programa de Nuria Piera y los comentarios de otros reconocidos periodistas.<\/p>\n","protected":false},"author":3,"featured_media":13875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13876"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13875"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}