{"id":13880,"date":"2011-11-21T14:37:20","date_gmt":"2011-11-21T18:37:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/pastillas-para-ser-inteligentes-el-debate\/"},"modified":"2011-11-21T14:37:20","modified_gmt":"2011-11-21T18:37:20","slug":"pastillas-para-ser-inteligentes-el-debate","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pastillas-para-ser-inteligentes-el-debate\/","title":{"rendered":"Pastillas para ser inteligentes: el debate"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13879\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/111115163110_brain_pill_promos__464x261_spl.jpg\" width=\"464\" height=\"261\" alt=\"111115163110_brain_pill_promos__464x261_spl\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/111115163110_brain_pill_promos__464x261_spl.jpg 464w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/111115163110_brain_pill_promos__464x261_spl-300x168.jpg 300w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/>Nootr\u00f3picos, drogas inteligentes, estimulantes de la memoria, potenciadores cognictivos. Sea como sea que se les denomine, lo que ofrecen es elevar nuestras funciones mentales&#8230; y \u00a1cu\u00e1n dif\u00edcil es decir &#8216;no&#8217; a la posibilidad de ser m\u00e1s brillante de lo que naturalmente se es!<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>La mayor\u00eda de nosotros queremos alcanzar nuestro potencial real. Quiz\u00e1s nos tomemos una taza de caf\u00e9 para mantenernos despiertos y alertas, o salgamos a trotar para sentirnos m\u00e1s vigorosos. As\u00ed que la idea de tomarse una pastilla que nos haga m\u00e1s listos podr\u00eda considerarse lo mismo.<\/div>\n<div><\/div>\n<div>Los potenciadores cognictivos ya se prescriben para tratar trastornos m\u00e9dicos, pero tambi\u00e9n tienen el poder de mejorar la memoria o la capacidad de concentrarse de las personas sanas.<\/div>\n<div><\/div>\n<div>Mucha gente las compra en internet, lo que es arriesgado, pues no saben qu\u00e9 est\u00e1n tomando realmente.<\/div>\n<div><\/div>\n<div>Adem\u00e1s, a\u00fan no se sabe casi nada sobre los efectos a largo plazo que estas drogas puedan tener en el cerebro de una persona saludable, particularmente en los j\u00f3venes.<\/div>\n<div><\/div>\n<div>Sin embargo, algunos cient\u00edficos piensan que podr\u00edan llegar a jugar un papel beneficioso en la sociedad, si se regularan apropiadamente.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>\u00bfSe la tomar\u00eda?<\/strong><\/span><\/div>\n<div><\/div>\n<div><\/div>\n<div>Usted es un piloto de combate en una larga misi\u00f3n. Su vida y la de los otros pilotos depende de que usted se mantenga alerta. Hay drogas que lo ayudar\u00edan a permanecer despierto y concentrado. \u00bfSe las tomar\u00eda?<\/div>\n<div><\/div>\n<div>Susan Watts, de la BBC, habl\u00f3 con un estudiante sobre su experiencia con modafinil, que normalmente se prescribe para des\u00f3rdenes del sue\u00f1o. Laurie Pycoft cursa su segundo a\u00f1o de estudios en la Universidad de Oxford, donde estudia ciencias psicol\u00f3gicas, con inter\u00e9s en la neurofarmacolog\u00eda.<\/div>\n<div><\/div>\n<div>\u00abHe tomado modafinil algunas veces, particularmente porque aumenta la capacidad de mantenerse en vigilia y porque me permite permanecer concentrado durante largos per\u00edodos de tiempo. No la tomo muy a menudo, pero si quiero quedarme despierto durante 20 o 30 horas, trabajando en un ensayo, es muy \u00fatil\u00bb.<\/div>\n<div><\/div>\n<div>Entre tanto, en la Universidad de Cambridge, Barbara Sahakian trabaja en la unidad de ciencias del cerebro y la mente.<\/div>\n<div><\/div>\n<div>\u00abNosotros hemos hecho estudios que muestran que pueden ayudar a personas sanas pero son pruebas cortas. Tomarlas a largo plazo (como lo ha hecho Pycoft y otros estudiantes) puede ser peligroso. No se sabe pues no se han hecho pruebas y adem\u00e1s, los cerebros en las personas j\u00f3venes todav\u00eda se est\u00e1n desarrollando\u00bb, le dice a la BBC.<\/div>\n<div><\/div>\n<div>Con su equipo, Sahakian se ocupa de pacientes que sufren de trastornos como la enfermedad de Alzheirmer y Parkinson, en los que la cognici\u00f3n es severamente afectada.<\/div>\n<div><\/div>\n<div>Investiga si la misma droga que usa Pycoft para hacer tareas le sirve a los pacientes.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Los que pueden y los que no<\/strong><\/span><\/div>\n<div>&nbsp;<\/div>\n<div>El modafinil ya se usa para tratar a personas con desordenes del sue\u00f1o.<\/div>\n<div><\/div>\n<div>Pero Sahakian no es de las que piensan que los nootr\u00f3picos deben restringirse al uso terap\u00e9utico. Opina que podr\u00edan jugar un papel m\u00e1s amplio en la sociedad.<\/div>\n<div><\/div>\n<div>Sus m\u00e1s recientes estudios mostraron que cirujanos que no hab\u00edan podido dormir lo suficiente operaban mejor si tomaban modafinil.<\/div>\n<div><\/div>\n<div>\u00abCreo que los subestimamos. Un estudio de la Academia de Ciencias M\u00e9dicas de 2008 mostr\u00f3 que incluso con una peque\u00f1a mejora del 10% en una prueba de memoria se consigue un puntaje m\u00e1s alto en un examen acad\u00e9mico y eso es una gran mejora\u00bb, dice la experta en neuropsicolog\u00eda cl\u00ednica en conversaci\u00f3n con la BBC.<\/div>\n<div><\/div>\n<div>Pero eso puede traer problemas. Ya hay preocupaci\u00f3n de que, si las cosas contin\u00faan como van, se podr\u00eda terminar con una sociedad que avanza a dos velocidades.<\/div>\n<div><\/div>\n<div>Graham Lawton, editor de la prestigiosa publicaci\u00f3n New Scientist, se\u00f1ala que \u00abhay gente que no s\u00f3lo est\u00e1 dispuesta a tomar estas pastillas sino que pueden comprarlas. Son un grupo selecto de pioneros. Eso trae a la mesa una serie de cuestionamientos sociales y \u00e9ticos, que van m\u00e1s all\u00e1 de las preocupaciones por la salud\u00bb.<\/div>\n<div><\/div>\n<div>Lawton se refiere a las ventajas que tendr\u00edan quienes tienen acceso a esas sustancias. \u00abTenemos que empezar a pensar si deber\u00eda permit\u00edrselas que tomaran esas drogas si van a presentar ex\u00e1menes, por ejemplo&#8230; \u00bfno es lo mismo que el dopaje en el deporte?\u00bb.<\/div>\n<div><\/div>\n<div>\u00abComo sociedad, podr\u00edamos quiz\u00e1s avanzar si todos tuvi\u00e9ramos alguna forma de potenciar la inteligencia libre de riesgos\u00bb, opina Sahakian.<\/div>\n<div><\/div>\n<div>No obstante, no ser\u00eda sencillo: como se\u00f1ala la misma doctora, habr\u00eda que lidiar por ejemplo con el problema de la coerci\u00f3n.<\/div>\n<div><\/div>\n<div>\u00abEn un sondeo de la revista Nature surgi\u00f3 un dato interesante. A la pregunta &#8216;\u00bfse le debe dar estas drogas a los ni\u00f1os si son seguras?&#8217;, la mayor\u00eda de la gente respondi\u00f3 &#8216;no&#8217;. A la pregunta &#8216;\u00bfSe las dar\u00eda a sus hijos si otros en su curso las estuvieran tomando?&#8217;, la mayor\u00eda contest\u00f3 &#8216;s\u00ed'\u00bb.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Pastillas morales<\/strong><\/span><\/div>\n<div><span style=\"font-size: 14pt;\"><strong><br \/><\/strong><\/span><\/div>\n<div>Otro de los senderos que se est\u00e1n explorando es el de los potenciadores morales, con cient\u00edficos pregunt\u00e1ndose si manipular hormonas podr\u00eda ayudarnos a ser m\u00e1s amables, m\u00e1s considerados.<\/div>\n<div><\/div>\n<div>&nbsp;\u00abObviamente ya usamos &#8216;potenciadores&#8217; -como gafas, ejercicio, educaci\u00f3n-, pero hay una l\u00ednea que se cruza cuando se trata de tomarse una sustancia todo el tiempo para ser un ser humano superior y diferente\u00bb<\/div>\n<div><\/div>\n<div>Brian Appleyard<\/div>\n<div><\/div>\n<div>\u00abUno puede imaginarse por ejemplo que se puede reducir el nivel de testosterona, que generalmente nos hace m\u00e1s agresivos, menos concientes de los rostros de la gente, por ende, menos interesados en entender al otro, y m\u00e1s arriesgados\u00bb, le explica a la BBC Anders Sandberg, de la Universidad de Oxford.<\/div>\n<div><\/div>\n<div>Pero ante la idea, hay quienes, como Brian Appleyard, autor de \u00abPor qu\u00e9 las soluciones simples no funcionan en un mundo complejo\u00bb, se declaran confundidos.<\/div>\n<div><\/div>\n<div>\u00abS\u00f3lo tenemos una vara para medir la conciencia humana, y estamos usando la palabra &#8216;potenciar&#8217;, asi que el resultado ser\u00eda algo sobrehumano. \u00bfC\u00f3mo ser\u00eda la conciencia humana mejorada? \u00bfOsama bin Laden o la madre Teresa?\u00bb.<\/div>\n<div><\/div>\n<div>Otros expertos como John Harris de la Universidad de Manchester se\u00f1alan que es un sendero que lleva al mismo destino.<\/div>\n<div><\/div>\n<div>\u00abLa gente no est\u00e1 moralmente potenciada necesariamente porque la induzcan a hacer cosas que otros aprueban. Para m\u00ed, est\u00e1 moralmente potenciada en la medida en que sea m\u00e1s capaz de formular juicios morales, es decir, m\u00e1s capaz de considerar alternativas, evaluar las consecuencias de sus acciones, entender el contexto en el que act\u00faa. La mayor parte de eso se logra mejor con potenciadores cognotivos que morales\u00bb.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Los l\u00edmites<\/strong><\/span><\/div>\n<div><span style=\"font-size: 14pt;\"><strong><br \/><\/strong><\/span><\/div>\n<div>Pero Appleyard no est\u00e1 convencido. Quiere decir esto que, suponiendo que las pastillas pudieran ser obtenidas apropiadamente y que no representen ning\u00fan riesgo&#8230; \u00bfno le interesar\u00eda ser m\u00e1s inteligente?<\/div>\n<div><\/div>\n<div>&nbsp;\u00abEs dif\u00edcil pensar en cu\u00e1l ser\u00eda un l\u00edmite plausible para imponerle a nuestro poder cognoctivo y si lo podemos mejorar, y al hacerlo acortar el tiempo que nos toma aprender, permitir que la educaci\u00f3n parta de un nivel m\u00e1s alto, etc., entonces no s\u00f3lo podr\u00eda ser bueno para los individuos sino tambi\u00e9n para la sociedad\u00bb<\/div>\n<div><\/div>\n<div>John Harris<\/div>\n<div>\u00abLo que me preocupa es a qu\u00e9 lleva. Yo no tengo ni la remota idea de qu\u00e9 es &#8216;realzar, mejorar o potenciar&#8217; a un ser humano. Pero pienso que convencer a la gente de que pueden vivir mejor si se toman un qu\u00edmico es pasarse del l\u00edmite. Obviamente ya usamos &#8216;potenciadores&#8217; -como gafas, ejercicio, educaci\u00f3n-, pero hay una l\u00ednea que se cruza cuando se trata de tomarse una sustancia todo el tiempo para ser un ser humano superior y diferente\u00bb, le responde a Susan Watts de la BBC.<\/div>\n<div><\/div>\n<div>No obstante, el bi\u00f3logo \u00e9tico Harris apunta que \u00abes dif\u00edcil pensar en cu\u00e1l ser\u00eda un l\u00edmite plausible para imponerle a nuestro poder cognoctivo y si lo podemos mejorar, y al hacerlo acortar el tiempo que nos toma aprender, permitir que la educaci\u00f3n parta de un nivel m\u00e1s alto, etc., entonces no s\u00f3lo podr\u00eda ser bueno para los individuos sino tambi\u00e9n para la sociedad\u00bb.<\/div>\n<div><\/div>\n<div>Intentar superar nuestras limitaciones es parte de la naturaleza humana pero <span style=\"font-size: 10pt;\"><strong>\u00bfy los riesgos?<\/strong><\/span><\/div>\n<div><\/div>\n<div>Los reguladores necesitar\u00e1n estudios a largo plazo en personas sanas para poder evaluar los riesgos y beneficios antes de considerar otorgar licencias.<\/div>\n<div><\/div>\n<div>Las compa\u00f1\u00edas farmac\u00e9uticas no est\u00e1n realmente \u00e1vidas de hacer tales pruebas, pero Sahakian est\u00e1 llamando a que se hagan, antes de que alguien se haga da\u00f1o.<\/div>\n<div><\/div>\n<div>La atracci\u00f3n de una p\u00edldora que nos haga m\u00e1s inteligentes no se esfumar\u00e1.<\/div>\n<div><\/div>\n<div>Quiz\u00e1s a muchos por ahora no les atraiga mucho la idea, pues por ahora se trata de una sustancia que hace una diferencia de apenas un poco por ciento. Pero, si encontraran una pastilla que nos volviera 50% o 100% m\u00e1s inteligentes, \u00bfseguir\u00edan dici\u00e9ndo que no?<\/div>\n<div><\/div>\n<div>fuente: <a href=\"http:\/\/www.elmundo.es\">www.elmundo.es<\/a>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nootr\u00f3picos, drogas inteligentes, estimulantes de la memoria, potenciadores cognictivos. Sea como sea que se les denomine, lo que ofrecen es elevar nuestras funciones mentales&#8230; y \u00a1cu\u00e1n dif\u00edcil es decir &#8216;no&#8217; a la posibilidad de ser m\u00e1s brillante de lo que naturalmente se es!<\/p>\n","protected":false},"author":3,"featured_media":13879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13880"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13879"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}