{"id":13896,"date":"2011-11-22T18:54:20","date_gmt":"2011-11-22T22:54:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/lio-entre-tony-dize-y-pina-records-qpica-y-se-extiendeq\/"},"modified":"2011-11-22T18:54:20","modified_gmt":"2011-11-22T22:54:20","slug":"lio-entre-tony-dize-y-pina-records-qpica-y-se-extiendeq","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lio-entre-tony-dize-y-pina-records-qpica-y-se-extiendeq\/","title":{"rendered":"L\u00edo entre Tony Dize y Pina Records \u00abpica y se extiende\u00bb"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13895\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/tony-dize657658.jpg\" width=\"400\" height=\"280\" alt=\"tony-dize657658\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/tony-dize657658.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/tony-dize657658-300x210.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/tony-dize657658-75x52.jpg 75w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Rafael Pina y sus empresas World Management Latino Corp. y World Music Corp. informan que Tony Feliciano Rivera, mejor conocido como Tony Dize, contin\u00faa bajo acuerdo contractual discogr\u00e1fico, de manejo y de contrataciones de manera exclusiva con estas entidades.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Anteriormente Tony Dize tuvo contratos de exclusividad con WY Records &amp; Management Team, sin embargo, en el 2009 estos acuerdos fueron negociados y cedidos a Pina Records y afiliadas, empresas que desde entonces han desarrollado la carrera del artista a un alto nivel dentro de la industria musical.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Cabe destacar que los m\u00faltiples obst\u00e1culos auto-impuestos por el propio artista han causado que sus decisiones erroneas lastimen el esfuerzo y trabajo profesional realizado por Pina y sus empresas. Inclusive se ha intentado entrar en dialogo cordial con el artista, sin embargo este ha optado por utilizar terceras personas carentes de credibilidad en la industria.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Pina no escatimar\u00e1 en tomar las acciones legales pertinentes contra todas las personas que han y contin\u00faan interfiriendo en la relaci\u00f3n entre el artista y las empresas mencionadas.<\/div>\n<div><\/div>\n<div>fuente: <a href=\"http:\/\/www.fuegoalalata.net\">www.fuegoalalata.net<\/a>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rafael Pina y sus empresas World Management Latino Corp. y World Music Corp. informan que Tony Feliciano Rivera, mejor conocido como Tony Dize, contin\u00faa bajo acuerdo contractual discogr\u00e1fico, de manejo y de contrataciones de manera exclusiva con estas entidades.<\/p>\n","protected":false},"author":3,"featured_media":13895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13896"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13895"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}