{"id":13952,"date":"2011-11-26T04:06:50","date_gmt":"2011-11-26T08:06:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/liceo-gregorio-luperon-rinde-homenajes-al-qdia-de-la-no-violencia-contra-la-mujerq\/"},"modified":"2011-11-26T04:06:50","modified_gmt":"2011-11-26T08:06:50","slug":"liceo-gregorio-luperon-rinde-homenajes-al-qdia-de-la-no-violencia-contra-la-mujerq","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/liceo-gregorio-luperon-rinde-homenajes-al-qdia-de-la-no-violencia-contra-la-mujerq\/","title":{"rendered":"Liceo Gregorio Luper\u00f3n rinde homenajes al \u00abD\u00eda de la No Violencia Contra La Mujer\u00bb (VER IM\u00c1GENES Y VIDEOS)"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13951\" style=\"float: left;\" class=\"caption\" title=\"Desfile y Acto de &quot;NO VIOLENCIA CONTRA LA MUJER&quot;\" alt=\"P1060660\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/P1060660.jpg\" width=\"780\" height=\"565\" \/>Sos\u00faa.- En la ma\u00f1ana de este viernes 25 de noviembre se efectu\u00f3 un desfile y posteriormente un acto para conmemorar una ocasi\u00f3n m\u00e1s del \u00abD\u00eda de la no violencia contra la mujer\u00bb.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Los j\u00f3venes honraron la memoria de \u00abLas Hermanas Mirabal\u00bb las cuales cumplen 51 a\u00f1os de asesinadas este 25 de noviembre y a las cuales se recuerdan a nivel internacional con esta fecha en su honor.<\/div>\n<div>&nbsp;<\/div>\n<div><object width=\"579\" height=\"362\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157628154569711%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157628154569711%2F&amp;set_id=72157628154569711&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"579\" height=\"362\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157628154569711%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157628154569711%2F&amp;set_id=72157628154569711&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/div>\n<div>&nbsp;<\/div>\n<div><object width=\"581\" height=\"359\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/LhMYF8Dl8PU\" \/><embed width=\"581\" height=\"359\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/LhMYF8Dl8PU\" wmode=\"opaque\"\/><\/object><\/p>\n<p><object width=\"578\" height=\"352\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/_g6SvcfOaZI\" \/><embed width=\"578\" height=\"352\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/_g6SvcfOaZI\" wmode=\"opaque\"\/><\/object><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- En la ma\u00f1ana de este viernes 25 de noviembre se efectu\u00f3 un desfile y posteriormente un acto para conmemorar una ocasi\u00f3n m\u00e1s del \u00abD\u00eda de la no violencia contra la mujer\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":13951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13952"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13951"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}