{"id":13954,"date":"2011-11-26T12:47:03","date_gmt":"2011-11-26T16:47:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/describen-como-actuan-los-anticuerpos-con-los-azucares-de-la-superficie-del-vih\/"},"modified":"2011-11-26T12:47:03","modified_gmt":"2011-11-26T16:47:03","slug":"describen-como-actuan-los-anticuerpos-con-los-azucares-de-la-superficie-del-vih","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/describen-como-actuan-los-anticuerpos-con-los-azucares-de-la-superficie-del-vih\/","title":{"rendered":"Describen c\u00f3mo act\u00faan los anticuerpos con los az\u00facares de la superficie del VIH"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-13953\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/sida.jpg\" width=\"500\" height=\"332\" alt=\"sida\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/sida.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/11\/sida-300x199.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Una investigaci\u00f3n publicada en el \u00faltimo n\u00famero de la revista &#8216;Nature&#8217; revela c\u00f3mo un anticuerpo ampliamente neutralizante del VIH utiliza parte de la capa de az\u00facar celular para ayudar a enlazar con el virus.<\/div>\n<p>  <!--more-->  <\/p>\n<div>El sitio de uni\u00f3n del anticuerpo, llamado regi\u00f3n V1\/V2, representa un objetivo adecuado para la vacuna contra el VIH, seg\u00fan los cient\u00edficos que realizaron el estudio; adem\u00e1s, la investigaci\u00f3n revela la estructura detallada de la regi\u00f3n V1\/V2, la \u00faltima parte de la superficie del virus que puede ser visualizada a nivel at\u00f3mico.<\/div>\n<div><\/div>\n<div><\/div>\n<div>&nbsp; &nbsp;El estudio fue dirigido por el doctor Peter D. Kwong, jefe de la Secci\u00f3n de Biolog\u00eda Estructural del Centro de Investigaci\u00f3n de Vacunas del Instituto Nacional de Alergias y Enfermedades Infecciosas (NIAID, por sus siglas en ingl\u00e9s), parte de los Institutos Nacionales de Salud de los Estados Unidos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>&nbsp; &nbsp;Algunas personas infectadas con el VIH durante varios a\u00f1os comienzan a producir anticuerpos que pueden neutralizar una amplia gama de cepas del virus del VIH, estos anticuerpos ampliamente neutralizantes se unen a uno de los cuatro sitios de entrada del virus. Uno de los sitios implica a ciertos az\u00facares llamados residuo de amino\u00e1cido 160 (los amino\u00e1cidos son los bloques constituyentes de las prote\u00ednas), el az\u00facar &nbsp;que sobresale de la superficie del VIH. El nuevo estudio demuestra c\u00f3mo un anticuerpo ampliamente neutralizante del VIH, llamado PG9, desarma el virus mediante el acaparamiento del residuo 160, junto con parte de un segundo az\u00facar y una cadena corta de amino\u00e1cidos en la regi\u00f3n V1\/V2.<\/div>\n<div><\/div>\n<div><\/div>\n<div>&nbsp; &nbsp;El estudio tambi\u00e9n puede ayudar a los cient\u00edficos que analizan los datos del ensayo cl\u00ednico de la primera vacuna contra el VIH a demostrar su eficacia en las personas; recientes an\u00e1lisis de muestras de sangre han demostrado que los participantes del estudio que fueron vacunados y despu\u00e9s desarrollaron anticuerpos frente a la regi\u00f3n V1\/V2 eran menos propensos a infectarse.<\/div>\n<div><\/div>\n<div>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.europapress.es\/salud\/noticia-describen-actuan-anticuerpos-azucares-superficie-vih-20111124103244.html\" target=\"_blank\">Europa Press<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una investigaci\u00f3n publicada en el \u00faltimo n\u00famero de la revista &#8216;Nature&#8217; revela c\u00f3mo un anticuerpo ampliamente neutralizante del VIH utiliza parte de la capa de az\u00facar celular para ayudar a enlazar con el virus.<\/p>\n","protected":false},"author":3,"featured_media":13953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-13954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=13954"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/13954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/13953"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=13954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=13954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=13954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}