{"id":14233,"date":"2011-12-12T05:13:11","date_gmt":"2011-12-12T09:13:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/bryant-critica-traspaso-de-odom-y-deron-williams-llama-maton-a-stern\/"},"modified":"2011-12-12T05:13:11","modified_gmt":"2011-12-12T09:13:11","slug":"bryant-critica-traspaso-de-odom-y-deron-williams-llama-maton-a-stern","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bryant-critica-traspaso-de-odom-y-deron-williams-llama-maton-a-stern\/","title":{"rendered":"Bryant critica traspaso de Odom y Deron Williams llama \u201cmat\u00f3n\u201d a Stern"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14232\" style=\"float: left;\" class=\"caption\" title=\"Kobe Est\u00e1 Killao Con Los Cambios\" alt=\"Kobe_Bryant\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/Kobe_Bryant.jpg\" width=\"300\" height=\"197\" \/>EE.UU..-Los efectos del frustrado traspaso del base Chris Paul a los Lakers de Los \u00c1ngeles siguen not\u00e1ndose en la NBA y esta vez las cr\u00edticas han llegado de la propia estrella del equipo angelino, el escolta Kobe Bryant, una vez que supo de la salida del alero Lamar Odom hacia los Mavericks de Dallas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Las \u00faltimas decisiones que ha tomado la directiva de los Lakers no han sido bien acogidas por Bryant, que despu\u00e9s de concluir el entrenamiento del domingo defini\u00f3 el traspaso de Odom como un \u201cregalo\u201d al mayor equipo rival que nadie entiende.<\/p>\n<p>Menos comprenden los jugadores de los Lakers la salida de Odom cuando el propio gerente general del equipo, Mitch Kupchak, alab\u00f3 la gran aportaci\u00f3n que hab\u00eda hecho al equipo durante las \u00faltimas siete temporadas, incluidos los dos t\u00edtulos de liga.<\/p>\n<p>Adem\u00e1s, los Lakers traspasan a Odom sin recibir ning\u00fan jugador importante a cambio, y se va a los Mavericks, los actuales campeones de liga, los verdugos de la pasada temporada.<\/p>\n<p>\u201cPara ser honesto con ustedes, no me gusta nada de esto\u201d, declar\u00f3 Bryant. \u201cEs muy duro perder a Lamar (Odom). Pau Gasol contin\u00faa aqu\u00ed y damos las gracias por ello. Son jugadores con los que hemos protagonizado duras batallas y no es f\u00e1cil asimilar su marcha\u201d.<\/p>\n<p>En Dallas existe un gran ambiente de satisfacci\u00f3n por la llegada de Odom, el nuevo compa\u00f1ero del escolta espa\u00f1ol Rudy Fern\u00e1ndez, y el entrenador del equipo tejano, Rick Carlisle, ya ha definido su adquisici\u00f3n como \u201cclave\u201d para el futuro del equipo.<\/p>\n<p>\u201cSin Tyson Chandler, la llegada de Odom va a permitirnos formar uno de los mejores ataques de la liga cuando se una a Dirk Nowitzki y Shawn Marion\u201d, destac\u00f3 Carlisle.<\/p>\n<p>Odom, de 32 a\u00f1os, llega a los Mavericks con 12 temporadas de experiencia en la NBA y promedios de 14,4 puntos; 8,7 rebotes y tres asistencias conseguidos en los 82 partidos que disput\u00f3 la pasada liga.<\/p>\n<p>Bryant y el base Derek Fisher fueron los que manifestaron p\u00fablicamente que no entienden nada de lo que sucede dentro del equipo al surgir ahora los rumores de la posible llegada del p\u00edvot Dwight Howard, que podr\u00eda costarle a los Lakers la salida del p\u00edvot Andrew Bynum y de Gasol, en funci\u00f3n de lo que puedan pedir el Magic de Orlando.<\/p>\n<p>\u201cEs muy dif\u00edcil para un jugador de baloncesto poder centrarse con este tipo de situaciones\u201d, valor\u00f3 Fisher, presidente del sindicato y que ya critic\u00f3 con dureza el \u201cveto\u201d que impuso el comisionado de la NBA, David Stern, al traspaso de Paul. \u201cEstoy muy decepcionado por Odom y Gasol. Por m\u00ed, Lamar no se hubiese ido\u201d.<\/p>\n<p>Bryan fue categ\u00f3rico cuando dijo que \u201codiaba\u201d ver marchar a Odom de Los \u00c1ngeles, sobre todo porque se iba a su peor rival y sin ning\u00fan tipo de compensaci\u00f3n, un simple derecho de selecci\u00f3n de la primera ronda del sorteo universitario del 2012.<\/p>\n<p>\u201cEspero que ahora Mark Cuban (due\u00f1o de los Mavericks) no haga ning\u00fan tipo de comentario negativo al traspaso ni se oponga como hizo cuando se iba a dar el de Paul\u201d, denunci\u00f3 Bryant.<\/p>\n<p>Ante este \u201ccaos\u201d que se vive dentro de los Lakers, el nuevo entrenador del equipo, Mike Brown, no ha podido todav\u00eda centrarse en su trabajo para tener al equipo lo mejor preparado posible para el D\u00eda de Navidad, cuando en el Staples Center se enfrente a los Bulls de Chicago en la jornada inaugural de la liga.<\/p>\n<p>Mientras, los Clippers se han colocado como el equipo con m\u00e1s opciones de conseguir el traspaso de Paul, pero de nuevo todo son rumores y nada sin concretar.<\/p>\n<p>El que si fue muy claro en sus declaraciones fue el base estrella de los Nets de Nueva Jersey, Deron Williams, que defini\u00f3 al Stern como un \u201cmat\u00f3n\u201d por la forma utiliz\u00f3 el veto en el traspaso de Paul.<\/p>\n<p>\u201c\u00c9l sabe que es un mat\u00f3n, no es ning\u00fan secreto\u201d, declar\u00f3 Williams a los periodistas al concluir el entrenamiento del domingo. \u201cCreo que todo el mundo sabe eso y no se puede ir contra \u00e9l, lo mismo que sucede con el resto de los due\u00f1os de la NBA y de grandes negocios\u201d.<\/p>\n<p>Williams tambi\u00e9n dijo que le hab\u00eda hecho \u201cgracia\u201d cuando escuch\u00f3 que Howard hab\u00eda pedido un traspaso para jugar con \u00e9l en Nueva Jersey.<\/p>\n<p>\u201cHablo todo el tiempo con Dwight (Howard) porque es mi amigo, como con Chris (Paul), al que no he podido contactar para conocer c\u00f3mo se encuentra, aunque considerado que mal, al igual que el resto de los jugadores implicados en el frustrado traspaso porque es una situaci\u00f3n est\u00fapida y sin sentido lo que est\u00e1n viviendo\u201d, agreg\u00f3 Williams.<\/p>\n<p>Fuente: Noticiassin.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EE.UU..-Los efectos del frustrado traspaso del base Chris Paul a los Lakers de Los \u00c1ngeles siguen not\u00e1ndose en la NBA y esta vez las cr\u00edticas han llegado de la propia estrella del equipo angelino, el escolta Kobe Bryant, una vez que supo de la salida del alero Lamar Odom hacia los Mavericks de Dallas.<\/p>\n","protected":false},"author":3,"featured_media":14232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14233"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14232"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}