{"id":14309,"date":"2011-12-17T16:05:06","date_gmt":"2011-12-17T20:05:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/tomar-cafe-puede-ayudar-a-reducir-el-riesgo-de-desarrollar-cancer-de-utero\/"},"modified":"2011-12-17T16:05:06","modified_gmt":"2011-12-17T20:05:06","slug":"tomar-cafe-puede-ayudar-a-reducir-el-riesgo-de-desarrollar-cancer-de-utero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tomar-cafe-puede-ayudar-a-reducir-el-riesgo-de-desarrollar-cancer-de-utero\/","title":{"rendered":"Tomar caf\u00e9 puede ayudar a reducir el riesgo de desarrollar c\u00e1ncer de \u00fatero"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14308\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/cafe-670xXx80.jpg\" width=\"644\" height=\"398\" alt=\"cafe-670xXx80\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/cafe-670xXx80.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/cafe-670xXx80-300x185.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>Beber m\u00e1s de cuatro tazas de caf\u00e9 al d\u00eda durante un periodo prolongado de tiempo reduce un 25 por ciento el riesgo de desarrollar c\u00e1ncer de \u00fatero, mientras que beber entre dos y tres lo rebaja un 7 por ciento.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Youjin Je, de la Escuela de Salud P\u00fablica de la Universidad de Harvard y autora principal del estudio que se publica en Cancer Epidemiology Biomarkers &amp; Prevention, explic\u00f3 que los altos niveles de estr\u00f3genos e insulina se han asociado con un mayor riesgo de c\u00e1ncer de endometrio, aqu\u00e9l que se origina en el revestimiento del \u00fatero.Varios estudios epidemiol\u00f3gicos hab\u00edan demostrado que las mujeres con un alto consumo de caf\u00e9 ten\u00edan menores niveles de esas hormonas, comparado con las que beb\u00edan poco o nada de caf\u00e9, por lo que trabajaron con la hip\u00f3tesis de que el consumo alto de caf\u00e9 pod\u00eda reducir el riesgo de ese tipo de c\u00e1ncer.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>\u00abEl caf\u00e9 contiene muchos compuestos biol\u00f3gicamente activos, incluyendo los \u00e1cidos fen\u00f3licos y la cafe\u00edna, que tienen una potente actividad antioxidante y pueden afectar al metabolismo de la glucosa y a los niveles de hormonas sexuales, que est\u00e1n relacionados con el riesgo de c\u00e1ncer endometrial\u00bb, se\u00f1al\u00f3.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>A largo plazo<\/strong><\/span><\/div>\n<div><span style=\"font-size: 14pt;\"><strong><br \/><\/strong><\/span><\/div>\n<div><\/div>\n<div>Los investigadores analizaron los datos de un estudio m\u00e1s amplio de salud en el que particip\u00f3 una muestra de 67.470 mujeres durante 26 a\u00f1os, en los que se registraron 672 casos de c\u00e1ncer de endometrio. El equipo de Je encontr\u00f3 que aquellas que sol\u00edan tomar m\u00e1s de cuatro tazas de caf\u00e9 al d\u00eda tuvieron un 25 por ciento menos de posibilidades de desarrollar c\u00e1ncer de \u00fatero, mientras que las que beb\u00edan entre dos y tres alcanzaron un 7 por ciento.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Una relaci\u00f3n similar se vio en el caf\u00e9 descafeinado, ya que las que indicaron beber m\u00e1s de dos tazas al d\u00eda tuvieron un 22 por ciento menos de posibilidades de padecer este c\u00e1ncer, algo que atribuyo a que el caf\u00e9 \u00abpuede modular los niveles de estr\u00f3genos e insulina favorablemente\u00bb y eso reduce el riesgo de c\u00e1ncer.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>El estudio concluye que beber caf\u00e9, dado su extendido consumo, puede ser una estrategia adicional para reducir el riesgo de c\u00e1ncer de \u00fatero. No obstante, a\u00f1adir mucho az\u00facar o crema \u00abpuede contrarrestar los beneficios para la salud\u00bb.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>\u00abNo recomendamos que las mujeres beban m\u00e1s caf\u00e9 s\u00f3lo para reducir el riesgo de c\u00e1ncer de endometrio. Sin embargo, las mujeres que consumen caf\u00e9 deben tener la seguridad de que esta infusi\u00f3n, en general, no es una sustancia nociva y puede incluso ofrecer algunos beneficios para la salud\u00bb, asegur\u00f3.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Cuidado con el az\u00facar<\/strong><\/span><\/div>\n<div><span style=\"font-size: 14pt;\"><strong><br \/><\/strong><\/span><\/div>\n<div><\/div>\n<div>Je enfatiz\u00f3 en que las personas que participaron en el estudio sol\u00edan tomar el caf\u00e9 solo o con un poco de leche y az\u00facar, o nata l\u00edquida, pero no se tuvo en cuenta las bebidas \u00abaltamente calor\u00edficas\u00bb como los caf\u00e9s helados que contienen nata y caramelo, que pueden provocar el efecto contrario. \u00abAgregar grandes cantidades de az\u00facar o nata al caf\u00e9 pueden contribuir al aumento de peso y a la resistencia a la insulina, lo que puede aumentar el riesgo de c\u00e1ncer de endometrio, as\u00ed como otras enfermedades cr\u00f3nicas\u00bb, advirti\u00f3.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>El equipo se\u00f1al\u00f3 que el caf\u00e9 tiene el potencial para reducir el riesgo de otros tipos de c\u00e1ncer debido a sus propiedades antioxidantes. Adem\u00e1s, en las personas sanas que no tienen problemas para metabolizar la cafe\u00edna, ni se enfrentan a insomnio o hiperactividad, tambi\u00e9n puede ayudar reducir el riesgo de diabetes, depresi\u00f3n, Parkinson y c\u00e1ncer de pr\u00f3stata.<\/div>\n<div><\/div>\n<div>fuente: <a href=\"http:\/\/www.abc.es\">www.abc.es<\/a>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beber m\u00e1s de cuatro tazas de caf\u00e9 al d\u00eda durante un periodo prolongado de tiempo reduce un 25 por ciento el riesgo de desarrollar c\u00e1ncer de \u00fatero, mientras que beber entre dos y tres lo rebaja un 7 por ciento.<\/p>\n","protected":false},"author":3,"featured_media":14308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14309"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14308"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}