{"id":14377,"date":"2011-12-23T03:15:44","date_gmt":"2011-12-23T07:15:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/probaran-vacuna-contra-el-vih-en-humanos-en-enero\/"},"modified":"2011-12-23T03:15:44","modified_gmt":"2011-12-23T07:15:44","slug":"probaran-vacuna-contra-el-vih-en-humanos-en-enero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/probaran-vacuna-contra-el-vih-en-humanos-en-enero\/","title":{"rendered":"Probar\u00e1n vacuna contra el VIH en humanos en enero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14376\" style=\"float: left;\" class=\"caption\" title=\"Prueba de Vacuna VIH\" alt=\"prueba_de_vacuna_vih\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/prueba_de_vacuna_vih.png\" width=\"270\" height=\"143\" \/>Hace ya un par de a\u00f1os que les hablamos de un equipo de cient\u00edficos de la Universidad de Western Ontario, en Canad\u00e1, que planeaban probar su vacuna contra el VIH en humanos. Pues bien, tras cuatro intentos finalmente recibieron la aprobaci\u00f3n de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA) para iniciar las pruebas cl\u00ednicas de la vacuna -bautizada como SAV001- a partir de enero del 2012 (s\u00ed, en un par de semanas).<\/p>\n<p>  <!--more-->  <\/p>\n<p>La ventaja de esta vacuna en comparaci\u00f3n con las tantas otras que se encuentran en desarrollo es que es la primera basada en modificaci\u00f3n gen\u00e9tica; utiliza el virus VIH-1 muerto con una metodolog\u00eda similar a la que deriv\u00f3 en las vacunas contra la poliomelitis, rabia y hepatitis A. Se produce en laboratorio, luego se mata y se modifica gen\u00e9ticamente para hacerlo inofensivo y finalmente se le aplica una prote\u00edna del veneno de abeja.<\/p>\n<p>El equipo liderado por el doctor Chil-Yong Kang ya hizo 230 pruebas de seguridad distintas para obtener el permiso de la FDA y los ensayos cl\u00ednicos se realizar\u00e1n en Estados Unidos con 40 voluntarios VIH positivos. La primera fase tomar\u00e1 seis meses en completar y luego otro a\u00f1o m\u00e1s para evaluar los resultados. La segunda etapa medir\u00e1 la respuesta del sistema inmune y contar\u00e1 con 600 personas sin el virus pero en categor\u00edas de alto riesgo (como hemof\u00edlicos, drogadictos, prostitutas y homosexuales con varias parejas sexuales).<\/p>\n<p>La \u00faltima etapa de pruebas abarcar\u00e1 6.000 personas VIH negativas en categor\u00edas de alto riesgo que ser\u00e1n comparadas con otro grupo no vacunado. Hasta entonces no se sabr\u00e1 con exactitud si la vacuna es 100% efectiva, pero de serlo podr\u00eda comenzar a ser distribuida dentro de cinco a\u00f1os.<\/p>\n<p>Probablemente requerir\u00eda dos dosis aplicadas con un intervalo de un mes, tal como funcion\u00f3 en las pruebas hechas en animales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace ya un par de a\u00f1os que les hablamos de un equipo de cient\u00edficos de la Universidad de Western Ontario, en Canad\u00e1, que planeaban probar su vacuna contra el VIH en humanos. Pues bien, tras cuatro intentos finalmente recibieron la aprobaci\u00f3n de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA) para iniciar las pruebas cl\u00ednicas de la vacuna -bautizada como SAV001- a partir de enero del 2012 (s\u00ed, en un par de semanas).<\/p>\n","protected":false},"author":3,"featured_media":14376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14377"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14376"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}