{"id":14383,"date":"2011-12-23T12:21:57","date_gmt":"2011-12-23T16:21:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/gigantes-avanzan-al-round-robin-tras-vencer-a-los-toros\/"},"modified":"2011-12-23T12:21:57","modified_gmt":"2011-12-23T16:21:57","slug":"gigantes-avanzan-al-round-robin-tras-vencer-a-los-toros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gigantes-avanzan-al-round-robin-tras-vencer-a-los-toros\/","title":{"rendered":"Gigantes avanzan al round robin tras vencer a los Toros"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14382\" style=\"float: left;\" class=\"caption\" title=\"Celebraci\u00f3n Clasificaci\u00f3n Gigantes\" alt=\"celebracion_de_clasificion_Gigantes\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/celebracion_de_clasificion_Gigantes.jpg\" width=\"445\" height=\"390\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/celebracion_de_clasificion_Gigantes.jpg 445w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/celebracion_de_clasificion_Gigantes-300x262.jpg 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/>Pedro Feliz, Robinzon D\u00edaz y Carlos Peguero conectaron sendos cuadrangulares guiando a Los Gigantes del Cibao a una f\u00e1cil victoria con anotaci\u00f3n de 7-3 sobre Los Toros del Este clasific\u00e1ndose al round robin del b\u00e9isbol profesional dominicano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Feliz conect\u00f3 el vuelacerca con dos corredores en circulaci\u00f3n en la segunda entrada, en tanto D\u00edaz y Peguero ligaron los jonrones solitario en la sexta entrada que fueron determinantes en la victoria de los orientados por H\u00e9ctor de la Cruz (La Manta).<\/p>\n<p>El lanzador ganador fue el relevista Erick Abr\u00e9u, quien tir\u00f3 2.1 de entradas permitiendo un solo hit y un ponche. El abridor de los Gigantes, Aquilino L\u00f3pez permiti\u00f3 dos carreras en dos tercios de entrada, pero fue relevado por el zurdo Jos\u00e9 de Paula, quien tir\u00f3 2.1 de entradas sin permitir carrera y ponch\u00f3 un bateador.<\/p>\n<p>El zurdo Juan P\u00e9rez se adjudic\u00f3 su cuarto juego salvado de la temporada entrando en la octava entrada luego de dos outs, enfrentando cinco bateadores, un hit, sin carreras y un ponche.<\/p>\n<p>De su lado, el derrotado fue el abridor por los Toros, Miguel De los Santos a quien le marcaron tres carreras en 2.2 de entradas, abanico a seis. Los Toros anotaron dos carreras en la primera con doblete al prado izquierdo de Esteban Germ\u00e1n, Pedro Ciriaco conect\u00f3 imparable por la antesala y en error en tiro de Pedro Feliz anot\u00f3 Germ\u00e1n, Diory Hern\u00e1ndez remolc\u00f3 a Ciriaco con imparable al izquierdo.<\/p>\n<p>En la segunda, los Gigantes fabricaron tres carreras recibiendo transferencia D\u00edaz, Carlos Peguero lig\u00f3 incogible que golpe\u00f3 al lanzador y Pedro Feliz empalm\u00f3 cuadrangular por la verja del jard\u00edn izquierdo remolcador de tres anotaciones.<\/p>\n<p>Los Gigantes anotaron tres carreras en la sexta entrada con cuadrangulares solitarios de D\u00edaz y Peguero, mientras que Feliz conect\u00f3 incogible por la antesala, Rafael Fern\u00e1ndez empalm\u00f3 hit golpeando al lanzador y Alexi Casilla remolc\u00f3 a Feliz con un sencillo por la intermedia.<\/p>\n<p>En la octava, los Toros anotaron una carrera con sencillo al central de Andy Dirks, quien se estaf\u00f3 la segunda y anot\u00f3 con imparable al central de Wilkin Ram\u00edrez. En el cierre de la octava entrada Los Gigantes anotaron unacarrera con imparable de Pedro Feliz, D\u2019Angelo Jim\u00e9nez negoci\u00f3 transferencia,RafaelFern\u00e1ndez entreg\u00f3 el primer out por la v\u00eda 1-3, Alexi Casilla fuetransferido intencionalmente y Wilson Valdez remolc\u00f3 a Feliz con elevado desacrificio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedro Feliz, Robinzon D\u00edaz y Carlos Peguero conectaron sendos cuadrangulares guiando a Los Gigantes del Cibao a una f\u00e1cil victoria con anotaci\u00f3n de 7-3 sobre Los Toros del Este clasific\u00e1ndose al round robin del b\u00e9isbol profesional dominicano.<\/p>\n","protected":false},"author":3,"featured_media":14382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14383"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14382"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}