{"id":14460,"date":"2011-12-30T18:13:30","date_gmt":"2011-12-30T22:13:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/al-horford-dejo-plantada-a-stephanie-gonzalez-por-amelia-vega\/"},"modified":"2011-12-30T18:13:30","modified_gmt":"2011-12-30T22:13:30","slug":"al-horford-dejo-plantada-a-stephanie-gonzalez-por-amelia-vega","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/al-horford-dejo-plantada-a-stephanie-gonzalez-por-amelia-vega\/","title":{"rendered":"AL HORFORD DEJO PLANTADA A STEPHANIE GONZALEZ POR AMELIA VEGA."},"content":{"rendered":"<div><strong><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14459\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/IMG_0339_2.jpg\" width=\"1024\" height=\"768\" alt=\"IMG_0339_2\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/IMG_0339_2.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/IMG_0339_2-300x225.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>Santo Domingo.-<\/strong> Seg\u00fan la p\u00e1gina web astrochicks.com el basketbolista de la NBA y ya esposo de Amelia Vega, Al Horford, habr\u00eda dejado plantada a su hasta entonces novia Stephanie Gonz\u00e1lez -quien desde hace un a\u00f1o preparaba boda-, por un ultim\u00e1tum de la Miss Universo 2003.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Seg\u00fan supo DL de fuentes de cr\u00e9dito, el deportista y la beldad se habr\u00edan conocido en casa del pelotero Sammy Sosa, durante una fiesta y cuando \u00e9l la vio dijo \u00abSi me la levanto, me caso de una vez sin pensarlo\u00bb. Alguien le habr\u00eda hecho saber a Amelia la expresi\u00f3n del joven multimillonario.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Astrochikcs.com dice en la nota que \u00abLa estrella del baloncesto rompi\u00f3 su compromiso y se separ\u00f3 de Stephanie. Esta joven, desconsolada, estaba planeando su boda, mientras que Al Horford estaba con un amor paralelo con la ex Miss Universo Amelia Vega\u00bb, quien le habr\u00eda puesto un ultimatum con la fecha.<\/div>\n<div><\/div>\n<div><\/div>\n<div>La urgencia matrimonial no es que est\u00e9 embarazada, seg\u00fan dijo al peri\u00f3dico boricua Primera Hora, David Ben\u00edtez, relacionista p\u00fablico, quien afirm\u00f3: \u00abMe comuniqu\u00e9 con Amelia y neg\u00f3 que fuera cierto que est\u00e1 embarazada\u00bb.<\/div>\n<div><\/div>\n<div>Ella misma neg\u00f3 a Ismael Cala de CNN, una semana atr\u00e1s, que tuviese alg\u00fan amor o compromiso.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Ben\u00edtez respondi\u00f3 a preguntas de DL que los reci\u00e9n casados \u00abno han tenido oportunidad de crear la tradicional Luna de Miel\u00bb, pues Al participa en la temporada de la NBA. Dijo que la ciudad de residencia de ambos ser\u00e1 Atlanta.&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Sobre el acuerdo matrimonial, escribi\u00f3: \u00abCon respecto a las capitulaciones, no tengo ninguna informaci\u00f3n al momento, pero estoy seguro que una de las capitulaciones que tienen es el amor que se profesa el uno por el otro\u00bb.&nbsp;<\/div>\n<div><\/div>\n<div><\/div>\n<div>Visto en Bonao.net<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- Seg\u00fan la p\u00e1gina web astrochicks.com el basketbolista de la NBA y ya esposo de Amelia Vega, Al Horford, habr\u00eda dejado plantada a su hasta entonces novia Stephanie Gonz\u00e1lez -quien desde hace un a\u00f1o preparaba boda-, por un ultim\u00e1tum de la Miss Universo 2003.<\/p>\n","protected":false},"author":3,"featured_media":14459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14460"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14459"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}