{"id":14464,"date":"2011-12-30T18:32:15","date_gmt":"2011-12-30T22:32:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/doce-secretos-caseros-contra-la-resaca-de-ano-nuevo\/"},"modified":"2011-12-30T18:32:15","modified_gmt":"2011-12-30T22:32:15","slug":"doce-secretos-caseros-contra-la-resaca-de-ano-nuevo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/doce-secretos-caseros-contra-la-resaca-de-ano-nuevo\/","title":{"rendered":"Doce secretos caseros contra la resaca de A\u00f1o Nuevo"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14463\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/Resacawegdfhntu536ijeuj6rk.jpg\" width=\"270\" height=\"165\" alt=\"Resacawegdfhntu536ijeuj6rk\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/Resacawegdfhntu536ijeuj6rk.jpg 270w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2011\/12\/Resacawegdfhntu536ijeuj6rk-440x270.jpg 440w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/>\u00bfSab\u00edas que frotar un lim\u00f3n en tu axila o beber una infusi\u00f3n de berenjenas podr\u00edan dar de baja los efectos de los tragos dem\u00e1s? Lee los siguientes consejos y deja todo listo.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>1: Partir un lim\u00f3n en dos mitades y frotar cada una en ambas axilas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>2: Hacer una infusi\u00f3n de jengibre, tomarla y luego apretar la parte carnosa existente entre el pulgar y el \u00edndice (en ambas manos).<\/div>\n<div><\/div>\n<div><\/div>\n<div>3: Tomar, antes de acostarse, un jugo de naranja donde se haya disuelto una cucharada de az\u00facar.<\/div>\n<div><\/div>\n<div><\/div>\n<div>4: Comer mandarinas, mel\u00f3n, frutillas o gazpacho.<\/div>\n<div><\/div>\n<div><\/div>\n<div>5: Comer dos bananas puede ayudar a que te sientas mejor m\u00e1s r\u00e1pidamente.<\/div>\n<div><\/div>\n<div><\/div>\n<div>6: Elaborar un hervido de ortigas en un \u00bc de litro de agua, un lim\u00f3n y un pu\u00f1ado de hojas de ortiga. Se hierven las hojas de ortigas en el agua durante 5 minutos y a continuaci\u00f3n se cuela. El jugo de lim\u00f3n se a\u00f1ade en el momento de tomarlo. Se recomienda tomar esta infusi\u00f3n en las ma\u00f1anas de resaca, en ayunas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>7: Mezclar lechuga, kiwi y pomelo en la licuadora. Beber un vaso de este jugo.<\/div>\n<div><\/div>\n<div><\/div>\n<div>8: Preparar un jugo con los siguientes ingredientes: una rebanada de papaya, un vaso de leche descremada, cuatro hielos molidos, un trozo de canela en polvo. Para ello se debe licuar todos los ingredientes con excepci\u00f3n de la canela que ser\u00e1 a\u00f1adida al final. Se debe tomar un vaso cada cuatro horas hasta que se vayan los s\u00edntomas de la resaca.<\/div>\n<div><\/div>\n<div><\/div>\n<div>9: Preparar un jugo con 3 tomates, un pepino sin c\u00e1scara picado y una cucharada de aceite de oliva. Licuar hasta desaparecer los grumos y se bebe de inmediato.<\/div>\n<div><\/div>\n<div><\/div>\n<div>10: Lavar y cortar en pedacitos una berenjena peque\u00f1a. Colocarla en una licuadora junto con un vaso de agua. Licuar por unos instantes. Colar y tomar tan pronto se regresa de la fiesta.<\/div>\n<div><\/div>\n<div><\/div>\n<div>11: Hacer un caldo vegetal donde se incluyan dos papas, apio, zapallo, betarraga y zanahorias: te devolver\u00e1n la energ\u00eda.<\/div>\n<div><\/div>\n<div><\/div>\n<div>12: Verter dos cucharadas de hojas de menta en 1 taza de agua que est\u00e9 hirviendo. Tapar y dejar enfriar. Tomar una taza a\u00f1adiendo, si se desea, 1 cucharadita de miel, con lo cual se aliviar\u00e1 el dolor de cabeza y, a la vez, que activar\u00e1 el proceso de rehidrataci\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div>13: Extraer el jugo de dos naranjas y luego agregar 1 cucharadita de jugo de lim\u00f3n y una pizca de comino molido. Tomar un vaso de este jugo<\/div>\n<div><\/div>\n<div>visto en: <a href=\"http:\/\/www.cachicha.com\">www.cachicha.com<\/a>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00edas que frotar un lim\u00f3n en tu axila o beber una infusi\u00f3n de berenjenas podr\u00edan dar de baja los efectos de los tragos dem\u00e1s? Lee los siguientes consejos y deja todo listo.<\/p>\n","protected":false},"author":3,"featured_media":14463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-14464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14464"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14463"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}