{"id":14667,"date":"2012-01-13T04:00:00","date_gmt":"2012-01-13T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/describen-nuevos-mecanismos-naturales-de-control-del-vih\/"},"modified":"2012-01-13T04:00:00","modified_gmt":"2012-01-13T08:00:00","slug":"describen-nuevos-mecanismos-naturales-de-control-del-vih","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/describen-nuevos-mecanismos-naturales-de-control-del-vih\/","title":{"rendered":"Describen nuevos mecanismos naturales de control del VIH"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14666\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/VIHtgh5ynhteukuyjg.jpg\" width=\"400\" height=\"343\" alt=\"VIHtgh5ynhteukuyjg\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/VIHtgh5ynhteukuyjg.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/VIHtgh5ynhteukuyjg-300x257.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Tres estudios promovidos por el Instituto de Investigaci\u00f3n del Sida IrsiCaixa confirman que la respuesta que predomina en los pacientes que controlan el VIH de forma natural se dirige a fragmentos del virus que sufren pocas mutaciones.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Tres estudios promovidos por el Instituto de Investigaci\u00f3n del Sida IrsiCaixa, y que se han publicado en las revistas Journal of Virology, Journal of Translational Medicine y PLOS One, describen los mecanismos naturales de control del VIH que se dan en personas capaces de mantener la cantidad de virus en sangre a niveles indetectables o muy bajos sin necesidad de medicaci\u00f3n.<\/div>\n<div><\/div>\n<div>Para descifrar los mecanismos del sistema inmunitario, los cient\u00edficos analizaron muestras de sangre de cerca de 1.000 personas infectadas por el VIH provenientes de \u00c1frica, Sudam\u00e9rica y Europa. En estas muestras se estudi\u00f3 la respuesta inmunitaria contra el VIH; concretamente, la respuesta mediada por unos gl\u00f3bulos blancos llamados linfocitos T.<\/div>\n<div><\/div>\n<div>El estudio confirma que la respuesta que predomina en los pacientes que controlan el VIH de forma natural se dirige a fragmentos del virus muy \u2018conservados\u2019, es decir, que sufren muy pocas mutaciones, e identifica los fragmentos del virus m\u00e1s activos a la hora de estimular el sistema inmunitario en estos individuos.<\/div>\n<div><\/div>\n<div>Seg\u00fan el coordinador del proyecto de investigaci\u00f3n, el investigador ICREA de IrsiCaixa Christian Brander, que es a la vez el coordinador cient\u00edfico del programa para el desarrollo de la vacuna HIVACAT, los estudios publicados \u00abhan ayudado a los investigadores a dise\u00f1ar los candidatos a vacuna que el Instituto tiene actualmente en desarrollo, y que est\u00e1n compuestos por fragmentos de VIH identificados en estos trabajos. IrsiCaixa ha podido identificar las mejores regiones del virus a incluir y comprobar que estimulan una buena respuesta inmunitaria como la descrita en el estudio, para que la vacuna pueda evitar que la infecci\u00f3n prolifere una vez que el virus penetra en el organismo\u00bb.<\/div>\n<div><\/div>\n<div>Fuente:&nbsp;<a target=\"_blank\" href=\"http:\/\/www.jano.es\/jano\/actualidad\/ultimas\/noticias\/janoes\/describen\/nuevos\/mecanismos\/naturales\/control\/vih\/_f-11+iditem-15958+idtabla-1\">Jano.es<\/a><\/div>\n<div>\n<p><a target=\"_blank\" href=\"http:\/\/www.jano.es\/jano\/actualidad\/ultimas\/noticias\/janoes\/describen\/nuevos\/mecanismos\/naturales\/control\/vih\/_f-11+iditem-15958+idtabla-1\"><\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tres estudios promovidos por el Instituto de Investigaci\u00f3n del Sida IrsiCaixa confirman que la respuesta que predomina en los pacientes que controlan el VIH de forma natural se dirige a fragmentos del virus que sufren pocas mutaciones.<\/p>\n","protected":false},"author":3,"featured_media":14666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14667"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14666"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}