{"id":14675,"date":"2012-01-14T04:00:00","date_gmt":"2012-01-14T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cosas-que-no-debes-hacer-en-facebook-si-no-quieres-parar-en-la-carcel\/"},"modified":"2012-01-14T04:00:00","modified_gmt":"2012-01-14T08:00:00","slug":"cosas-que-no-debes-hacer-en-facebook-si-no-quieres-parar-en-la-carcel","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cosas-que-no-debes-hacer-en-facebook-si-no-quieres-parar-en-la-carcel\/","title":{"rendered":"Cosas que no debes hacer en facebook si no quieres parar en la carcel"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14674\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/Facebook2-300x187thdfhgjeytkjythg.jpg\" width=\"300\" height=\"187\" alt=\"Facebook2-300x187thdfhgjeytkjythg\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/Facebook2-300x187thdfhgjeytkjythg.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/01\/Facebook2-300x187thdfhgjeytkjythg-400x250.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>El portal espa\u00f1ol Cookingideas public\u00f3 una lista de los hechos m\u00e1s resonantes depersonas que terminaron tras las rejas por delatar sus delitos a trav\u00e9s de Facebook.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Subir una foto de tu hijo fumando marihuana<\/strong><\/span><\/div>\n<div><\/div>\n<div>Rachel Stienringer, de 19 a\u00f1os, colg\u00f3 una imagen de su peque\u00f1o hijo jugando con su \u201cpipa\u201d. La mujer fue detenida, acusada de posesi\u00f3n de drogas, y estuvo a punto de perder la custodia del menor.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Transmitir un secuestro en directo<\/strong><\/span><\/div>\n<div><\/div>\n<div>Jason Valdez, de Utah, EEUU, secuestr\u00f3 a una mujer y la retuvo en una habitaci\u00f3n de hotel. Lo extra\u00f1o del caso es que Valdez dio un informe detallado de lo ocurrido, actualizando su estado en Facebook minuto a minuto con la evoluci\u00f3n de los hechos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>No pagar el taxi y dejar el celular en el coche<\/strong><\/span><\/div>\n<div><\/div>\n<div>Un hombre decidi\u00f3 no pagar el taxi en el que se trasladaba, pero el detalle est\u00e1 en que, a la hora de salir huyendo del auto, olvid\u00f3 su celular dentro del veh\u00edculo. El taxista aprovech\u00f3 la oportunidad y se veng\u00f3 revelando lo sucedido en el estado del ladr\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Entrar a robar y revisar si tienes mensajes nuevos en Facebook<\/strong><\/span><\/div>\n<div><span style=\"font-size: 12pt;\"><strong><br \/><\/strong><\/span><\/div>\n<div>Un hombre en los EEUU decidi\u00f3 entrar a robar en una casa, pero su adicci\u00f3n a la red social lo llev\u00f3 a revisar si ten\u00eda alg\u00fan mensaje nuevo en su cuenta. Lo malo fue que olvid\u00f3 cerrar la sesi\u00f3n antes de salir y la polic\u00eda lo pudo identificar.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Tomarte una foto con un tel\u00e9fono robado<\/strong><\/span><\/div>\n<div><\/div>\n<div>Un chico le hurt\u00f3 un celular de \u00faltima generaci\u00f3n a una mujer en Atlanta. El problema estuvo cuando el ladr\u00f3n se tom\u00f3 una foto con el tel\u00e9fono y la poste\u00f3 en la cuenta de Facebook de su v\u00edctima.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Ofrecer dinero para matar a tu ex<\/strong><\/span><\/div>\n<div><\/div>\n<div>Una joven ofreci\u00f3 US$ 1.000 a trav\u00e9s de su muro a quien estuviera dispuesto a asesinar a su ex pareja y padre de su hijo. Luego de 15 minutos, un \u201camigo\u201d de la red social se ofreci\u00f3 como voluntario para el crimen. Pocos d\u00edas despu\u00e9s, el hombre apareci\u00f3 muerto. La ex pareja y el sicario fueron acusados de asesinato y conspiraci\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Presumir de cosas robadas en Facebook<\/strong><\/span><\/div>\n<div><\/div>\n<div>Robert Driscoll le regal\u00f3 un costoso anillo hurtado a su novia, quien no tard\u00f3 ni un segundo en mostrarles a sus amistades el obsequio subiendo una foto en Facebook.<\/div>\n<div><\/div>\n<div><\/div>\n<div>La Polic\u00eda fue informada enseguida del asunto y poco despu\u00e9s unas c\u00e1maras captaban c\u00f3mo Driscoll empe\u00f1aba la joya robada.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Cuidado a qui\u00e9n aceptas o eliminas de Facebook<\/strong><\/span><\/div>\n<div><\/div>\n<div>Jennifer Christine Harris enfureci\u00f3 cuando descubri\u00f3 que su mejor amiga, Nikki Rasmussen, la hab\u00eda eliminado de su lista de contactos en el sitio. En un arrebato de ira, Harris prendi\u00f3 fuego la casa de su ex mejor amiga.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Robar un banco con la misma ropa que llevas en la foto del perfil<\/strong><\/span><\/div>\n<div><\/div>\n<div>Investigadores del FBI atraparon a un hombre acusado de robar cinco bancos en el \u00e1rea de Detroit, EEUU, tras comprobar que en varias fotos de Facebook vest\u00eda igual que como lo hab\u00edan capturaron las c\u00e1maras de seguridad del banco.<\/div>\n<div><\/div>\n<div><\/div>\n<div>[Infobae.com]<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El portal espa\u00f1ol Cookingideas public\u00f3 una lista de los hechos m\u00e1s resonantes depersonas que terminaron tras las rejas por delatar sus delitos a trav\u00e9s de Facebook.<\/p>\n","protected":false},"author":3,"featured_media":14674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-14675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14675"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14674"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}