{"id":14992,"date":"2012-02-03T16:22:12","date_gmt":"2012-02-03T20:22:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cinco-pasos-clave-para-proteger-tu-correo-electronico-de-los-hackers\/"},"modified":"2012-02-03T16:22:12","modified_gmt":"2012-02-03T20:22:12","slug":"cinco-pasos-clave-para-proteger-tu-correo-electronico-de-los-hackers","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cinco-pasos-clave-para-proteger-tu-correo-electronico-de-los-hackers\/","title":{"rendered":"Cinco pasos clave para proteger tu correo electr\u00f3nico de los hackers"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-14991\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/correo_electronico43765675456867.jpg\" width=\"183\" height=\"182\" alt=\"correo_electronico43765675456867\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/correo_electronico43765675456867.jpg 183w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/correo_electronico43765675456867-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/correo_electronico43765675456867-120x120.jpg 120w\" sizes=\"auto, (max-width: 183px) 100vw, 183px\" \/>Los hackers pueden explotar el correo electr\u00f3nico para suplantarte en tu puesto de trabajo. Utiliza cinco t\u00e9cnicas muy sencillas para protegerte.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>A pesar de la popularidad de las comunicaciones en tiempo real como la mensajer\u00eda instant\u00e1nea, adem\u00e1s de las actualizaciones via Facebook y Twitter, la mayor\u00eda de los centros de trabajo todav\u00eda utilizan y conf\u00edan en su correo electr\u00f3nico.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Sin embargo, un sistema de email puede ser tan \u00fatil como peligroso. Los enlaces pueden contener virus y los mensajes esconder enlaces maliciosos que te lleven a webs falsas en un intento por robar informaci\u00f3n de entrada.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Gigantes de la industria, como Google y Facebook, luchan por establecer un nuevo est\u00e1ndar llamado DMARC (Autenticaci\u00f3n, Reporte y Conformidad de Mensajes basada en Dominios) para reducir las amenazas en el futuro, pero por ahora hay cinco cosas que se deben hacer para ayudar a blindar el correo.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Protege tu contrase\u00f1a.<\/strong><\/span> Es la primera l\u00ednea de defensa y la m\u00e1s importante para proteger tu correo. Aunque la mayor\u00eda de los sistemas de correo requieren una, hay muchas formas de evitarla. En muchos casos, el usuario no dispone de password en su smartphone o laptop. Si no cuentas con una contrase\u00f1a de acceso, el correo que llega a este dispositivo estar\u00e1 desprotegido. Por eso muy importante utilizar passwords en todos y cada uno de los equipos que utilizamos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Que sea segura.<\/strong><\/span> Tan importante como una contrase\u00f1a para el correo almacenado localmente, es contar con otra para el correo que puede consultarse de forma remota. Por eso es tan importante utilizar una password compleja, con al menos 8 caracteres, combinadas con letras, n\u00fameros y s\u00edmbolos. As\u00ed es muy dif\u00edcil de romper. S\u00f3lo utilizando diferentes contrase\u00f1as para cada cuenta es posible estar a salvo.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Utilizar HTTPS.<\/strong><\/span> Cuando se utilizan sistemas de correo web es necesario utilizar el m\u00e9todo de seguridad HTTPS que cifra tus datos si viajan por Internet, &nbsp;haciendo m\u00e1s dif\u00edcil que sean interceptados o caigan en malas manos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Evitar enlaces.<\/strong><\/span> Hay que tener cuidado con los enlaces mandados por correo, ya que pueden contener virus o malware y s\u00f3lo hay que abrir los mensajes para que sean activados. Estos ataques pueden estar escondidos en mensajes de amigos o compa\u00f1eros, por lo que es recomendable preguntar al remitente qu\u00e9 hay en los enlaces que envi\u00f3, antes de abrirlos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 12pt;\"><strong>Huye del phishing.<\/strong><\/span> Si eres objeto de un ataque de phishing, aparecer\u00e1 un email simulando fue enviado por una fuente de confianza. Suelen emplear enlaces falsos para dirigirte a webs que tratar\u00e1n de convencerte de que incluyas informaci\u00f3n de contacto, lo que le dar\u00e1 a los criminales acceso a tu cuenta real.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Se han reforzado esfuerzos para reducir este peligro, como la reciente colaboraci\u00f3n DMARC ya mencionada, que una vez adoptados deber\u00e1n servir para asegurar que los mensajes son de quien realmente dicen ser. Pero, hasta que \u00e9sta y otras iniciativas similares den sus frutos, evita darle clic a enlaces en mensajes de correo, incluso si estos parecen ser de tu propia compa\u00f1\u00eda. En vez de eso, utiliza una direcci\u00f3n que tengas en favoritos o teclea a mano la direcci\u00f3n del site que quieres visitar.<\/div>\n<div><\/div>\n<div>fuente: audienciaelectronica.net&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los hackers pueden explotar el correo electr\u00f3nico para suplantarte en tu puesto de trabajo. Utiliza cinco t\u00e9cnicas muy sencillas para protegerte.<\/p>\n","protected":false},"author":3,"featured_media":14991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=14992"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/14992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14991"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=14992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=14992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=14992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}