{"id":15010,"date":"2012-02-04T13:35:16","date_gmt":"2012-02-04T17:35:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/destacan-papel-de-rd-en-escogencia-poblacion-judia\/"},"modified":"2012-02-04T13:35:16","modified_gmt":"2012-02-04T17:35:16","slug":"destacan-papel-de-rd-en-escogencia-poblacion-judia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/destacan-papel-de-rd-en-escogencia-poblacion-judia\/","title":{"rendered":"Destacan papel de RD en  escogencia poblaci\u00f3n jud\u00eda"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15009\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/0EAA50E1-0A48-470B-B682-E2DDCF059C09.jpg__209__400__CROPz0x209y400.jpeg\" width=\"209\" height=\"110\" alt=\"0EAA50E1-0A48-470B-B682-E2DDCF059C09.jpg__209__400__CROPz0x209y400\" class=\"caption\" style=\"float: left;\" \/>La ceremonia para conmemorar el &nbsp;D\u00eda Internacional del &nbsp;Holocausto jud\u00edo, instituida por la Organizaci\u00f3n de las &nbsp;Naciones Unidas, este a\u00f1o tuvo un especial reconocimiento para la &nbsp; Rep\u00fablica Dominicana, por ser la \u00fanica naci\u00f3n en el mundo en dar acogida a los jud\u00edos, en el momento de la amenaza nazi.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>&nbsp;En el acto, realizado en el Sal\u00f3n Principal de la Asamblea de las Naciones Unidas, el pa\u00eds estuvo representado por la viceministra de la presidencia Sandra Severino, quien encabezaba la delegaci\u00f3n, el embajador del pa\u00eds ante Israel, Alexander de la Rosa y el embajador dominicano ante las Naciones Unidas, Luis Lithgow.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Al pronunciar un discurso ante la Asamblea General, Lithgow destac\u00f3 la laboriosidad de la colonia jud\u00eda asentada en Sos\u00faa y los lazos indisolubles entre los dos pueblos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>En el evento tambi\u00e9n se present\u00f3 una obra de teatro musical denominada \u201cSos\u00faa: dare to dance together\u201d, que representa situaciones dif\u00edciles de las familias jud\u00edas que fueron recibidas en el pa\u00eds y el agradecimiento que tiene la comunidad jud\u00eda a esta &nbsp;isla del Caribe.<\/div>\n<div><\/div>\n<div><\/div>\n<div>&nbsp;Se estima que unos 6 millones de jud\u00edos murieron por la persecuci\u00f3n del r\u00e9gimen de Adolfo Hitler.<\/div>\n<div><\/div>\n<div>fuente: hoy.com.do<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La ceremonia para conmemorar el &nbsp;D\u00eda Internacional del &nbsp;Holocausto jud\u00edo, instituida por la Organizaci\u00f3n de las &nbsp;Naciones Unidas, este a\u00f1o tuvo un especial reconocimiento para la &nbsp; Rep\u00fablica Dominicana, por ser la \u00fanica naci\u00f3n en el mundo en dar acogida a los jud\u00edos, en el momento de la amenaza nazi.<\/p>\n","protected":false},"author":3,"featured_media":15009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15010"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15009"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}