{"id":15033,"date":"2012-02-06T16:42:41","date_gmt":"2012-02-06T20:42:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-becaria-que-perdio-la-virginidad-con-kennedy\/"},"modified":"2012-02-06T16:42:41","modified_gmt":"2012-02-06T20:42:41","slug":"la-becaria-que-perdio-la-virginidad-con-kennedy","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-becaria-que-perdio-la-virginidad-con-kennedy\/","title":{"rendered":"La becaria que perdi\u00f3 la virginidad con Kennedy"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15032\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/1328512296_extras_ladillos_1_0.jpg\" width=\"215\" height=\"260\" alt=\"1328512296_extras_ladillos_1_0\" class=\"caption\" style=\"float: left;\" \/>Una mujer de 69 a\u00f1os afirma que perdi\u00f3 la virginidad con el expresidente de Estados Unidos John F. Kennedy, cuando trabajaba como becaria en la Casa Blanca hace cincuenta a\u00f1os.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Comparti\u00f3 alcoba, y secretos, con uno de los hombres m\u00e1s poderosos del mundo hace medio siglo. Le llamaba \u00abMr. President\u00bb, jam\u00e1s por su nombre de pila. En &#8216;Once Upon a Secret: My Affair with President John F. Kennedy and Its Aftermath&#8217; (\u00ab\u00c9rase una vez mi secreto. Mi &#8216;affair&#8217; John F. Kennedy y sus secuelas\u00bb), Mimi Alford, de 69 a\u00f1os y ex administradora de una iglesia en Nueva York, cuenta c\u00f3mo hace 50 a\u00f1os perdi\u00f3 la virginidad en el dormitorio del entonces presidente de EEUU y su mujer, Jackie, y comenz\u00f3 un fogoso romance de 18 meses, siempre seg\u00fan su versi\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>En 1962 entr\u00f3 a hacer pr\u00e1cticas de verano como becaria de la oficina de prensa de la Casa Blanca. Alford desgrana los detalles \u00edntimos del comportamiento del mandatario asesinado en un libro repleto de explosivas declaraciones, recogidas por el New York Post, en las que se\u00f1ala que Kennedy le inst\u00f3 a mantener relaciones sexuales con uno de sus asesores delante de \u00e9l y que, durante la &#8216;crisis de los misiles&#8217; en 1962, uno de los puntos m\u00e1s cr\u00edticos de la Guerra Fr\u00eda entre EEUU y la URSS, lleg\u00f3 a decirle: \u00abPrefiero a mis hijos comunistas que muertos\u00bb.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Todo empez\u00f3, seg\u00fan su testimonio, cuatro d\u00edas despu\u00e9s de comenzar el trabajo, cuando recibi\u00f3 una invitaci\u00f3n para utilizar la piscina de la Casa Blanca. All\u00ed se present\u00f3 el presidente, que entonces ten\u00eda 45 a\u00f1os y nadaba a diario, casi siempre a mediod\u00eda, para combatir sus dolores de espalda. &#8211; \u00ab\u00bfTe llamas Mimi, no?\u00bb. -\u00abS\u00ed, se\u00f1or\u00bb.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Su relato no ahorra en detalles de c\u00f3mo fue conducida al dormitorio, c\u00f3mo le desabroch\u00f3 su blusa o c\u00f3mo le quit\u00f3 la ropa interior. Incluso cuenta que \u00e9l se dej\u00f3, aquella primera vez, la camisa puesta cuando se acostaron. \u00abLo has hecho antes?\u00bb, le pregunt\u00f3 \u00e9l. \u00abNo\u00bb, contest\u00f3 ella. &#8211; \u00ab\u00bfEst\u00e1s bien?\u00bb. -\u00abS\u00ed\u00bb.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Al respecto, cuenta Aldorf: \u00abEl hecho de que me deseara el hombre m\u00e1s famoso y poderoso de Am\u00e9rica solo aument\u00f3 mi sensaci\u00f3n de que cualquier resistencia no era una opci\u00f3n. Por eso es por lo que no le dije que no al presidente. Es la mejor respuesta que puedo ofrecer\u00bb. Aquella primera vez, recalca, fue la \u00fanica en el dormitorio del matrimonio Kennedy.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>En la ba\u00f1era con patitos de goma<\/strong><\/span><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Fue un amante que en el sexo era \u00abvariado y divertido\u00bb, comenta. Incluso compartieron ba\u00f1era con patitos de pl\u00e1stico a los que el presidente pon\u00eda nombres de su familia e inventaba historias. Le ense\u00f1\u00f3 a hacer huevos revueltos y escuchaban juntos a Tony Bennett y Frank Sinatra. Tambi\u00e9n se divert\u00edan cantando temas del musical &#8216;How to Succeed in Business Without Really Trying&#8217; (&#8216;C\u00f3mo triunfar en los negocios sin apenas propon\u00e9rselo&#8217;).<\/div>\n<div><\/div>\n<div><\/div>\n<div>A\u00f1ade la autora de estas pol\u00e9micas revelaciones que siempre hubo distancias insalvables. \u00abNunca nos besamos. El abismo que hab\u00eda entre ambos, en edad, poder y experiencia, garantizaba que nuestro affair nunca se convertir\u00eda en algo m\u00e1s serio\u00bb.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Llegaron a pasar noches juntos, estuvo en su yate y se citaron despu\u00e9s de que ella regresara a la universidad en septiembre, siempre que \u00e9l le llamaba bajo el seud\u00f3nimo de Michael Carter y le enviaba un coche oficial. Antes de marcharse, ella le regal\u00f3 un vinilo que hab\u00edan escuchado juntos, &#8216;Autumn Leaves&#8217;, de Nat King Cole, repleto de hojas de \u00e1rboles en su interior. \u00abIntentas hacerme llorar\u00bb, le dijo. \u00abNo, se\u00f1or Presidente. Intento que me recuerde\u00bb, contest\u00f3 la joven.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 14pt;\"><strong>Drogas y sexo con sus amigos<\/strong><\/span><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>En sus libro de memorias cuenta que no siempre le result\u00f3 agradable estar al lado del presidente. Como una noche en que \u00e9ste le dio a oler &#8216;popper&#8217;, una droga que se usa con fines sexuales. \u00abMe dio miedo y me fui llorando a mi habitaci\u00f3n\u00bb, recuerda.<\/div>\n<div><\/div>\n<div><\/div>\n<div>En otra ocasi\u00f3n, Kennedy se le acerc\u00f3 durante otro de los ba\u00f1os a medio d\u00eda en la piscina y le susurr\u00f3 que su asesor Dave Powers andaba \u00abalgo tenso\u00bb. Ella descifr\u00f3 el mensaje: \u00abEra una llamada, un desaf\u00edo para que le hiciera sexo oral a Dave Powers. No creo que \u00e9l pensara que iba a hacerlo, pero me averg\u00fcenza reconocer que lo hice&#8230; mientras el presidente nos miraba en silencio\u00bb, afirma, y agrega que \u00e9l se disculp\u00f3 m\u00e1s tarde.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Sin embargo, en uno de sus \u00faltimos encuentros volvi\u00f3 a hacerle una petici\u00f3n similar. Tambi\u00e9n le inst\u00f3 a que se \u00abencargara\u00bb de su hermano Ted, que necesitaba \u00abun poco de relajaci\u00f3n\u00bb. Ah\u00ed es cuando la autora de estas memorias manifiesta que se plant\u00f3 y le dio un categ\u00f3rico no.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Durante el romance tuvo un \u00absusto\u00bb. Una falsa alarma de embarazo. El aborto estaba prohibido, pero ya le hab\u00edan arreglado una cita. Adem\u00e1s, cuenta que en esos meses cuenta que le vio llorar una vez, por la muerte de su hijo Patrick Bouvier Kennedy, que naci\u00f3 prematuro y falleci\u00f3 a los dos d\u00edas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Se vieron por \u00faltima vez siete d\u00edas antes de que Kennedy viajara a Texas: \u00abNos abrazamos y me dijo que ojal\u00e1 pudiera ir con \u00e9l, que me llamar\u00eda cuando volviera. Yo le dije que recordase que me iba a casar. &#8216;Lo s\u00e9, pero te llamar\u00e9 de todas formas&#8217;, me dijo\u00bb.<\/div>\n<div><\/div>\n<div>fuente: elmundo.es<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una mujer de 69 a\u00f1os afirma que perdi\u00f3 la virginidad con el expresidente de Estados Unidos John F. Kennedy, cuando trabajaba como becaria en la Casa Blanca hace cincuenta a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":15032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-15033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15033"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15032"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}