{"id":15039,"date":"2012-02-06T17:26:15","date_gmt":"2012-02-06T21:26:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/masa-y-mia-sancionados-por-la-fiscalia-con-servicio-social\/"},"modified":"2012-02-06T17:26:15","modified_gmt":"2012-02-06T21:26:15","slug":"masa-y-mia-sancionados-por-la-fiscalia-con-servicio-social","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/masa-y-mia-sancionados-por-la-fiscalia-con-servicio-social\/","title":{"rendered":"Masa y M\u00eda sancionados por la Fiscal\u00eda con servicio social"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15038\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/MASAAAA68467859567536746786.jpg\" width=\"340\" height=\"400\" alt=\"MASAAAA68467859567536746786\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/MASAAAA68467859567536746786.jpg 340w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/MASAAAA68467859567536746786-255x300.jpg 255w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/>Entonces la Fiscal\u00eda del Distrito Nacional conmin\u00f3 al presentador Jes\u00fas Gil \u00abMasa\u00bb y al travesti M\u00eda Cepeda a realizar una labor social de 20 horas a cambio de no procesarlos judicialmente tras protagonizar una escena bochornosa en televisi\u00f3n donde el primero le toc\u00f3 el pene, los pechos y las nalgas al segundo con su consentimiento.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Algunos se han encontrado d\u00e9bil la sanci\u00f3n mientras otros entienden que deber\u00edan ponerlos a asear la nauseabunda \u00abbolita del mundo\u00bb, en el Centro de los H\u00e9roes, de la capital, zona de gran actividad sexual de prostitutas y homosexuales, a donde Masa desde un principio tenia que invitar a M\u00eda para satisfacer su curiosidad de saber si en su af\u00e1n de ser mujer hab\u00eda reemplazado su parte \u00edntima masculina.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Un chusco coment\u00f3 que de esta manera el presentador no compromet\u00eda la seriedad de un canal de televisi\u00f3n que no le qued\u00f3 otra salida que expulsarlo como tambi\u00e9n ten\u00edan que hacerlo con el co-protagonista del esc\u00e1ndalo.<\/div>\n<div><\/div>\n<div>fuente: fuegoalalata.net&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entonces la Fiscal\u00eda del Distrito Nacional conmin\u00f3 al presentador Jes\u00fas Gil \u00abMasa\u00bb y al travesti M\u00eda Cepeda a realizar una labor social de 20 horas a cambio de no procesarlos judicialmente tras protagonizar una escena bochornosa en televisi\u00f3n donde el primero le toc\u00f3 el pene, los pechos y las nalgas al segundo con su consentimiento.<\/p>\n","protected":false},"author":3,"featured_media":15038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15039"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15038"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}