{"id":15123,"date":"2012-02-13T13:21:06","date_gmt":"2012-02-13T17:21:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/prd-realiza-bandereo-y-caminata-en-sosua-ver-fotos-y-video-pendiente\/"},"modified":"2012-02-13T13:21:06","modified_gmt":"2012-02-13T17:21:06","slug":"prd-realiza-bandereo-y-caminata-en-sosua-ver-fotos-y-video-pendiente","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/prd-realiza-bandereo-y-caminata-en-sosua-ver-fotos-y-video-pendiente\/","title":{"rendered":"PRD Realiza Bandereo y Caminata en Sos\u00faa (VER FOTOS Y VIDEO)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15122\" style=\"float: left;\" alt=\"P1180334\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/P1180334.jpg\" width=\"596\" height=\"367\" \/>El Partido Revolucionario Dominicano se lanz\u00f3 a las calles de Sos\u00faa este domingo 12 de febrero en horas de la tarde reuniendo los m\u00e1s altos dirigentes, miembros y simpatizantes de la entidad pol\u00edtica, de igual modo fue observada una nutrida participaci\u00f3n de los denominados Reformistas con Pap\u00e1 encabezados por el Dr. Tito Sierra. <!--more--> <\/p>\n<p>La actividad del tipo bandereo inici\u00f3 aproximadamente a las tres de la tarde y se mantuvo creciendo m\u00e1s all\u00e1 de las cinco cuando se convirti\u00f3 en una marcha por el populoso sector de Los Charamicos. Desde la calle Eugenio Kunhardt, el sector La Gallera y la Dr. Morris cientos de perredeistas caminaron junto a la Licenciada Ilana Neumann, alcaldesa del municipio de Sos\u00faa, Willy Olivence, vice-alcalde, Los regidores M\u00e9lida Guzm\u00e1n y Miguel Fern\u00e1ndez, adem\u00e1s de Gabriel Severino y el Dr. Sierra.<\/p>\n<p><object width=\"594\" height=\"369\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629300722495%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629300722495%2F&amp;set_id=72157629300722495&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"594\" height=\"369\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629300722495%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629300722495%2F&amp;set_id=72157629300722495&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p>Al terminar el bandereo caminada fue muy notable la alegr\u00eda de los participantes, especialmente de los dirigentes mencionados quienes agarrados de las manos hicieron la se\u00f1al de victoria al tiempo que ofrecieron declaraciones de unidad y triunfo ante los medios de prensa presentes.<\/p>\n<p><object width=\"594\" height=\"394\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/N5vxUWkP9Xk\" \/><embed width=\"594\" height=\"394\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/N5vxUWkP9Xk\" wmode=\"opaque\"\/><\/object><\/p>\n<p>Este ha sido un paso muy positivo para el PRD y su dirigencia en el municipio de Sos\u00faa donde hace algunos meses hubo serias diferencias, posiblemente ligadas a los albores de las tendencias pol\u00edticas en las que fueron enfrentados los Ingenieros Hip\u00f3lito Mej\u00eda y Miguel Vargas Maldonado. El tiempo, la verdadera amistad y la necesitad de cambios para el pa\u00eds, han logrado una hegemon\u00eda en el Partido Revolucionario Dominicano en el municipio de Sos\u00faa.<\/p>\n<p>Seg\u00fan Ilana Neumann d\u00eda a d\u00eda decenas de ciudadanos est\u00e1n solicitando participar en las actividades proselitistas del PRD con la finalidad de llevar a Hip\u00f3lito Mej\u00eda de nuevo al gobierno. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Partido Revolucionario Dominicano se lanz\u00f3 a las calles de Sos\u00faa este domingo 12 de febrero en horas de la tarde reuniendo los m\u00e1s altos dirigentes, miembros y simpatizantes de la entidad pol\u00edtica, de igual modo fue observada una nutrida participaci\u00f3n de los denominados Reformistas con Pap\u00e1 encabezados por el Dr. Tito Sierra.<\/p>\n","protected":false},"author":3,"featured_media":15122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15123"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15122"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}