{"id":15190,"date":"2012-02-17T04:00:00","date_gmt":"2012-02-17T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/conozca-como-espian-por-los-telefonos-e-internet-en-republica-dominicana\/"},"modified":"2012-02-17T04:00:00","modified_gmt":"2012-02-17T08:00:00","slug":"conozca-como-espian-por-los-telefonos-e-internet-en-republica-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conozca-como-espian-por-los-telefonos-e-internet-en-republica-dominicana\/","title":{"rendered":"Conozca c\u00f3mo esp\u00edan por los tel\u00e9fonos e internet en Rep\u00fablica Dominicana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15189\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/espan-por-los-telfonos.jpg\" width=\"500\" height=\"405\" alt=\"espan-por-los-telfonos\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/espan-por-los-telfonos.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/espan-por-los-telfonos-300x243.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Para muchos, el espionaje de las intimidades de pol\u00edticos, empresarios y militares se ha convertido en un negocio muy lucrativo por la contrataci\u00f3n de esos servicios y la utilizaci\u00f3n de grabaciones comprometedoras para exigir dinero a cambio de no hacerlas p\u00fablicas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Paralelamente a las ventajas de comunicaci\u00f3n r\u00e1pida desde cualquier lugar del mundo, el avance de la tecnolog\u00eda ha servido para husmear en la cotidianidad y en las conversaciones de voz y de texto que sostienen a nivel laboral, familiar, entre amigos o parejas, con la facilidad de comprar un programa por 130 d\u00f3lares mensuales.<\/p>\n<p>Consultado por LIST\u00cdN DIARIO sobre el tema del momento, a ra\u00edz de hackeo de correos electr\u00f3nicos, Hiddekel Morrison, ingeniero en electr\u00f3nica y telecomunicaciones, asegura que en el pa\u00eds hay instalado al menos tres equipos de origen israel\u00ed de alta capacidad de manejo en diversos organismos de seguridad del estado y en manos de particulares.<\/p>\n<p>Morrison explica que la intervenci\u00f3n o interceptaci\u00f3n de los tel\u00e9fonos celulares, como ya son digitales bajo el est\u00e1ndar europeo GSM en su mayor\u00eda, se requiere contar con un equipo de monitoreo que est\u00e1 conectado a la central o switch de la empresa telef\u00f3nica que permite monitorear un n\u00famero espec\u00edfico de l\u00edneas seg\u00fan la capacidad que tenga dicho equipo interceptador.<\/p>\n<p>\u201cEsto lamentablemente se hace conect\u00e1ndolo desde la mismas empresas telef\u00f3nicas que por mandato legal deben interconectar sus equipos a los organismos de seguridad del Estado, que al estar permeados por la corrupci\u00f3n y la pol\u00edtica hacen un uso inadecuado de estas instalaciones para chantajear y extorsionar, olvidando su verdadero rol de combate a la delincuencia, el narcotr\u00e1fico y garant\u00eda de la seguridad nacional\u201d, dice. Morrison explica que se interceptan los correos electr\u00f3nicos hackeando el servidor donde se almacenan los correos, lo que consiste en tener acceso remoto a un computador de gran capacidad (servidor) donde usualmente se almacenan los correos. Narra que cuando son locales de instituciones p\u00fablicas o privadas tienen niveles muy bajos de seguridad de los datos, lo que permite que con diversos programas se pueda romper la seguridad y tener acceso a dichos correos.<\/p>\n<p><strong><\/strong>Para protegerse o conocer si se es espiado, Morrison sugiere no descargar, abrir o instalar ning\u00fan programa o software que se le env\u00ede que se desconozca, pues puede ser un programa de monitoreo o espionaje que al instalarse no deja rastro y graba o env\u00eda copia de todo lo que se haga o hable a terceras personas.<\/p>\n<p>Dice que en el caso de los correos electr\u00f3nicos es fundamental cambiar con frecuencia las contrase\u00f1as, no dejar activa su conexi\u00f3n en computadoras p\u00fablicas o desconocidas y combinar n\u00fameros y letras en sus contrase\u00f1as, cambiando la \u201cS\u201d por \u201c$\u201d y la \u201cO\u201d por el cero.<\/p>\n<p>fuente: audienciaelectronica.com&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para muchos, el espionaje de las intimidades de pol\u00edticos, empresarios y militares se ha convertido en un negocio muy lucrativo por la contrataci\u00f3n de esos servicios y la utilizaci\u00f3n de grabaciones comprometedoras para exigir dinero a cambio de no hacerlas p\u00fablicas.<\/p>\n","protected":false},"author":3,"featured_media":15189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15190"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15189"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}