{"id":15393,"date":"2012-03-02T14:33:57","date_gmt":"2012-03-02T18:33:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/actos-76-aniversario-policia-polanco-gomez-resalta-avances-de-la-policia-durante-su-trayectoria-de-76-anos\/"},"modified":"2012-03-02T14:33:57","modified_gmt":"2012-03-02T18:33:57","slug":"actos-76-aniversario-policia-polanco-gomez-resalta-avances-de-la-policia-durante-su-trayectoria-de-76-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/actos-76-aniversario-policia-polanco-gomez-resalta-avances-de-la-policia-durante-su-trayectoria-de-76-anos\/","title":{"rendered":"ACTOS 76 ANIVERSARIO POLIC\u00cdA: Polanco G\u00f3mez resalta avances de la Polic\u00eda durante su trayectoria de 76 a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15392\" style=\"float: left;\" alt=\"76_de_la_pn\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/76_de_la_pn.jpg\" width=\"330\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/76_de_la_pn.jpg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/76_de_la_pn-300x154.jpg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/>El jefe de la Polic\u00eda Nacional, Jos\u00e9 Armando Polanco G\u00f3mez, destac\u00f3 la trayectoria de ese organismo y asegur\u00f3 que sigue jugando su rol como garante del cumplimiento de las leyes, as\u00ed como su participaci\u00f3n en los distintos procesos hist\u00f3ricos en los \u00faltimos a\u00f1os.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dijo que en estos 76 a\u00f1os de existencia del organismo, los agentes del orden han arriesgado sus vidas, para garantizar la paz y seguridad ciudadana.<\/p>\n<p>Resalt\u00f3 que se ha logrado fortalecer los aspectos preventivos, investigativos y de inteligencia, en base a un proceso de capacitaci\u00f3n continuo.<\/p>\n<p>\u201cActualmente la Polic\u00eda Nacional se encuentra preparada y fortalecida, para trabajar acorde con estos tiempos, basado en la profesionalidad de cada unos de sus agentes\u201d, dijo Polanco G\u00f3mez al iniciar los actos en conmemoraci\u00f3n del aniversario de esa instituci\u00f3n en la sede del organismo.<\/p>\n<p>Los actos iniciaron con el izamiento de la Bandera Nacional y una ofrenda floral en el monumento a los miembros ca\u00eddos en el cumplimiento del deber, en la explanada frontal del Palacio de la instituci\u00f3n.<\/p>\n<p>En las actividades tambi\u00e9n participan altos oficiales de esa instituci\u00f3n e invitados especiales.<\/p>\n<p>Polanco G\u00f3mez exhort\u00f3 a los agentes del orden a mantenerse firmes en los principios \u00e9ticos y morales de la instituci\u00f3n, a la cual deben proteger con sus buenas acciones.<\/p>\n<p>Previamente, una comisi\u00f3n de generales de la instituci\u00f3n, encabezados por el subjefe policial, general V\u00edctor Campusano Jim\u00e9nez, deposit\u00f3 una ofrenda floral ante el Altar de la Patria.<\/p>\n<p>Mientras que en estos momentos es oficiada una misa solemne en la capilla San Judas Tadeo, de la instituci\u00f3n, con la asistencia del vicepresidente de la Rep\u00fablica, Rafael Alburquerque.<\/p>\n<p>Conforme a la agenda oficial, las actividades contin\u00faan con la graduaci\u00f3n de cadetes en la Escuela de Grado Academia para Cadetes \u201c2 de Marzo\u201d, en Hatillo, San Crist\u00f3bal.<\/p>\n<p>Tras la graduaci\u00f3n, la Jefatura de la Polic\u00eda prepar\u00f3 una actividad de corte festivo, que incluye almuerzo y una fiesta.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Listindiario.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jefe de la Polic\u00eda Nacional, Jos\u00e9 Armando Polanco G\u00f3mez, destac\u00f3 la trayectoria de ese organismo y asegur\u00f3 que sigue jugando su rol como garante del cumplimiento de las leyes, as\u00ed como su participaci\u00f3n en los distintos procesos hist\u00f3ricos en los \u00faltimos a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":15392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15393"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15392"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}