{"id":15487,"date":"2012-03-07T04:00:00","date_gmt":"2012-03-07T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/youtube-incorporara-por-fin-previsualizaciones-en-su-reproductor\/"},"modified":"2012-03-07T04:00:00","modified_gmt":"2012-03-07T08:00:00","slug":"youtube-incorporara-por-fin-previsualizaciones-en-su-reproductor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/youtube-incorporara-por-fin-previsualizaciones-en-su-reproductor\/","title":{"rendered":"YouTube incorporar\u00e1 por fin previsualizaciones en su reproductor"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15486\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/previsualizaciones_de_youtube23434256435.jpg\" width=\"299\" height=\"168\" alt=\"previsualizaciones_de_youtube23434256435\" class=\"caption\" style=\"float: left;\" \/>Se ha hecho de rogar, pero el equipo responsable de YouTube ha decidido anunciar por fin una opci\u00f3n que la comunidad de usuarios llevaba a\u00f1os reclamando. Se trata de la posibilidad de observar previsualizaciones del v\u00eddeo durante su reproducci\u00f3n, a modo de fotogramas en miniatura sobre la barra de reproducci\u00f3n.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Estas previsualizaciones se podr\u00e1n aprovechar de tres formas: como un simple fotograma que se muestra al poner el rat\u00f3n sobre un instante determinado de la barra, como un carrusel de miniaturas con las escenas destacadas o como una segunda barra en v\u00eddeos muy extensos para poder realizar b\u00fasquedas m\u00e1s precisas de momentos exactos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Todas las opciones me parecen acertadas y necesarias, as\u00ed que muy probablemente se convertir\u00e1n en un a\u00f1adido imprescindible cuando est\u00e9n disponibles. El plan es que las previsualizaciones vayan llegando al m\u00e1s popular servicio de v\u00eddeo en la Red durante las pr\u00f3ximas semanas, proceso que muy probablemente se realice de forma escalonada.<\/div>\n<div><\/div>\n<div>\n<p>V\u00eda |&nbsp;<a href=\"http:\/\/youtube-global.blogspot.com\/2012\/03\/looking-ahead-in-youtube-player.html\">YouTube<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se ha hecho de rogar, pero el equipo responsable de YouTube ha decidido anunciar por fin una opci\u00f3n que la comunidad de usuarios llevaba a\u00f1os reclamando. Se trata de la posibilidad de observar previsualizaciones del v\u00eddeo durante su reproducci\u00f3n, a modo de fotogramas en miniatura sobre la barra de reproducci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":15486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15487"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15486"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}