{"id":15504,"date":"2012-03-07T15:04:50","date_gmt":"2012-03-07T19:04:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-10-mentiras-mas-grandes-sobre-el-ejercicio\/"},"modified":"2012-03-07T15:04:50","modified_gmt":"2012-03-07T19:04:50","slug":"las-10-mentiras-mas-grandes-sobre-el-ejercicio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-10-mentiras-mas-grandes-sobre-el-ejercicio\/","title":{"rendered":"Las 10 mentiras m\u00e1s grandes sobre el ejercicio"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15503\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/El-ejercicio57865r6867845.jpg\" width=\"270\" height=\"202\" alt=\"El-ejercicio57865r6867845\" class=\"caption\" style=\"float: left;\" \/>Maik Wiedenbach es un ex atleta ol\u00edmpico, que ahora trabaja como entrenador personal y nutricionista en Nueva York. Particip\u00f3 en varias pruebas ol\u00edmpicas y en diferentes oportunidades en la Copa del Mundial como nadador.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Recientemente, public\u00f3 un libro \u201cLos 101 mitos sobre el ejercicio\u201d, de donde extraemos estos:<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>1. Si ejercitas m\u00e1s un \u00e1rea, quemar\u00e1s grasa en esa \u00e1rea.<\/strong><\/span> Es muy com\u00fan escuchar en los gimnasios decir que 500 abdominales ayudar\u00e1 a marcar los abs o el aparato para hacer abductores ayudar\u00e1 a tonificar los muslos. Esto es un grave error: el cuerpo no reduce grasa en el \u00e1rea que se trabaja. Para quemar grasa, se necesita lograr un d\u00e9ficit en la ecuaci\u00f3n dieta \u2013 ejercicio.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>Pierde 1 o 2 libras por semana, es decir, entre medio y un kilo.<\/strong><\/span> Algunas zonas del cuerpo se \u201cafinar\u00e1n\u201d m\u00e1s r\u00e1pidamente que otras. Para los hombres: las \u201cmanos del amor\u201d \u2013tal como se le llama a la grasa que se acumula en la cintura- es la \u00faltima zona de donde se pierde grasa. Para las mujeres: las caderas y los muslos son los lugares donde m\u00e1s se deposita y \u201caferra\u201d la grasa.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>2. Hacer ejercicio con fajas reduce la cintura.<\/strong><\/span> No s\u00f3lo no queman grasas sino que, lo que es peor, estos productos como fajas o cinturones para sudar m\u00e1s son peligrosos para la salud. Transpirar m\u00e1s no implica quemar grasas. Simplemente se pierde m\u00e1s agua, lo que reducir\u00e1 el rendimiento y podr\u00eda llevarte a sufrir de cansancio excesivo.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>3. Las flexiones o \u201ccurls\u201d son lo mejor para los b\u00edceps.<\/strong><\/span> Esto no es cierto. Mejor que los \u201ccurls\u201d (se llaman as\u00ed los ejercicios con flexiones de brazos o \u201cgiros\u201d de mu\u00f1eca para trabajar el b\u00edceps), son las flexiones cortas con los brazos hacia arriba, sostenidos en una barra (sobre el nivel de la cabeza, ver la foto). M\u00e1s que las tradicionales flexiones de brazos, estos ejercicios lograr\u00e1n un trabajo muscular mucho m\u00e1s intenso y conseguir\u00e1 mejores resultados para los b\u00edceps. De hecho, este ejercicio tambi\u00e9n es bueno para los abdominales.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>4. Es fundamental tomar quemadores de grasa.<\/strong><\/span> En su mayor\u00eda, estos productos son p\u00edldoras con cafe\u00edna que se venden a precios elevados. Si bien se ha demostrado que la cafe\u00edna tiene un leve efecto quemador de grasa, se puede conseguir en la farmacia por precios mucho m\u00e1s econ\u00f3micos. Advertencia: algunos productos contienen ingredientes que pueden ser peligrosos o han sido discontinuados por alguna raz\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>5. Es importante elongar antes de entrenar.<\/strong><\/span> Si lo haces, estar\u00e1s m\u00e1s d\u00e9bil y m\u00e1s susceptible a sufrir alguna lesi\u00f3n. El estiramiento es necesario pero despu\u00e9s de entrenar, para que la masa muscular se recupere, luego de haber estado ejercitando.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>6. Las clases de aerobics te ponen en forma.<\/strong><\/span> Salvo que seas un atleta experimentado y conozcas tu cuerpo muy bien, es muy probable que est\u00e9s por debajo o por encima del nivel del resto de tu clase. La explicaci\u00f3n es simple: es imposible que un entrenador o el profesor dise\u00f1en una clase para 30 personas diferentes. Adem\u00e1s de que el riesgo de lesiones es alto.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>7. Los ejercicios de moda son lo m\u00e1s avanzado.<\/strong><\/span> Cada verano, aparecen nuevos equipos por la televisi\u00f3n para quemar calor\u00edas con el m\u00ednimo esfuerzo. A la vez, otros desaparecen y quedan en el olvido. Lo mejor es no seguir las modas, sino adherirse a aquello que uno ya comprob\u00f3 que da resultados, seguir la dieta y as\u00ed conseguir\u00e1s alcanzar el cuerpo que so\u00f1amos.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>8. No hay que cenar despu\u00e9s de las 6 PM.<\/strong><\/span> Para las personas que entrenan a la tarde, esto puede ser contraproducente, ya que no se estar\u00e1n \u201cnutriendo\u201d los m\u00fasculos despu\u00e9s de trabajarlos. Adem\u00e1s, m\u00e1s importa que \u201ccu\u00e1ndo\u201d es \u201cqu\u00e9\u201d comemos. Lo importante para mantenerse en forma es tener un plan diario de calor\u00edas y seguirlo.<\/div>\n<div><\/div>\n<div>Claro que si uno come justo antes de irse a la cama, nos iremos a dormir con el est\u00f3mago inflamado.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>9. Las grasas hay que eliminarlas por completo.<\/strong><\/span> Exactamente lo opuesto: cuando alguien quiere perder peso, necesita consumir un poco de grasas. Si no, el cuerpo \u201cinterpretar\u00e1\u201d que entr\u00f3 en un c\u00edrculo de \u201cinanici\u00f3n\u201d y guardar\u00e1 las grasas como reservas. Por otra parte, se necesita consumir algo de grasa para producir las hormonas sexuales: testosterona, progesterona y estr\u00f3genos. Si los niveles de estas hormonas caen, la p\u00e9rdida de grasa se hace m\u00e1s lenta. Buenas fuentes de grasa: nueces, aguacate (palta) y bistec.<\/div>\n<div><\/div>\n<div><\/div>\n<div><span style=\"font-size: 10pt;\"><strong>10. Los s\u00faper alimentos te hacen adelgazar.<\/strong><\/span> No existe un alimento que pueda \u201cponernos en forma\u201d si no tenemos una actividad f\u00edsica y una dieta apropiadas. Menos a\u00fan se puede \u201ccontrarrestar\u201d una hamburguesa con queso con un jugo de bayas \u201cacai\u201d. Sugerencia: las uvas y los ar\u00e1ndanos son mucho m\u00e1s saludables y baratas que las hamburuguesas.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Maik Wiedenbach es un ex atleta ol\u00edmpico, que ahora trabaja como entrenador personal y nutricionista en Nueva York. Particip\u00f3 en varias pruebas ol\u00edmpicas y en diferentes oportunidades en la Copa del Mundial como nadador.<\/p>\n","protected":false},"author":3,"featured_media":15503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15504"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15503"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}