{"id":15566,"date":"2012-03-10T04:00:00","date_gmt":"2012-03-10T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/si-quiere-verse-bien-coma-frutas-y-verduras\/"},"modified":"2012-03-10T04:00:00","modified_gmt":"2012-03-10T08:00:00","slug":"si-quiere-verse-bien-coma-frutas-y-verduras","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/si-quiere-verse-bien-coma-frutas-y-verduras\/","title":{"rendered":"Si quiere verse bien, coma frutas y verduras"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15565\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/comer-frutas-y-verduras.jpg\" width=\"280\" height=\"266\" alt=\"comer-frutas-y-verduras\" class=\"caption\" style=\"float: left;\" \/>El consumo de frutas y verduras no s\u00f3lo tiene beneficios para la salud, como han demostrado varios estudios en el pasado.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Estos productos tambi\u00e9n pueden hacernos m\u00e1s atractivos, afirma una nueva investigaci\u00f3n.<\/p>\n<p>El estudio -publicado en la revista&nbsp;<em>PLoS One<\/em>&nbsp;(Biblioteca P\u00fablica de Ciencia)- encontr\u00f3 que la gente que come frutas y verduras tiene una piel m\u00e1s radiante y sana, lo cual incrementa el atractivo f\u00edsico.<\/p>\n<p>Se cree que el efecto se debe a los carotenoides, los pigmentos amarillos, anaranjados y rojos que se encuentran de forma natural en muchos tipos de vegetales.<\/p>\n<p>Los investigadores de la Universidad de St. Andrews, en Escocia, quer\u00edan analizar si el consumo de determinada cantidad de estos productos tiene un efecto en el color de la piel.<\/p>\n<p>En el estudio siguieron un registro de 35 participantes, la mayor\u00eda blancos, que consumieron frutas y verduras durante seis semanas.<\/p>\n<p>Se pidi\u00f3 a los voluntarios que no utilizaran camas solares, bronceado artificial ni maquillaje durante el per\u00edodo de estudio.<\/p>\n<p>Los cient\u00edficos usaron un dispositivo para analizar el tono de la piel de los individuos antes, durante y al final del experimento.<\/p>\n<p>Los resultados al final del estudio mostraron un incremento en los tonos rojos y amarillos de la piel, lo cual proporciona un efecto radiante en la piel.<\/p>\n<h2>Piel sana y atractiva<\/h2>\n<p>El mismo equipo de investigadores ya hab\u00eda demostrado en estudios anteriores que la gente suele percibir un rostro atractivo dependiendo de los cambios, incluso los m\u00e1s sutiles, en estos tonos de la piel.<\/p>\n<p>\u00abEs posible que incluso los cambios muy peque\u00f1os en la dieta puedan producir beneficios perceptibles en la coloraci\u00f3n de la piel\u00bb afirman los doctores Ross Whitehead y David Perrett, autores del estudio.<\/p>\n<div>\n<div>\n<div>\n<div>\n<blockquote>\n<p>\u00ab\u00c9sta es una buena forma de estimular a la gente: despertar nuestra vanidad innata para incrementar nuestro consumo de vegetales\u00bb<br \/>Dr. Glenys Jones<\/p>\n<\/blockquote>\n<div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>Pero subrayan que no se sabe si este mismo efecto puede encontrarse en la piel de la gente que no es blanca o aqu\u00e9llos de edad m\u00e1s avanzada, por lo que ser\u00e1 necesario llevar a cabo m\u00e1s estudios para confirmarlo.<\/p>\n<p>El impacto de los carotenoides en la coloraci\u00f3n de la piel es un tema que se ha estado estudiando desde hace tiempo.<\/p>\n<p>Se sabe, por ejemplo, que las t\u00e9cnicas de preparaci\u00f3n y procesamiento de los alimentos tienen un efecto muy importante en la cantidad de carotenoides que podemos obtener en nuestra dieta.<\/p>\n<p>Seg\u00fan la doctora Glenys Jones, del laboratorio de investigaci\u00f3n de nutrici\u00f3n humana del Consejo de Investigaci\u00f3n M\u00e9dica de la Universidad de Cambridge, Inglaterra, \u00abuna vasta mayor\u00eda de la poblaci\u00f3n no consume las cinco porciones de frutas y verduras que se recomiendan diariamente\u00bb.<\/p>\n<p>\u00abY \u00e9sta es una buena forma de estimular a la gente: despertar nuestra vanidad innata para incrementar nuestro consumo de vegetales\u00bb.<\/p>\n<p>\u00abPorque las frutas y verduras contienen una amplia variedad de nutrientes que no s\u00f3lo son buenos para nuestra constituci\u00f3n f\u00edsica, sino para nuestra salud en general\u00bb, agrega.<\/p>\n<p>La doctora Catherine Collins, nutricionista del Hospital St George&#8217;s en Londres, est\u00e1 de acuerdo en que cualquier estrategia que estimule a la gente a comer m\u00e1s frutas y verduras es algo positivo.<\/p>\n<p>\u00abCiertamente esta es otra raz\u00f3n por la que debemos comer nuestras porciones de vegetales, ya sean verdes, rojos, anaranjados o amarillos\u00bb.<\/p>\n<p>\u00abPodemos comerlos cocidos, hervidos, como acompa\u00f1amiento de otro alimento, o fruta de postre. Lo principal es incrementar nuestro consumo de estos \u00fatiles compuestos, los cuales adem\u00e1s de contribuir a nuestra salud general, tambi\u00e9n nos har\u00e1n m\u00e1s atractivos\u00bb agrega.<\/p>\n<p>Los beneficios nutricionales de las frutas y verduras no s\u00f3lo se deben a los carotenoides.<\/p>\n<p>Estos alimentos son fuentes ricas de vitaminas, minerales, fibra y fitonutrientes, unos importantes compuestos que act\u00faan como antioxidantes protegiendo al organismo de los da\u00f1os causados en las c\u00e9lulas.<\/p>\n<p>Los estudios han demostrado que la gente que come al menos cinco porciones de frutas o verduras diariamente tiene menos riesgo de desarrollar enfermedades cardiovasculares y algunos tipos de c\u00e1ncer.<\/p>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2012\/03\/120308_piel_atractiva_vegetales_men.shtml\" target=\"_blank\">BBC Salud<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consumo de frutas y verduras no s\u00f3lo tiene beneficios para la salud, como han demostrado varios estudios en el pasado.<\/p>\n","protected":false},"author":3,"featured_media":15565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15566"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15565"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}