{"id":15767,"date":"2012-03-18T16:52:07","date_gmt":"2012-03-18T20:52:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/mas-de-un-millon-en-rd-con-problemas-del-sueno-2\/"},"modified":"2012-03-18T16:52:07","modified_gmt":"2012-03-18T20:52:07","slug":"mas-de-un-millon-en-rd-con-problemas-del-sueno-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mas-de-un-millon-en-rd-con-problemas-del-sueno-2\/","title":{"rendered":"M\u00e1s  de un  mill\u00f3n en RD con problemas del sue\u00f1o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15765\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_57E8BD5E-30AB-444E-A0EC-6A256922E3F6.jpg__209__400__CROPz0x209y400.jpeg\" width=\"209\" height=\"323\" alt=\"57E8BD5E-30AB-444E-A0EC-6A256922E3F6.jpg__209__400__CROPz0x209y400\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_57E8BD5E-30AB-444E-A0EC-6A256922E3F6.jpg__209__400__CROPz0x209y400.jpeg 209w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_57E8BD5E-30AB-444E-A0EC-6A256922E3F6.jpg__209__400__CROPz0x209y400-194x300.jpeg 194w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/>Los problemas del sue\u00f1o constituyen una pandemia&nbsp; que en la Rep\u00fablica Dominicana afecta a m\u00e1s de un mill\u00f3n de personas, asegur\u00f3 ayer el doctor Luis Felipe Encarnaci\u00f3n, experto en el tema.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Se recomienda que las personas duerman entre siete y nueve horas, pues esa pr\u00e1ctica eleva la calidad de vida de las personas y los lleva a un descanso m\u00e1s pleno.<\/p>\n<p>Explic\u00f3 que dormir es un componente vital del bienestar general,&nbsp; y sus alteraciones afectan la salud mental, emocional y f\u00edsica de ni\u00f1os y adultos,&nbsp; asegur\u00f3 Encarnaci\u00f3n.<\/p>\n<p>\u201cPero desafortunadamente, para cientos de miles de personas en nuestro pa\u00eds la falta de un sue\u00f1o de calidad es un problema muy real que afecta sus vidas en la noche cuando no pueden dormir y al d\u00eda siguiente, cuando sienten las consecuencias de la \u2018mala noche\u2019 previa\u201d, asegur\u00f3.<\/p>\n<p>Este problema es tratado por los otorrinolaring\u00f3logos y otros especialistas del sue\u00f1o.<\/p>\n<p>La Asociaci\u00f3n Mundial de Medicina del Sue\u00f1o, a trav\u00e9s del comit\u00e9 para el D\u00eda Mundial del Sue\u00f1o, codirigido a nivel internacional por los doctores Antonio Culebras y Liborio Parrino, y&nbsp; en la Rep\u00fablica Dominicana por el doctor Luis Felipe Encarnaci\u00f3n, afirma que tal es la gravedad de la situaci\u00f3n en el pa\u00eds, que recientemente se constituy\u00f3 la Academia de Medicina del Sue\u00f1o.<\/p>\n<p>Est\u00e1 integrada por los doctores Encarnaci\u00f3n, Jorge Marte B\u00e1ez, Alexander Joubert, Alejandro Lora, Evelyn Lora,&nbsp; Franklyn Montero y el t\u00e9cnico Aurelio Henr\u00edquez.<\/p>\n<p>El problema constituye una pandemia (epidemia&nbsp; global) que afecta al 45%&nbsp; de la poblaci\u00f3n mundial.<\/p>\n<p><a href=\"http:\/\/www.hoy.com.do\/el-pais\/2012\/3\/17\/419312\/Mas-de-un-millon-en-RD-con-problemas-del-sueno\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los problemas del sue\u00f1o constituyen una pandemia&nbsp; que en la Rep\u00fablica Dominicana afecta a m\u00e1s de un mill\u00f3n de personas, asegur\u00f3 ayer el doctor Luis Felipe Encarnaci\u00f3n, experto en el tema.<\/p>\n","protected":false},"author":3,"featured_media":15765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15767"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15765"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}