{"id":15785,"date":"2012-03-18T18:09:43","date_gmt":"2012-03-18T22:09:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/actividad-politica-online-caravana-del-prd-en-sosua-ver-fotos-y-video-2\/"},"modified":"2012-03-18T18:09:43","modified_gmt":"2012-03-18T22:09:43","slug":"actividad-politica-online-caravana-del-prd-en-sosua-ver-fotos-y-video-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/actividad-politica-online-caravana-del-prd-en-sosua-ver-fotos-y-video-2\/","title":{"rendered":"Actividad Politica Online, Caravana del PRD En Sos\u00faa (VER FOTOS Y VIDEO)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15783\" style=\"float: left;\" alt=\"caravana_prd1\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_caravana_prd1.jpg\" width=\"582\" height=\"337\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_caravana_prd1.jpg 582w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_caravana_prd1-300x173.jpg 300w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/>Sos\u00faa.- El pasado s\u00e1bado 17 de marzo el Partido Revolucionario Dominicanno (PRD) realiz\u00f3 un caravana partiendo desde Sabaneta de Y\u00e1sica y cubriendo el Municipio de Sos\u00faa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;<\/p>\n<p>Ver video y fotos &#8230;<\/p>\n<p>&nbsp;<object width=\"585\" height=\"356\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629248645640%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629248645640%2F&amp;set_id=72157629248645640&amp;jump_to=\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"585\" height=\"356\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629248645640%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629248645640%2F&amp;set_id=72157629248645640&amp;jump_to=\" allowfullscreen=\"true\"\/><\/object><\/p>\n<p><object width=\"587\" height=\"422\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/WKxXy6ZGy64\" \/><embed width=\"587\" height=\"422\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/WKxXy6ZGy64\" wmode=\"opaque\"\/><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- El pasado s\u00e1bado 17 de marzo el Partido Revolucionario Dominicanno (PRD) realiz\u00f3 un caravana partiendo desde Sabaneta de Y\u00e1sica y cubriendo el Municipio de Sos\u00faa.<\/p>\n","protected":false},"author":3,"featured_media":15783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15785"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15783"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}