{"id":15787,"date":"2012-03-19T14:42:24","date_gmt":"2012-03-19T18:42:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/roberto-cavada-confirma-rumores-de-salida-de-telesistema\/"},"modified":"2012-03-19T14:42:24","modified_gmt":"2012-03-19T18:42:24","slug":"roberto-cavada-confirma-rumores-de-salida-de-telesistema","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/roberto-cavada-confirma-rumores-de-salida-de-telesistema\/","title":{"rendered":"Roberto Cavada confirma rumores de salida de Telesistema"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15784\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/cavada_concho768466798745378658467.jpg\" width=\"387\" height=\"400\" alt=\"cavada_concho768466798745378658467\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/cavada_concho768466798745378658467.jpg 387w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/cavada_concho768466798745378658467-290x300.jpg 290w\" sizes=\"auto, (max-width: 387px) 100vw, 387px\" \/>Aunque no lo afirm\u00f3, Roberto Cavada podr\u00eda tener fecha establecida para dejar de ser el rostro de Telenoticias en su edici\u00f3n estelar, y dedicarse a su pasi\u00f3n: la producci\u00f3n.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\u201cLa verdad, todo tiene un comienzo y un final, todo tiene su etapa en la vida . Yo creo que he cumplido con el noticiario y debe haber otras propuestas de presentaci\u00f3n de noticias y de puesta en escena que deben tener cabida.<\/div>\n<div><\/div>\n<div>Creo que cinco a\u00f1os es suficiente\u201d, puntualiz\u00f3 el denominado \u201cHombre Noticia\u201d en entrevista a la secci\u00f3n \u00abAlegr\u00eda\u00bb del matutino.<\/div>\n<div><\/div>\n<div>Cavada declar\u00f3 que podr\u00eda irse \u201cma\u00f1ana o el 7 de septiembre de este a\u00f1o, que es cuando cumplo cinco a\u00f1os en el noticiario de Telesistema, canal 11\u201d.<\/div>\n<div><\/div>\n<div>El comunicador cubano asegur\u00f3 que su salida no se debe a presiones de pol\u00edticos debido a sus fuertes cr\u00edticas, y mucho menos a exigencias del Grupo de Comunicaciones Corripio.<\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"http:\/\/fuegoalalata.net\/\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque no lo afirm\u00f3, Roberto Cavada podr\u00eda tener fecha establecida para dejar de ser el rostro de Telenoticias en su edici\u00f3n estelar, y dedicarse a su pasi\u00f3n: la producci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":15784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15787"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15784"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}