{"id":15807,"date":"2012-03-17T04:00:00","date_gmt":"2012-03-17T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/montellaneros-enfrascados-en-limpieza-playa-cangrejos-2\/"},"modified":"2012-03-17T04:00:00","modified_gmt":"2012-03-17T08:00:00","slug":"montellaneros-enfrascados-en-limpieza-playa-cangrejos-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/montellaneros-enfrascados-en-limpieza-playa-cangrejos-2\/","title":{"rendered":"Montellaneros enfrascados en limpieza Playa Cangrejos"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15804\" style=\"float: left;\" class=\"caption\" alt=\"420979_10150603439232283_606687282_9568213_510155337_n\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_420979_10150603439232283_606687282_9568213_510155337_n.jpg\" width=\"960\" height=\"720\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_420979_10150603439232283_606687282_9568213_510155337_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_420979_10150603439232283_606687282_9568213_510155337_n-300x225.jpg 300w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>Apegados al dicho de que \u00aben la uni\u00f3n est\u00e1 la fuerza\u00bb y que no todo hay que dej\u00e1rselo a las autoridades, que de hecho solo se acuerdan de limpiar las playas una vez al a\u00f1o, en septiembre, un grupo de montellaneros, hombres de trabajo, profesores y estudiantes se han enfrascado en la dif\u00edcil pero no imposible tarea de limpiar la playa de Cangrejos.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>La playa de Cangrejos tiene fama de ser una de las m\u00e1s sucias de la provincia, primero por la dejadez de las autoridades municipales y por la gran cantidad de residuos y basura que llegan a sus arenas fruto de las continuas crecidas del R\u00edo Cam\u00fa, el cual recibe agua de otros r\u00edos de la regi\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Esperamos que el Alcalde de Monte Llano, Omar S\u00e1nchez, faltando pocos d\u00edas para la Semana Santa, siga el ejemplo de estos ciudadanos, preocupados por la mala impresi\u00f3n que deja visitar la Playa de Cangrejos, ubicada a unos 5 minutos del casco urbano de Monte Llano y del Aeropuerto Intl. Gregorio Luperon. <\/p>\n<p>As\u00ed se pone la playa de Cangrejos, FOTOS DE ARCHIVO&#8230;<a href=\"http:\/\/www.sacandomelao.com\/2008\/11\/fotos-buscando-mbar-en-la-playa.html\">VER M\u00c1S<\/a><\/p>\n<p>fuente: <a href=\"http:\/\/www.sacandomelao.com\">www.sacandomelao.com<\/a>&nbsp;<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apegados al dicho de que \u00aben la uni\u00f3n est\u00e1 la fuerza\u00bb y que no todo hay que dej\u00e1rselo a las autoridades, que de hecho solo se acuerdan de limpiar las playas una vez al a\u00f1o, en septiembre, un grupo de montellaneros, hombres de trabajo, profesores y estudiantes se han enfrascado en la dif\u00edcil pero no imposible tarea de limpiar la playa de Cangrejos.<\/p>\n","protected":false},"author":3,"featured_media":15804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15807"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15804"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}