{"id":15871,"date":"2012-03-20T04:22:01","date_gmt":"2012-03-20T08:22:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-espermatozoides-saben-hacer-calculos-complejos-segun-cientificos-2\/"},"modified":"2012-03-20T04:22:01","modified_gmt":"2012-03-20T08:22:01","slug":"los-espermatozoides-saben-hacer-calculos-complejos-segun-cientificos-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-espermatozoides-saben-hacer-calculos-complejos-segun-cientificos-2\/","title":{"rendered":"Los espermatozoides saben hacer c\u00e1lculos complejos, seg\u00fan cient\u00edficos."},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15869\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_espermatozoides-290x3006734565.jpg\" width=\"290\" height=\"300\" alt=\"espermatozoides-290x3006734565\" class=\"caption\" style=\"float: left;\" \/>Un equipo cient\u00edfico internacional liderado por el espa\u00f1ol Luis \u00c1lvarez y ligado al Instituto Max Planck alem\u00e1n ha descubierto que los espermatozoides son capaces de realizar c\u00e1lculos complejos.<\/div>\n<p>  <!--more-->  <\/p>\n<div>El equipo del Centro Europeo de Estudios e Investigaci\u00f3n Avanzados (Caesar, por sus siglas en ingl\u00e9s) de Bonn determin\u00f3 que cuando el \u00f3vulo libera atrayentes que modifican la concentraci\u00f3n de calcio en el interior de los espermatozoides, \u00e9stos no reaccionan a la concentraci\u00f3n en s\u00ed, sino a los cambios que se producen en esta.<\/div>\n<div>\u201cLo que miden son las tasas de cambio a lo largo del tiempo, es decir, cu\u00e1n r\u00e1pido o lento cambia la concentraci\u00f3n de calcio que entra en la c\u00e9lula del exterior. En lenguaje matem\u00e1tico, lo que hacen es calcular la derivada temporal\u201d, precis\u00f3 en una entrevista a Efe el cient\u00edfico espa\u00f1ol.<\/div>\n<div>As\u00ed, \u201cen funci\u00f3n del valor de la tasa de cambio, alteran la forma en que mueven la cola y cambian de direcci\u00f3n, en otras palabras, el \u2018tim\u00f3n\u2019 de los espermatozoides se mueve al son de la velocidad de cambio del calcio\u201d.<\/div>\n<div>\u201cResulta bastante c\u00f3mico pensar que el c\u00e1lculo diferencial no lo realizaron por primera vez en el siglo XVII, sino que ya lo hac\u00edan los espermatozoides hace m\u00e1s de 400 millones de a\u00f1os\u201d, se\u00f1al\u00f3.<\/div>\n<div>Al mismo tiempo y \u201ca t\u00edtulo anecd\u00f3tico\u201d indic\u00f3 que \u201ccabr\u00eda resaltar que el padre del c\u00e1lculo diferencial (ya sea Isaac Newton o Gottfried Leibniz) todav\u00eda es una cuesti\u00f3n de debate\u201d.<\/div>\n<div>Por otra parte, \u00c1lvarez precis\u00f3 que \u201clos espermatozoides, como muchas otras c\u00e9lulas, calculan multitud de par\u00e1metros\u201d.<\/div>\n<div>\u201cEl c\u00f3mo los miden no esta siempre claro, pero lo m\u00e1s habitual es que midan los valores absolutos y no la velocidad de cambio\u201d, dijo.<\/div>\n<div>El fen\u00f3meno descubierto por el equipo de cient\u00edficos ha sido observado por el momento \u00fanicamente en esperma de varias especies mar\u00edtimas.<\/div>\n<div>\u201cEs por ello que estamos todav\u00eda realizando esfuerzos para conocer el espectro de especies que se comportan de este modo\u201d y, por lo tanto, si este fen\u00f3meno se extiende tambi\u00e9n al esperma humano.<\/div>\n<div>Por otra parte, \u00c1lvarez destac\u00f3 que \u201cel mecanismo que mueve la cola del espermatozoide ha sido conservado a lo largo de la evoluci\u00f3n y se encuentra en diferentes tipos de c\u00e9lulas del cuerpo humano\u201d.<\/div>\n<div>\u201cEstas c\u00e9lulas poseen extensiones similares a la cola del espermatozoide, llamadas cilios m\u00f3viles, y desarrollan diferentes funciones\u201d, agreg\u00f3. En este sentido, \u201ces probable que estos cilios posean estrategias similares a la del espermatozoide para ajustar su movimiento como respuesta a se\u00f1ales\u201d, se\u00f1al\u00f3.<\/div>\n<div>Entre otras funciones, \u201climpian nuestras v\u00edas respiratorias empujando la suciedad hacia el exterior, determinan que nuestro coraz\u00f3n est\u00e9 a la izquierda y no a la derecha durante el desarrollo del embri\u00f3n o empujan el \u00f3vulo desde las trompas hasta el \u00fatero\u201d.<\/div>\n<div>El estudio plantea que al existir otras sustancias mensajeras que controlan las funciones celulares, ser\u00eda posible concluir que las c\u00e9lulas en general son capaces de realizar c\u00e1lculos qu\u00edmicos complejos con estos otros mensajeros intracelulares.<\/div>\n<div>\u201cA nivel cient\u00edfico supone un paso en el entendimiento de c\u00f3mo las c\u00e9lulas procesan las se\u00f1ales que reciben\u201d, indic\u00f3 al respecto. As\u00ed, \u201cel c\u00e1lculo de la tasa de cambio es importante, porque permite a las c\u00e9lulas identificar y responder \u00fanicamente a se\u00f1ales que tienen una tasa de cambio adecuada\u201d, mientras que \u201cen t\u00e9rminos t\u00e9cnicos, les permite filtrar est\u00edmulos por frecuencias\u201d.<\/div>\n<div>\u201cUno puede imaginarse que un sistema complejo compuesto por m\u00e1s de una c\u00e9lula, como un cerebro, pueda realizar este tipo de c\u00e1lculos\u201d, se\u00f1al\u00f3. No obstante, el descubrimiento realizado por el equipo de cient\u00edficos implica que \u201cuna c\u00e9lula posee las herramientas para realizar c\u00e1lculos elaborados por s\u00ed sola\u201d. \u201cLas repercusiones globales de este descubrimiento\u2026 el tiempo lo dir\u00e1\u201d, concluy\u00f3.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.cachicha.com\/2012\/03\/los-espermatozoides-saben-hacer-calculos-complejos-segun-cientificos\/\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un equipo cient\u00edfico internacional liderado por el espa\u00f1ol Luis \u00c1lvarez y ligado al Instituto Max Planck alem\u00e1n ha descubierto que los espermatozoides son capaces de realizar c\u00e1lculos complejos.<\/p>\n","protected":false},"author":3,"featured_media":15869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15871"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15869"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}