{"id":15927,"date":"2012-03-22T13:23:28","date_gmt":"2012-03-22T17:23:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/secreto-queda-libre-de-culpa-en-caso-de-video-en-el-que-aparece-menor\/"},"modified":"2012-03-22T13:23:28","modified_gmt":"2012-03-22T17:23:28","slug":"secreto-queda-libre-de-culpa-en-caso-de-video-en-el-que-aparece-menor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/secreto-queda-libre-de-culpa-en-caso-de-video-en-el-que-aparece-menor\/","title":{"rendered":"Secreto queda libre de culpa en caso de video en el que aparece menor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15926\" style=\"float: left;\" alt=\"el_famoso_biberon\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/el_famoso_biberon.jpg\" width=\"300\" height=\"400\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/el_famoso_biberon.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/el_famoso_biberon-225x300.jpg 225w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>La jueza del Juzgado tambi\u00e9n anul\u00f3 la acusaci\u00f3n civil que pesaba en contra del m\u00e1nager de Secreto&#8230; <!--more-->  <\/p>\n<p>El juez suplente del Sexto Juzgado de la Instrucci\u00f3n del Distrito Nacional exoner\u00f3 ayer de responsabilidad penal al int\u00e9rprete de m\u00fasica urbana Odal\u00eds P\u00e9rez Vicioso, \u201cSecreto, el Famoso Biber\u00f3n\u201d, de la acusaci\u00f3n de utilizar una menor fingiendo sexo y consumiendo bebidas alcoh\u00f3licas en el videoclip del tema \u201cP\u2019a que te d\u00e9\u201d.<\/p>\n<p>El magistrado Bayoan Rodr\u00edguez Portalat\u00edn emiti\u00f3 un auto de no ha lugar a favor de Secreto, el Famoso Biber\u00f3n y de su m\u00e1nager, Juan Ram\u00f3n Hern\u00e1ndez, as\u00ed como Carlos Rond\u00f3n, ejecutivo de la empresa Yacusa Record.<\/p>\n<p>La fiscal\u00eda hab\u00eda pedido al tribunal enviar a juicio de fondo al grupo de los imputados para que respondieran por los hechos que se les imputan.<\/p>\n<p>A la salida del tribunal el int\u00e9rprete de \u201cPa que te d\u00e9\u201d dijo con j\u00fabilo que era inocente de los hechos que se le imputaban, ya que \u00e9l no tiene que ver con las bailarinas que buscan para realizar los videos y que la acusaci\u00f3n lo ha afectado enormemente, pues ni siquiera en los Premios Casandra lo toman en cuenta.<\/p>\n<p>\u201cGracias a Pap\u00e1 Dios, Santo, me siento super bien, a beber para mi barrio\u201d, expreso Secreto, el Famoso Biber\u00f3n.<\/p>\n<p>La querella en contra del artista y de la empresa Yacusa Record fue presentada por los padres de la menor, cuyo nombre se omite por razones legales.<\/p>\n<p>En el video se observa a la menor tomando bebidas alcoh\u00f3licas y simulando un acto sexual, en un baile totalmente para adulto mientras suena el dembow \u201cPa\u2019que te d\u00e9\u201d.<\/p>\n<p>La jueza del Juzgado tambi\u00e9n anul\u00f3 la acusaci\u00f3n civil que pesaba en contra del m\u00e1nager de Secreto, Juan Ram\u00f3n Hern\u00e1ndez.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Masvip.com.do<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jueza del Juzgado tambi\u00e9n anul\u00f3 la acusaci\u00f3n civil que pesaba en contra del m\u00e1nager de Secreto&#8230;<\/p>\n","protected":false},"author":3,"featured_media":15926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15927"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15926"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}