{"id":15998,"date":"2012-03-25T01:28:27","date_gmt":"2012-03-25T05:28:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/escuderia-la-iguana-tm-racing-compitiendo-en-jarabacoa-ver-fotos-y-video\/"},"modified":"2012-03-25T01:28:27","modified_gmt":"2012-03-25T05:28:27","slug":"escuderia-la-iguana-tm-racing-compitiendo-en-jarabacoa-ver-fotos-y-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/escuderia-la-iguana-tm-racing-compitiendo-en-jarabacoa-ver-fotos-y-video\/","title":{"rendered":"Escuder\u00eda La Iguana TM Racing compitiendo en Jarabacoa (VER FOTOS Y VIDEO)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-15997\" style=\"float: left;\" alt=\"IMG_1757\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/IMG_1757.jpg\" width=\"1024\" height=\"768\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/IMG_1757.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/IMG_1757-300x225.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>Jarabacoa.- Este domingo 11 de marzo se realiz\u00f3 la primera carrera puntuable de motocross con la participaci\u00f3n de corredores de diferentes partes del pa\u00eds y como es claro, la participaci\u00f3n de representantes de Sos\u00faa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Josiel Brito (La Iguanita) qued\u00f3 en segundo lugar en categor\u00eda 250 CC y en tercer lugar en la categor\u00eda 450 CC; desde que Josiel comenz\u00f3 a participar en carreras, tanto fuera como dentro del pa\u00eds ha ido imponiendo su calidad y exaltando la bandera de Sos\u00faa.<\/p>\n<p>&nbsp;<object width=\"647\" height=\"386\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629299386298%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629299386298%2F&amp;set_id=72157629299386298&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"647\" height=\"386\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629299386298%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629299386298%2F&amp;set_id=72157629299386298&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p><object width=\"651\" height=\"415\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/M5ZXJYL8zpM\" \/><embed width=\"651\" height=\"415\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/M5ZXJYL8zpM\" wmode=\"opaque\"\/><\/object><\/p>\n<p>Felicitamos a La Iguanita y a los sosuenses que fueron a apoyar desde el s\u00e1bado 11 hasta el domingo 12 de marzo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jarabacoa.- Este domingo 11 de marzo se realiz\u00f3 la primera carrera puntuable de motocross con la participaci\u00f3n de corredores de diferentes partes del pa\u00eds y como es claro, la participaci\u00f3n de representantes de Sos\u00faa.<\/p>\n","protected":false},"author":3,"featured_media":15997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-15998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=15998"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/15998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/15997"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=15998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=15998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=15998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}