{"id":16036,"date":"2012-03-22T17:29:06","date_gmt":"2012-03-22T21:29:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-imposibilidad-de-traer-al-mundo-un-bebe-causas-de-la-infertilidad-2\/"},"modified":"2012-03-22T17:29:06","modified_gmt":"2012-03-22T21:29:06","slug":"la-imposibilidad-de-traer-al-mundo-un-bebe-causas-de-la-infertilidad-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-imposibilidad-de-traer-al-mundo-un-bebe-causas-de-la-infertilidad-2\/","title":{"rendered":"La imposibilidad de traer al mundo un beb\u00e9, causas de la infertilidad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16035\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_11-290x183.jpg\" width=\"290\" height=\"183\" alt=\"11-290x183\" class=\"caption\" style=\"float: left;\" \/>Seguramente el deseo insatisfecho de tener un&nbsp;<strong>reci\u00e9n nacido<\/strong>&nbsp;en casa, es una de las frustraciones m\u00e1s grandes que puede atravesar una pareja. En este art\u00edculo hablaremos de esa imposibilidad de traer al mundo un beb\u00e9 denominada infertilidad; sea masculina o femenina no siempre viene como consecuencia de una enfermedad, sino que muchas de las causas est\u00e1n ligadas a los estilos de vida de los posibles progenitores de&nbsp;<strong>\u00e9l bebe<\/strong>.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Como lo dec\u00edamos muchas veces el estilo de vida tienen&nbsp;una gran influencia sobre la infertilidad, sobre todo el estr\u00e9s, el consumo excesivo de alcohol y de caf\u00e9 y el tabaco. Por otra parte los aspectos ps\u00edquicos tambi\u00e9n pueden afectar negativamente. Por ello para las parejas que planifican tener&nbsp;<strong>bebes<\/strong>, es preciso que revisen los h\u00e1bitos cotidianos de vida.<\/p>\n<p>Si crees que ha pasado un tiempo prudente en la espera de tener un&nbsp;<strong>reci\u00e9n nacido<\/strong>; antes de iniciar un tratamiento de reproducci\u00f3n asistida, debes investigar las causas por las que no es posible concebir un hijo. Los dos miembros de la pareja deben someterse a ex\u00e1menes en el caso de la mujer se analiza el ciclo menstrual, se observa el fol\u00edculo ov\u00e1rico en desarrollo que es completado con un an\u00e1lisis &nbsp;de sangre para comprobar la presencia de la hormona LH u hormona luteinizante, que estimula las c\u00e9lulas ov\u00e1ricas y responsable de la evoluci\u00f3n.<\/p>\n<p>Otra parte en el caso del hombre, este debe someterse a un estudio denominado semiograma o espermiograma, para analizar el semen y valorar la cantidad, la movilidad y la forma de los espermatozoides. Para mayor informaci\u00f3n se&nbsp; considera que una cifra aceptable al menos 20 millones de espermatozoides por mil\u00edmetro de esperma, de los cuales la mitad deben tener buena movilidad.<\/p>\n<p>En resumen, el grado de influencia de los estilos de vida perjudiciales como el tabaquismos, alcoholismo, estados de estr\u00e9s y mala alimentaci\u00f3n, pueden ser causas combinadas para la infertilidad, por ello es vital trabajar para modificar estos malos h\u00e1bitos precozmente porque de lo contrario en el caso de las mujeres es muy dif\u00edcil revertir los da\u00f1os que se generan en el organismo.<\/p>\n<p> <a href=\"http:\/\/www.pensandoenbebes.com\/la-imposibilidad-de-traer-al-mundo-un-bebe-causas-de-la-infertilidad\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguramente el deseo insatisfecho de tener un&nbsp;reci\u00e9n nacido&nbsp;en casa, es una de las frustraciones m\u00e1s grandes que puede atravesar una pareja. En este art\u00edculo hablaremos de esa imposibilidad de traer al mundo un beb\u00e9 denominada infertilidad; sea masculina o femenina no siempre viene como consecuencia de una enfermedad, sino que muchas de las causas est\u00e1n ligadas a los estilos de vida de los posibles progenitores de&nbsp;\u00e9l bebe.<\/p>\n","protected":false},"author":3,"featured_media":16035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16036"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16035"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}