{"id":16078,"date":"2012-03-27T16:37:21","date_gmt":"2012-03-27T20:37:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-10-cosas-que-talvez-no-sabias-de-ti-mismo\/"},"modified":"2012-03-27T16:37:21","modified_gmt":"2012-03-27T20:37:21","slug":"las-10-cosas-que-talvez-no-sabias-de-ti-mismo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-10-cosas-que-talvez-no-sabias-de-ti-mismo\/","title":{"rendered":"Las 10 cosas que talvez no sab\u00edas de ti mismo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16076\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/cuerpo-1876784367768998786564334.jpeg\" width=\"259\" height=\"194\" alt=\"cuerpo-1876784367768998786564334\" class=\"caption\" style=\"float: left;\" \/>A lo largo del tiempo siempre encontramos cosas nuevas de nosotros mismos, pero aunque no lo creas siempre van a ver cosas que desconoces de ti. Por eso te invitamos a ver 10 cosas muy curiosas que no sabias de ti. Para que ahora si lo sepas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>1. El est\u00f3mago excreta \u00e1cidos corrosivos. En efecto, el \u00e1cido clorh\u00eddrico (compuesto que se usa industralmente para tratar los metales) puede corroer el acero, pero la mucosidad que recubre las paredes estomacales mantiene bajo control esta peligrosa sustancia.<\/p>\n<p>2. \u00bfSab\u00edas que la posici\u00f3n y los recuerdos est\u00e1n relacionados? Seg\u00fan el art\u00edculo, si trabajaste repartiendo peri\u00f3dicos en bicicleta cuando eras ni\u00f1o (yo no lo hice, pero obviamente LifeScience es una web estadounidense), cuando te subas a la bicicleta est\u00e1tica del gimnasio es probable que recuerdes mejor la vieja ruta de reparto infantil.<\/p>\n<p>3. La tercera tampoco la conoc\u00eda. Al parecer el cuerpo humano cuenta con un mecanismo peculiar para regular sus niveles de calcio y f\u00f3sforo. Cuando los niveles de estos dos elementos no son lo bastante altos, ciertas hormonas pueden provocar ruputuras \u00f3seas para que el calcio se eleve hasta alcanzar la concentraci\u00f3n apropiada.<\/p>\n<p>4. La cuarta caracter\u00edstica es tambi\u00e9n bastante obvia: buena parte de lo que comemos se usa como combustible cerebral. Aunque nuestro cerebro solo supone el 2% del peso total corporal, este \u00f3rgano demanda el 20% de los recursos de ox\u00edgeno y cal\u00f3ricos. Para que el suministro no falle contamos con tres grandes arterias cerebrales que bombean constantemente ox\u00edgeno. Cuando una de ellas se bloquea o se rompe, las neuronas afectadas se \u201cmueren de hambre\u201d por la ausencia de energ\u00eda. Esto es lo que sucede en los infartos cerebrales.<\/p>\n<p>5. El quinto punto tratado tambi\u00e9n es conocido. Cuando una mujer entra en fase de menopausia, sus fol\u00edculos se echan a perder. Hablamos de miles de \u00f3vulos que nunca llegar\u00e1n a desarrollarse. Una adolescente cuenta con 34.000 fol\u00edculos, de los cuales solo llegar\u00e1n a \u00f3vulos 350 a lo largo de su vida.<\/p>\n<p>6. Seguimos. \u00bfSabi\u00e1is que la pubertad reestructura el cerebro ? Los insportables adolescentes y sus cambios hormonales\u2026 la cosa es m\u00e1s seria de lo que parece. La testosterona influye en el desarrollo de las neuronas, y los cambios que produce en la estructura cerebral tiene consecuencias en el comportamiento. Mientras las regiones del c\u00f3rtex frontal maduran, los chicos y chicas \u201cen la edad del pavo\u201d padecen torpeza emocional, apat\u00eda y pocas habilidades a la hora de tomar decisiones.<\/p>\n<p>7. Otro hecho bastante desconocido en s\u00e9ptimo lugar: los cilios celulares mueven mucosidades. La mayor\u00eda de las c\u00e9lulas de nuestro cuerpo cuentan con unos org\u00e1nulos llamados cilios que ayudan en una serie de funciones que van desde la digesti\u00f3n al o\u00eddo. En la nariz, los cilios ayudan a drenar la mucosidad de la cavidad nasal hacia la garganta. Cuando el tiempo se enfr\u00eda este proceso de drenado se ralentiza, lo cual hace que el exceso de mucosidad deba subsanarse de otro modo (ah\u00ed entra tu cleenex).<\/p>\n<p>8. Y llegamos a las tres \u00faltimas. El aumento en el tama\u00f1o de nuestros cerebros nos llev\u00f3 al dentista. B\u00e1sicamente este apartado habla de las muelas del juicio. Hubo un tiempo en que fueron \u00fatiles como tercer juego de molares para mascar carne. Nuestro cerebro al crecer provoc\u00f3 cambios en la estructura de nuestra mand\u00edbula. Ahora nuestras bocas est\u00e1n \u201cdemasiado llenas\u201d de dientes.<\/p>\n<p>9. El mundo r\u00ede contigo. Al igual que el bostezo, la risa es contagiosa. O\u00edr una risa estimula realmente la regi\u00f3n cerebral asociada a los movimientos faciales. La imitaci\u00f3n juega un papel importante en la interaci\u00f3n social. Re\u00edrse y bostezar, podr\u00edan ser formas de crear fuertes v\u00ednculos sociales dentro del grupo.<\/p>\n<p>10. Y para acabar. Tu piel tiene cuatro colores. Todas las pieles, sin pigmentos, parecen blancas en su base. Los vasos sangu\u00edneos pr\u00f3ximos a la superficie a\u00f1aden un tono rojizo. Los carotenoides de la grasa a\u00f1aden un pigmento amarillo. La melanina da una tonalidad sepia creada como respuesta a los rayos ultravioleta (que en caso de grandes concentraciones parecen negras). Estos cuatro tonos combinados en distintas proporciones dan lugar a todos los colores de piel de la Tierra.<\/p>\n<p><a href=\"http:\/\/10curiosidades.com\/las-10-cosas-que-no-sabias-de-ti-mismo\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A lo largo del tiempo siempre encontramos cosas nuevas de nosotros mismos, pero aunque no lo creas siempre van a ver cosas que desconoces de ti. Por eso te invitamos a ver 10 cosas muy curiosas que no sabias de ti. Para que ahora si lo sepas.<\/p>\n","protected":false},"author":3,"featured_media":16076,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-16078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16078"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16076"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}