{"id":16213,"date":"2012-03-27T14:53:27","date_gmt":"2012-03-27T18:53:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/comienza-a-derrumbarse-el-merengue-de-calle-2\/"},"modified":"2012-03-27T14:53:27","modified_gmt":"2012-03-27T18:53:27","slug":"comienza-a-derrumbarse-el-merengue-de-calle-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/comienza-a-derrumbarse-el-merengue-de-calle-2\/","title":{"rendered":"Comienza a derrumbarse el merengue de calle"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16211\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_kkkkkkkkkkkkkkk56758543834.jpg\" width=\"620\" height=\"412\" alt=\"kkkkkkkkkkkkkkk56758543834\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_kkkkkkkkkkkkkkk56758543834.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_kkkkkkkkkkkkkkk56758543834-300x199.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>En la m\u00fasica no hay f\u00f3rmula exacta para lograr un \u00e9xito. Lo que hoy puede funcionar, ma\u00f1ana est\u00e1 desfasado y viceversa. As\u00ed de simple. Y los \u00faltimos a\u00f1os son un reflejo de lo cambiante que es el negocio de la m\u00fasica, cuando un d\u00eda estaba muy de moda el reggaet\u00f3n, luego la bachata urbana, posteriormente el merengue de calle y ahora el dembow.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pero ha sido el merengue de calle que ha sufrido en su popularidad la mayor ca\u00edda en el \u00faltimo a\u00f1o. El acelerado ritmo que aliment\u00f3 este vilipendiado estilo musical, que colocaba canciones en internet y en la radio con una rapidez inusitada, ha ido en franca disminuci\u00f3n, obligando a algunos de sus exponentes m\u00e1s importantes, como es el caso de Tulile, a salir del pa\u00eds buscando posibilidades de negocio en otras plazas como la de Nueva York y otras ciudades de EE.UU.<\/p>\n<p>La inconsistencia es para Ram\u00f3n Lluberes, director de Esc\u00e1ndalo 107.3 FM, una de las principales causas de la salida del mercado de esta m\u00fasica. \u201cLa mayor\u00eda de esos grupos hacen uno o dos temas, los pegan y no se preocupan en preparar un repertorio. No siguen produciendo nuevas canciones, pero adem\u00e1s, sus canciones tienen un corte refranero de corta duraci\u00f3n, de poca vida. Ya a los tres meses nadie los escucha. No es lo que pasa con el merengue con buenas letras, que dura m\u00e1s para entrar al gusto popular, pero al final permanecen\u201d, dijo el experimentado director radial en entrevista telef\u00f3nica con elCaribe.<\/p>\n<p>Una cotizaci\u00f3n muy por encima de lo que puede aguantar la plaza dominicana, tendencia que se ha manifestado con la mayor\u00eda de los exponentes de este g\u00e9nero cuando est\u00e1n pegados, tambi\u00e9n ha afectado su permanencia. \u201cSi no tienen difusi\u00f3n y pegada no van a tener contrataciones. Tambi\u00e9n sus tarifas, en su mayor\u00eda, se fueron por encima de lo que pueden generar en una puerta y eso lo alej\u00f3 de esos escenarios y le dio m\u00e1s apertura a los dembowsero y reggaetoneros con menos cotizaci\u00f3n pero que estaban pegados\u201d, agreg\u00f3 Lluberes.<\/p>\n<p>Es el panorama en el que se circunscriben algunos de los exponentes m\u00e1s populares del merengue de calle en los \u00faltimos a\u00f1os. Pr\u00e1cticamente nulos en estos d\u00edas, y los hay como Juli\u00e1n Oro Duro y Tito Swing de quienes no se sabe de su existencia, est\u00e1n Tulile, Moreno Negr\u00f3n y El Sujeto, quienes en alg\u00fan momento dominaban en el negocio.<\/p>\n<p>En lo que va del 2012, ninguno de estos cantantes \u2013que abrazaron una propuesta que dio al traste un cancionero cuya materia prima sal\u00eda del refranero popular\u2013 se ha acercado por las emisoras que programan sus canciones, seg\u00fan coment\u00f3 ayer Mon Lluberes. \u201cEsto llama a preocupaci\u00f3n, porque fueron artistas que cosecharon una buena popularidad entre el p\u00fablico dominicano\u201d, agreg\u00f3 el director de Esc\u00e1ndalo 107.3 FM.<\/p>\n<p>Y si las contrataciones que en un momento se contaban de hasta tres actividades en un d\u00eda cualquiera de fin de semana, dejan de caer en las oficinas de estos exponentes, la realidad hoy es insostenible para algunos de ellos que descuidaron aspectos fundamentales para un artista seguir vigente. \u201cLa inestabilidad de estos cantantes, la mala calidad de su m\u00fasica, los altos costos de sus tarifas y la falta de inversi\u00f3n en la promoci\u00f3n\u201d fueron factores que tuvieron que ver con la ca\u00edda de este estilo musical, seg\u00fan explic\u00f3 Carlos Bautista, m\u00e1nager de Mozart La Para.<\/p>\n<p>El merengue de calle, contrario a otros estilos como el reggaet\u00f3n, no aprovech\u00f3 la popularidad de su propuesta para evolucionar a una mejor orquestaci\u00f3n, mejores arreglos y un manejo m\u00e1s profesional de sus protagonistas. La falta de productores tambi\u00e9n ha sido su tal\u00f3n de Aquiles. \u201cEn esa m\u00fasica lo que est\u00e1 faltando es grabar canciones que conecten directamente con el p\u00fablico. M\u00e1s que hacer m\u00fasica urbana, sino m\u00fasica que pueda permanecer y cotizarse en el mercado internacional\u201d ha sido una de las necesidades incumplidas de este estilo musical, seg\u00fan coment\u00f3 el locutor Brea Frank, quien estuvo nominado a los Premios Casandra en su pasada edici\u00f3n.<\/p>\n<p>En el boca a boca de la gente, para no decir de su ausencia en la radio tropical, no se escuchan canciones como \u201cEl caf\u00e9\u201d, \u201cEl bol\u00f3n\u201d, \u201cHablan de todo\u201d, (Tito Swing), \u201cPlomo, plomo\u201d, del Negro 5 Estrellas, \u201cEl camar\u00f3n\u201d, \u201cCarrito rojo de carrera\u201d (Silvio Mora), \u201cLa culebra\u201d, \u201cPrende la hooka\u201d, de Tulile; \u201cCon cotorra no\u201d, de El Sujeto y \u201cChambonea\u201d, Si t\u00fa no me amas\u201d de Omega, que fueron grandes \u00e9xitos en boca de estos exponentes.<\/p>\n<p>Visto en&nbsp;<b>Losmoncioneros.com<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la m\u00fasica no hay f\u00f3rmula exacta para lograr un \u00e9xito. Lo que hoy puede funcionar, ma\u00f1ana est\u00e1 desfasado y viceversa. As\u00ed de simple. Y los \u00faltimos a\u00f1os son un reflejo de lo cambiante que es el negocio de la m\u00fasica, cuando un d\u00eda estaba muy de moda el reggaet\u00f3n, luego la bachata urbana, posteriormente el merengue de calle y ahora el dembow.<\/p>\n","protected":false},"author":3,"featured_media":16211,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16213"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16211"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}