{"id":16351,"date":"2012-03-29T15:54:44","date_gmt":"2012-03-29T19:54:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/muy-personal-dice-adios-de-la-pantalla-chica-dominicana-2\/"},"modified":"2012-03-29T15:54:44","modified_gmt":"2012-03-29T19:54:44","slug":"muy-personal-dice-adios-de-la-pantalla-chica-dominicana-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muy-personal-dice-adios-de-la-pantalla-chica-dominicana-2\/","title":{"rendered":"Muy Personal\u201d dice adi\u00f3s de la pantalla chica dominicana"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16349\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_miralba_ruiz766785745.jpg\" width=\"320\" height=\"226\" alt=\"miralba_ruiz766785745\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_miralba_ruiz766785745.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_miralba_ruiz766785745-300x211.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/03\/sosua_images_miralba_ruiz766785745-75x52.jpg 75w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>Con siete anos en el aire, cargados de gratas experiencias y grandes satisfacciones para su mentora, conductora y productora ejecutiva Miralba Ruiz, la Revista Semanal de Variedades \u201cMuy Personal\u201d dice adi\u00f3s de la pantalla chica dominicana este s\u00e1bado 31 de marzo en su horario regular de las 7:00 de la noche, por Teleantillas, canal 2.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Para Miralba Ruiz, quien ha sido clara y reiterativa al afirmar que no pretender culminar sus d\u00edas frente a las c\u00e1maras, ya que en un futuro se ve produciendo televisi\u00f3n para ella misma y para otros talentos de la televisi\u00f3n dominicana; visualiza este cese de Muy Personal como el inicio de una nueva etapa en su carrera profesional en el mundo de la comunicaci\u00f3n.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cAmo lo que hago y creo que la televisi\u00f3n te ofrece m\u00faltiples maneras de comunicar. He descubierto en los programas de temporada una elemento interesante de llevar entretenimiento, educar, sensibilizar a la audiencia, pero sobre todo de llevar variedad\u201d, puntualiz\u00f3 la comunicadora.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Senala que todo este proceso ha sido una hermosa coincidencia de Dios porque se ubic\u00f3 en el momento perfecto. \u201cCon la llegada de un nuevo beb\u00e9 a la familia la pausa era inminente; as\u00ed que todo qued\u00f3 en orden divino para darme paso a una de las experiencias m\u00e1s gratas de mi vida\u2026 la maternidad; todos en casa estamos felices y ansiosos con el nuevo nino\/a de la familia\u201d, indic\u00f3 Ruiz. Miralba revel\u00f3 que seguir\u00e1 trabajando en algunos proyectos por separado para el Grupo Corripio hasta la llegada del beb\u00e9, \u201cya luego de la pausa retornar\u00e9 con otros proyectos personales, de temporada, de los cuales estoy segura ser\u00e1n del benepl\u00e1cito de la teleaudiencia\u201d.<\/div>\n<div><\/div>\n<div><\/div>\n<div>De igual manera confes\u00f3 que para inicios del pr\u00f3ximo ano 2013 regresa al Grupo Corripio con un nuevo proyecto, que se transmitir\u00e1 semanalmente. Ruiz aprovech\u00f3 la oportunidad para agradecer el apoyo incondicional del Grupo Corripio, de las agencias publicitarias, de los clientes y relacionados, de los queridos amigos de la prensa radial, escrita, televisiva y digitales; as\u00ed como de los televidentes. Asimismo, agradeci\u00f3 el apoyo y entrega del equipo de producci\u00f3n que actualmente conformaba Muy Personal y a todos aquellos que en alg\u00fan momento formaron parte de la empresa.<\/div>\n<div><\/div>\n<div><\/div>\n<div>\u201cQuiero decir gracias a todos por poner su talento a la disposici\u00f3n de Producciones Miralba Ruiz, para entregar un producto de calidad semana tras semana\u201d, concluy\u00f3 Miralba Ruiz. No se pierda este s\u00e1bado 31 de marzo desde las 7:00 P.M. un programa muy especial, cargado de emociones muy personales, por Teleantillas, canal 2.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.cachicha.com\/2012\/03\/muy-personal-dice-adios-de-la-pantalla-chica-dominicana\/\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con siete anos en el aire, cargados de gratas experiencias y grandes satisfacciones para su mentora, conductora y productora ejecutiva Miralba Ruiz, la Revista Semanal de Variedades \u201cMuy Personal\u201d dice adi\u00f3s de la pantalla chica dominicana este s\u00e1bado 31 de marzo en su horario regular de las 7:00 de la noche, por Teleantillas, canal 2.<\/p>\n","protected":false},"author":3,"featured_media":16349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16351"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16349"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}