{"id":16366,"date":"2012-04-04T15:50:26","date_gmt":"2012-04-04T19:50:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/bicimonteo-los-navas-patrocinado-por-la-casa-de-las-bicicletas-agua-sasino-y-sosuaonlinenet-ver-fotos-y-videos\/"},"modified":"2012-04-04T15:50:26","modified_gmt":"2012-04-04T19:50:26","slug":"bicimonteo-los-navas-patrocinado-por-la-casa-de-las-bicicletas-agua-sasino-y-sosuaonlinenet-ver-fotos-y-videos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bicimonteo-los-navas-patrocinado-por-la-casa-de-las-bicicletas-agua-sasino-y-sosuaonlinenet-ver-fotos-y-videos\/","title":{"rendered":"BiciMonteo Los Navas patrocinado por La Casa de las Bicicletas, Agua Sasino y Sosuaonline.net ( VER FOTOS Y VIDEOS)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16365\" style=\"float: left;\" class=\"caption\" alt=\"P1090186\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/P1090186.jpg\" width=\"1024\" height=\"768\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/P1090186.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/P1090186-300x225.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>Sos\u00faa.- El pasado domingo 01 de abril del 2012 efectuamos con un rotundo \u00e9xito &nbsp;el \u201cBiciMonteo Los Navas\u201d, con la participaci\u00f3n de m\u00e1s de 80 ciclistas j\u00f3venes y menos j\u00f3venes, cubriendo la ruta Los Charamicos, Sos\u00faa Abajo, Maranatha, Bella Vista, Arroyo Seco hasta el r\u00edo de Madre Vieja.<\/p>\n<p>  <!--more-->  <\/p>\n<p>En todo momento prim\u00f3 la energ\u00eda y alegr\u00eda entre los ciclistas y aunque algunos nos cansamos o se nos da\u00f1o la bicicleta, siempre estuvo el equipo de apoyo que socorr\u00eda al necesitado. Hubo Agua Sasino en todo el camino, adicionado con Gatorade para rehidratar, a la llegada un sabroso moro de guandules con tajo (Carne de Cerdo) y se aprovech\u00f3 hasta para una celebraci\u00f3n de cumplea\u00f1os con biscocho.&nbsp;&nbsp;&nbsp;<\/p>\n<p><object width=\"497\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629374829324%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629374829324%2F&amp;set_id=72157629374829324&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"497\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629374829324%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629374829324%2F&amp;set_id=72157629374829324&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p>Este evento fue organizaci\u00f3n de La Casa de Las Bicicletas y el patrocinio de Agua Sasino &amp; Sosuaonline.net, adem\u00e1s de la asistencia medica del Dr. Jason Dom\u00ednguez y todo un equipo, desde los cocineros, mec\u00e1nicos de bicicletas y camar\u00f3grafos.<\/p>\n<p><object width=\"502\" height=\"369\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/BDOM8aAooaU\" \/><embed width=\"502\" height=\"369\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/BDOM8aAooaU\" wmode=\"opaque\"\/><\/object><\/p>\n<p><object width=\"500\" height=\"372\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/IxIAKG16NuM\" \/><embed width=\"500\" height=\"372\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/IxIAKG16NuM\" wmode=\"opaque\"\/><\/object><br \/>Nos sentimos muy contentos con la misi\u00f3n cumplida y la bendiciones que Dios dispuso para la realizaci\u00f3n de este apoyo a nuestra comunidad que en verdad no dispone de muchas alternativas de distracci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- El pasado domingo 01 de abril del 2012 efectuamos con un rotundo \u00e9xito &nbsp;el \u201cBiciMonteo Los Navas\u201d, con la participaci\u00f3n de m\u00e1s de 80 ciclistas j\u00f3venes y menos j\u00f3venes, cubriendo la ruta Los Charamicos, Sos\u00faa Abajo, Maranatha, Bella Vista, Arroyo Seco hasta el r\u00edo de Madre Vieja.<\/p>\n","protected":false},"author":3,"featured_media":16365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16366"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16365"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}