{"id":16576,"date":"2012-04-10T15:44:55","date_gmt":"2012-04-10T19:44:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-licey-tiene-20-peloteros-en-gl\/"},"modified":"2012-04-10T15:44:55","modified_gmt":"2012-04-10T19:44:55","slug":"el-licey-tiene-20-peloteros-en-gl","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-licey-tiene-20-peloteros-en-gl\/","title":{"rendered":"El Licey tiene 20 peloteros en GL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16575\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_DE205D65-440F-4A1C-B244-08C3BBDDCD60.jpg__294__440__CROPz0x294y440.jpeg\" width=\"294\" height=\"202\" alt=\"DE205D65-440F-4A1C-B244-08C3BBDDCD60.jpg__294__440__CROPz0x294y440\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_DE205D65-440F-4A1C-B244-08C3BBDDCD60.jpg__294__440__CROPz0x294y440.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_DE205D65-440F-4A1C-B244-08C3BBDDCD60.jpg__294__440__CROPz0x294y440-75x52.jpeg 75w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>Para este a\u00f1o 2012, los Tigres del Licey tendr\u00e1n una representaci\u00f3n m\u00e1s amplia que la que tuvo al inicio de la temporada pasada en Grandes Ligas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un total de 20 miembros de la organizaci\u00f3n azul tienen un puesto en la n\u00f3mina de sus respectivas novenas para esta campa\u00f1a, lo que representa un 24% de los 84 dominicanos que hay actualmente en el roster activo de los 30 conjuntos.<\/p>\n<p>Esos 20 peloteros se dividen en 11 lanzadores, seis infielders, dos jardineros y un receptor, informa una nota de la oficina del Licey.<\/p>\n<p>Los pitchers son: Juan Carlos Cruz (Piratas), Ervin Santana (Anaheim), Cristhian Mart\u00ednez (Atlanta), Ubaldo Jim\u00e9nez (Cleveland) y Fautino de los Santos (Oakland).<\/p>\n<p>Adem\u00e1s, Carlos M\u00e1rmol (Cubs), Esmil Rogers (Colorado), H\u00e9ctor Noes\u00ed (Seattle), Frank Francisco (Mets), V\u00edctor Marte (San Luis) y Guillermo Mota (San Francisco).<\/p>\n<p>A estos se suman defensores del cuadro como Erick Aybar (Anaheim), Hanley Ram\u00edrez (Marlins), Juan Francisco (Atlanta), Carlos Pe\u00f1a (Tampa Bay), Aramis Ram\u00edrez (Milwaukee) y Yamaico Navarro (Pittsburgh).<\/p>\n<p>Jos\u00e9 Bautista (Toronto) y Emilio Bonifacio (Miami) son los encargados de defender los jardines, mientras que Ronny Paulino (Baltimore) es el catcher que tiene el Licey en la Gran Carpa.<\/p>\n<p>Es importante se\u00f1alar que el lanzador Michael Pineda no est\u00e1 en roster de 25 debido a que est\u00e1 en lista de lesionados de 15 d\u00edas por tendinitis en el hombro derecho.<\/p>\n<p><a href=\"http:\/\/www.listindiario.com\/el-deporte\/2012\/4\/10\/228240\/El-Licey-tiene-20-peloteros-en-GL\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para este a\u00f1o 2012, los Tigres del Licey tendr\u00e1n una representaci\u00f3n m\u00e1s amplia que la que tuvo al inicio de la temporada pasada en Grandes Ligas.<\/p>\n","protected":false},"author":3,"featured_media":16575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16576"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16575"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}