{"id":16720,"date":"2012-04-17T17:48:19","date_gmt":"2012-04-17T21:48:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/fiesta-de-la-primavera-en-la-calle-pedro-clisante-fue-un-exito\/"},"modified":"2012-04-17T17:48:19","modified_gmt":"2012-04-17T21:48:19","slug":"fiesta-de-la-primavera-en-la-calle-pedro-clisante-fue-un-exito","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fiesta-de-la-primavera-en-la-calle-pedro-clisante-fue-un-exito\/","title":{"rendered":"\u00bbFiesta de la Primavera\u00bb en la Calle Pedro Clisante fue un \u00e9xito"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16719\" style=\"float: left;\" class=\"caption\" alt=\"04-17_streetparty_1\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_04-17_streetparty_1.jpg\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_04-17_streetparty_1.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_04-17_streetparty_1-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Este pasado s\u00e1bado 14 de abril, algunos empresarios de la calle Pedro Clisante organizaron una fiesta en la calle. La fiesta tuvo lugar con&nbsp;el texto promocional \u00abStreet Party &#8211; Primavera! &#8216;Los empresarios del Para\u00edso Schnitzel, Cubana Caf\u00e9 y la&nbsp;Bella pizzer\u00eda Italia contrat\u00f3 una banda de jazz que toc\u00f3 realmente excelente.<\/div>\n<p>  <!--more-->  <\/p>\n<div>\n<p>No era s\u00f3lo la m\u00fasica de jazz y lo que tocaban , sino que tambi\u00e9n tocaba m\u00fasica pop de los a\u00f1os &#8217;80 para un p\u00fablico m\u00e1s amplio. La calle fue cerrada al tr\u00e1nsito vehicular&nbsp;a partir del Schnitzel Paradise. <\/p>\n<p>En la calle se crearon un mont\u00f3n de mesas en las que todos los grupos de personas mostraban su alegr\u00eda. Wolfgang de El Para\u00edso Schnitzel estaba muy contento con el gran apoyo mostrado por el p\u00fablico que &nbsp;acudi\u00f3 en masa. <\/p>\n<p>\u00c9l prometi\u00f3 que pronto se llevar\u00e1 a cabo otra fiesta en la calle. \u00abVale la pena repetir\u00bb, dijo, visiblemente encantado.<\/p><\/div>\n<div><\/div>\n<div>Fuente: <a href=\"http:\/\/www.sosuanews.com\/index.php?id=2934&amp;article=1\">sosuanews.com&nbsp;<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este pasado s\u00e1bado 14 de abril, algunos empresarios de la calle Pedro Clisante organizaron una fiesta en la calle. La fiesta tuvo lugar con&nbsp;el texto promocional \u00abStreet Party &#8211; Primavera! &#8216;Los empresarios del Para\u00edso Schnitzel, Cubana Caf\u00e9 y la&nbsp;Bella pizzer\u00eda Italia contrat\u00f3 una banda de jazz que toc\u00f3 realmente excelente.<\/p>\n","protected":false},"author":3,"featured_media":16719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16720"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16719"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}