{"id":16980,"date":"2012-04-30T19:00:00","date_gmt":"2012-04-30T23:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/actualidad-la-camara-que-dice-lo-que-ve\/"},"modified":"2012-04-30T19:00:00","modified_gmt":"2012-04-30T23:00:00","slug":"actualidad-la-camara-que-dice-lo-que-ve","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/actualidad-la-camara-que-dice-lo-que-ve\/","title":{"rendered":"ACTUALIDAD: La c\u00e1mara que dice lo que ve"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-16979\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_120429083254_descripcion__304x171_other_nocredit.jpg\" width=\"304\" height=\"171\" alt=\"120429083254_descripcion__304x171_other_nocredit\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_120429083254_descripcion__304x171_other_nocredit.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/04\/sosua_images_120429083254_descripcion__304x171_other_nocredit-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Un estudiante de Estados Unidos invent\u00f3 una c\u00e1mara capaz de describir im\u00e1genes. El aparato carga fotos en internet, que luego son descritas en cuesti\u00f3n de minutos por usuarios del servicio&nbsp;<em>Mechanical<\/em>&nbsp;Turk de Amazon.<\/div>\n<div>Luego la descripci\u00f3n se env\u00eda a la c\u00e1mara y \u00e9sta la imprime.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>Mecanismo:&nbsp;El portento lo dise\u00f1\u00f3 Matt Richardson, graduado en comunicaci\u00f3n interactiva de la Universidad de Nueva York.<\/div>\n<p> <\/p>\n<div>\u00abHab\u00eda estado pensando mucho en c\u00f3mo las c\u00e1maras capturan much\u00edsimos datos cuando toman im\u00e1genes: su localizaci\u00f3n, fecha, el tipo de c\u00e1mara y modelo\u00bb, dijo a la BBC.<\/div>\n<div>\u00abUn mont\u00f3n de informaci\u00f3n, pero mucha no es \u00fatil o tiene uso limitado\u00bb.<\/div>\n<div>La c\u00e1mara usa&nbsp;<em>BeagleBone<\/em>, una peque\u00f1a computadora utilizada en prototipos y computadoras experimentales, y est\u00e1 conectada a<em>Mechanical Turk<\/em>, un servicio donde la gente puede realizar tareas a cambio de peque\u00f1as sumas de dinero.<\/div>\n<div>En este caso, Richardson pag\u00f3 US$1,25 por cada fotograf\u00eda descrita.<\/div>\n<div>\u00abEmpec\u00e9 ofreciendo un precio bajo por la descripci\u00f3n y llev\u00f3 como 15 minutos el recibirla\u00bb, dijo.<\/div>\n<div>\u00abComo quer\u00eda tener una respuesta m\u00e1s r\u00e1pida, increment\u00e9 el pago, y finalmente llegu\u00e9 a los US$1,25, que es lo que cuesta una impresi\u00f3n con una c\u00e1mara Polaroid. A este precio, la descripci\u00f3n llega en cuesti\u00f3n de tres a seis minutos\u00bb.<\/div>\n<div>Adem\u00e1s de utilizar<em>&nbsp;Mechanical Turk<\/em>, Richardson configur\u00f3 la c\u00e1mara para enviar la fotograf\u00eda a cualquier amigo disponible para que \u00e9ste la describa gratis.<\/div>\n<h2>An\u00e1lisis \u00absubjetivos\u00bb<\/h2>\n<div><\/div>\n<div>Seg\u00fan Richardson, aunque no existe ninguna tecnolog\u00eda para realizar la labor descriptiva, espera que aparezca en alg\u00fan momento, dando a la c\u00e1mara mayor utilidad.<\/div>\n<div>\u00abImagino un tiempo donde las c\u00e1maras puedan captar informaci\u00f3n m\u00e1s \u00fatil que luego pueda buscarse, compararse y clasificarse\u00bb, expres\u00f3.<\/div>\n<div>\u00abA pesar de que la tecnolog\u00eda no existe todav\u00eda, pens\u00e9 que ser\u00eda interesante una c\u00e1mara que explore esta posibilidad\u00bb.<\/div>\n<div>Seg\u00fan dijo, not\u00f3 que mucha gente adopta un tono anal\u00edtico al describir fotograf\u00edas m\u00e1s all\u00e1 de ofrecer una emoci\u00f3n humana.<\/div>\n<div>\u00abHablan llanamente sobre ella, son muy subjetivos. No hacen un juicio de valor o dicen que es bonito o feo\u00bb, apunt\u00f3.<\/div>\n<div>\u00abCreo que quiz\u00e1s podr\u00eda guiar a la gente e invitarles a sentirse libres a la hora de expresar sus opiniones sobre ellas. Si algo es bonito, di que lo es\u00bb.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.bbc.co.uk\/\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un estudiante de Estados Unidos invent\u00f3 una c\u00e1mara capaz de describir im\u00e1genes. El aparato carga fotos en internet, que luego son descritas en cuesti\u00f3n de minutos por usuarios del servicio&nbsp;Mechanical&nbsp;Turk de Amazon. Luego la descripci\u00f3n se env\u00eda a la c\u00e1mara y \u00e9sta la imprime.<\/p>\n","protected":false},"author":3,"featured_media":16979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-16980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=16980"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/16980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/16979"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=16980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=16980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=16980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}