{"id":17141,"date":"2012-05-06T03:03:35","date_gmt":"2012-05-06T07:03:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/actividad-politica-online-paso-del-candidato-del-prd-ing-hipolito-mejia-por-sosua\/"},"modified":"2012-05-06T03:03:35","modified_gmt":"2012-05-06T07:03:35","slug":"actividad-politica-online-paso-del-candidato-del-prd-ing-hipolito-mejia-por-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/actividad-politica-online-paso-del-candidato-del-prd-ing-hipolito-mejia-por-sosua\/","title":{"rendered":"Actividad Pol\u00edtica Online: Paso del candidato del PRD, Ing. Hip\u00f3lito Mej\u00eda por Sos\u00faa (VER FOTOS Y VIDEOS)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17140\" style=\"float: left;\" alt=\"P1110053\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_P1110053.jpg\" width=\"634\" height=\"451\" \/>Sos\u00faa.- El candidato a la presidencia por el Partido Revolucionario Dominicano (PRD), Ing. Hip\u00f3lito Mej\u00eda, luego de un recorrido por la zona norte pas\u00f3 por Sos\u00faa aproximadamente a la 8:00 PM, donde fue recibido por sus seguidores.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Vean las fotos y video de esta actividad pol\u00edtica online\u2026<\/p>\n<p><object width=\"545\" height=\"355\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629975219705%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629975219705%2F&amp;set_id=72157629975219705&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"545\" height=\"355\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629975219705%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157629975219705%2F&amp;set_id=72157629975219705&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p><object width=\"545\" height=\"384\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"opaque\" \/><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/e8b1xoQxdTE\" \/><embed width=\"545\" height=\"384\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/e8b1xoQxdTE\" wmode=\"opaque\"\/><\/object><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- El candidato a la presidencia por el Partido Revolucionario Dominicano (PRD), Ing. Hip\u00f3lito Mej\u00eda, luego de un recorrido por la zona norte pas\u00f3 por Sos\u00faa aproximadamente a la 8:00 PM, donde fue recibido por sus seguidores.<\/p>\n","protected":false},"author":3,"featured_media":17140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17141"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17140"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}