{"id":17281,"date":"2012-05-13T22:25:41","date_gmt":"2012-05-14T02:25:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/galletas-suizas-de-pimienta\/"},"modified":"2012-05-13T22:25:41","modified_gmt":"2012-05-14T02:25:41","slug":"galletas-suizas-de-pimienta","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/galletas-suizas-de-pimienta\/","title":{"rendered":"Galletas suizas de pimienta"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17280\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_galletas_suizas_pimienta.jpg\" width=\"650\" height=\"445\" alt=\"galletas_suizas_pimienta\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_galletas_suizas_pimienta.jpg 650w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_galletas_suizas_pimienta-300x205.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_galletas_suizas_pimienta-75x52.jpg 75w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/>Aunque tienen variantes por otros pa\u00edses europeos, una&nbsp;<em>Pf\u00e4ffern\u00fcss<\/em>&nbsp;en Suiza es una bolita del tama\u00f1o de una nuez, con un t\u00edpico glaseado de lim\u00f3n que cubre un exterior duro y crujiente, ocultando el interior tierno y lleno de aromas. El toque de la pimienta debe ser muy sutil, lo justo para que aporte un matiz picante que potencie las dem\u00e1s especias.<\/p>\n<p>  <!--more-->  <\/p>\n<h2>Ingredientes para unas 30-40 galletas<\/h2>\n<ul>\n<li>250 gr de az\u00facar, 2 huevos L, 75 gr de almendra molida, 30 gr de naranja confitada picada, 1\/2 cucharadita de levadura qu\u00edmica (impulsor), 1 cucharadita de canela molida, 1\/8 cucharadita de nuez moscada molida, 1\/8 cucharadita de clavo molido, 1 pizca al gusto de pimienta blanca reci\u00e9n molida, 250 gr de harina.<\/li>\n<li>Para el glaseado: 70 gr de az\u00facar glas (lustre) tamizado, unas gotas de zumo de lim\u00f3n.<\/li>\n<\/ul>\n<h2>C\u00f3mo hacer galletas suizas de pimienta<\/h2>\n<p>Precalentar el horno a 190\u00baC y preparar una bandeja forr\u00e1ndola con papel sulfurizado.<br \/>En un recipiente grande,&nbsp;<strong>batir a mano los huevos con el az\u00facar hasta que empiecen a espumar<\/strong>. A\u00f1adir la naranja confitada, la&nbsp;<a href=\"http:\/\/www.directoalpaladar.com\/ingredientes\/frutas\/almendras\">almendra<\/a>&nbsp;molida, las especias y la levadura y mezclar un poco. Incorporar la harina y trabajar la masa hasta que quede homog\u00e9nea.<\/p>\n<p>Con las manos humedecidas,&nbsp;<strong>tomar peque\u00f1as porciones del tama\u00f1o de una nuez<\/strong>, formar bolitas y colocarlas en la bandeja, un poco separadas. Hornear durante unos 12-15 minutos, hasta que se hayan dorado bien. Mientras tanto, mezclar el az\u00facar con el zumo de&nbsp;<a href=\"http:\/\/www.directoalpaladar.com\/ingredientes\/frutas\/limon\">lim\u00f3n<\/a>&nbsp;hasta conseguir un glaseado ligeramente espeso.<\/p>\n<p>Una vez fuera del horno, a\u00fan en caliente y sobre su bandeja (para evitar manchar la superficie de trabajo),&nbsp;<strong>pintar las galletas con ayuda de un pincel<\/strong>. Dejar enfriar totalmente para que se seque el glaseado antes de guardar en un recipiente herm\u00e9tico.<\/p>\n<p><a href=\"http:\/\/www.directoalpaladar.com\/postres\/galletas-suizas-de-pimienta-receta\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque tienen variantes por otros pa\u00edses europeos, una&nbsp;Pf\u00e4ffern\u00fcss&nbsp;en Suiza es una bolita del tama\u00f1o de una nuez, con un t\u00edpico glaseado de lim\u00f3n que cubre un exterior duro y crujiente, ocultando el interior tierno y lleno de aromas. El toque de la pimienta debe ser muy sutil, lo justo para que aporte un matiz picante que potencie las dem\u00e1s especias.<\/p>\n","protected":false},"author":3,"featured_media":17280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17281"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17280"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}