{"id":17339,"date":"2012-05-17T15:50:12","date_gmt":"2012-05-17T19:50:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cientificos-producen-vacuna-contra-la-malaria-a-partir-de-las-algas\/"},"modified":"2012-05-17T15:50:12","modified_gmt":"2012-05-17T19:50:12","slug":"cientificos-producen-vacuna-contra-la-malaria-a-partir-de-las-algas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cientificos-producen-vacuna-contra-la-malaria-a-partir-de-las-algas\/","title":{"rendered":"Cient\u00edficos producen vacuna contra la malaria a partir de las algas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17338\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_Malaria-800x557.jpg\" width=\"800\" height=\"557\" alt=\"Malaria-800x557\" class=\"caption\" style=\"float: left;\" \/>Un conjunto de investigadores de la Universidad de San Diego han tenido \u00e9xito con la utilizaci\u00f3n de&nbsp;<strong><a href=\"http:\/\/phys.org\/news\/2012-05-biologists-potential-malarial-vaccine-algae.html\">algas para producir una vacuna que podr\u00eda prevenir la transmisi\u00f3n del par\u00e1sito que causa la malaria<\/a><\/strong>. Un hallazgo que podr\u00eda allanar el camino para el desarrollo econ\u00f3mico de un m\u00e9todo que proteja a millones de personas en el mundo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La malaria es una enfermedad transmitida por el mosquito causada por la&nbsp;<strong>infecci\u00f3n de par\u00e1sitos del g\u00e9nero&nbsp;<em>Plasmodium<\/em><\/strong>. Actualmente afecta a m\u00e1s de 225 millones de personas en todo el mundo en las regiones tropicales y subtropicales. La enfermedad da lugar a fiebre, dolores de cabeza y estados de coma y muerte en los casos m\u00e1s graves.<\/p>\n<p>Su dificultad radica en que, si bien existen una variedad de medicamentos contra la enfermedad muy costosos para aquellos que viajen a estas regiones, en la actualidad no hay vacunas que ofrezcan un nivel alto de protecci\u00f3n.<\/p>\n<p>Por ello los investigadores han buscado una soluci\u00f3n en el uso de algas que produzcan prote\u00ednas que creen anticuerpos contra el&nbsp;<em>Plasmodium<\/em>&nbsp;y eviten la transmisi\u00f3n. Ellos mismos cuentan que la dificultad para crear una vacuna contra la malaria es que requiere de un sistema de producci\u00f3n complejo, con prote\u00ednas que se asemejen a las realizadas por el par\u00e1sito. La mayor\u00eda requieren de un proceso muy caro que utiliza cultivos de c\u00e9lulas de mam\u00edferos.<\/p>\n<p>Seg\u00fan Stephen Mayfield, cient\u00edfico que encabez\u00f3 la investigaci\u00f3n:<\/p>\n<blockquote>\n<p>La malaria es causada por un par\u00e1sito que produce prote\u00ednas complejas, pero por alguna raz\u00f3n este par\u00e1sito no pone az\u00facar en esas prote\u00ednas. Si tenemos una prote\u00edna cubierta de az\u00facar y se realiza la inyecci\u00f3n en alguien como una vacuna, la tendencia es a producir anticuerpos contra los az\u00facares, no contra la columna vertebral de los amino\u00e1cidos de la prote\u00edna del organismo invasor que desea inhibir. Los investigadores han hecho las vacunas sin estos az\u00facares en las bacterias y luego han tratado de replegarse en una configuraci\u00f3n correcta tridimensional, pero eso es una propuesta costosa y no funciona muy bien.<\/p>\n<\/blockquote>\n<p>As\u00ed que los investigadores buscaron en la producci\u00f3n de prote\u00ednas con la ayuda de un&nbsp;<strong>alga verde comestible, la&nbsp;<em>Chlamydomonas reinhardtii<\/em><\/strong>, utilizada ampliamente en los laboratorios de investigaci\u00f3n como un organismo gen\u00e9tico. De hecho este m\u00e9todo llev\u00f3 a los bi\u00f3logos hace dos a\u00f1os a la publicaci\u00f3n de un estudio que conclu\u00eda que las&nbsp;<em>Chlamydomonas<\/em>&nbsp;pod\u00edan producir anticuerpos monoclonales y hormonas de crecimiento.<\/p>\n<p>Del estudio anterior parti\u00f3 esta nueva idea, la de producir un complejo de prote\u00ednas que protegieran contra el par\u00e1sito de la malaria a trav\u00e9s de la&nbsp;<em>Chlamydomonas<\/em>. La raz\u00f3n: el bajo coste que tendr\u00eda producir la prote\u00edna que inhibe las infecciones.<\/p>\n<blockquote>\n<p>Es demasiado costoso vacunar a millones de personas utilizando las tecnolog\u00edas actuales. Siendo realistas, la \u00fanica manera de vacunar contra la malaria es que se puedan producir a una fracci\u00f3n del costo de las vacunas actuales. Las algas tienen este potencial, ya que pueden crecer en cualquier lugar del planeta, en los estanques o incluso en una ba\u00f1era.<\/p>\n<\/blockquote>\n<p>Los primeros tests desarrollando la vacuna contra la malaria han demostrado que las prote\u00ednas producidas por algas, cuando se inyectan en ratones de laboratorio,&nbsp;<strong>producen que los anticuerpos bloqueen la transmisi\u00f3n de malaria<\/strong>.<\/p>\n<blockquote>\n<p>Este trabajo nos dice dos cosas: las prote\u00ednas que se hacen aqu\u00ed son candidatas viables a vacuna, y que por lo menos ahora tenemos la oportunidad de producir suficiente cantidad de esta vacuna y podemos pensar en la inoculaci\u00f3n de millones de personas. En ning\u00fan otro sistema podr\u00edamos empezar siquiera a pensar en eso.<\/p>\n<\/blockquote>\n<p>Los cient\u00edficos anuncian que a partir de aqu\u00ed comenzar\u00e1n los primeros ensayos en humanos con el fin de saber si act\u00faan por igual.<\/p>\n<p><a href=\"http:\/\/alt1040.com\/2012\/05\/cientificos-producen-vacuna-contra-la-malaria-a-partir-de-las-algas\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un conjunto de investigadores de la Universidad de San Diego han tenido \u00e9xito con la utilizaci\u00f3n de&nbsp;algas para producir una vacuna que podr\u00eda prevenir la transmisi\u00f3n del par\u00e1sito que causa la malaria. Un hallazgo que podr\u00eda allanar el camino para el desarrollo econ\u00f3mico de un m\u00e9todo que proteja a millones de personas en el mundo.<\/p>\n","protected":false},"author":3,"featured_media":17338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17339"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17338"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}