{"id":17377,"date":"2012-05-19T15:44:51","date_gmt":"2012-05-19T19:44:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/10-consejos-para-soportar-el-final-de-una-relacion-2\/"},"modified":"2012-05-19T15:44:51","modified_gmt":"2012-05-19T19:44:51","slug":"10-consejos-para-soportar-el-final-de-una-relacion-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-consejos-para-soportar-el-final-de-una-relacion-2\/","title":{"rendered":"10 Consejos para soportar el final de una relaci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17376\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_triste_por_rompimiento1.jpg\" width=\"236\" height=\"235\" alt=\"triste_por_rompimiento1\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_triste_por_rompimiento1.jpg 236w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_triste_por_rompimiento1-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_triste_por_rompimiento1-120x120.jpg 120w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>Cuando decidimos unir nuestra vida con la de quien ocupa todo nuestro coraz\u00f3n y con quien hemos hecho planes, pensamos que ser\u00e1 un amor para toda la vida. \u00bfPero qu\u00e9 entendemos por eso de<strong>&nbsp;\u201ctoda la vida\u201d?<\/strong>&nbsp;Creemos que pasaremos toda la vida juntos, comparti\u00e9ndolo todo hasta llegar a viejos\u2026 pero los a\u00f1os tienen muchos efectos y tambi\u00e9n consecuencias.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00bfQu\u00e9 pasa cuando el amor se desgasta?&nbsp;La rutina puede matar el amor,&nbsp;<strong>\u00bfc\u00f3mo hacer para no caer en la rutina?<\/strong><\/p>\n<p><strong><\/strong><\/p>\n<div>\n<div>Cuando nos enamoramos el sentimiento de amor se hace muy fuerte, as\u00ed como el sentimiento de posesi\u00f3n sobre la otra persona. No est\u00e1 en nuestros planes ni en el de nadie que un d\u00eda nuestra pareja se vaya de nuestro lado, sea por la razones que sea.<\/div>\n<\/p><\/div>\n<p>A muchas no les importa que sus parejas les enga\u00f1en, prefieren vivir enga\u00f1adas a ser olvidadas, ellas aman a su ex-pareja, y no les importa haber dejado de ser correspondidas mientras \u00e9l se mantenga junto a ella. Podr\u00edan vivir as\u00ed el resto de sus d\u00edas.<\/p>\n<p><strong>\u00bfPero qu\u00e9 pasa con el amor?<\/strong>&nbsp;Creo que las personas que no dejan ir a sus amores no aman de verdad, pues aunque les cueste hay que dejarles ir. Su felicidad debe estar por encima de la tuya propia, y contra el desamor no hay mucho que hacer. No se debe obligar a nadie estar juntos si el amor ya se ha ido, y es all\u00ed donde recuerdo estas frases:<em>&nbsp;\u201cSi amas a alguien, d\u00e9jalo ir. Si regresa a ti, es tuyo. Si no regresa, es que nunca lo fue\u201d.<\/em><\/p>\n<p>Recuerda siempre estos consejos para salir adelante y darte tu lugar, hay que ser dignas hasta el final del camino, no puedes ir llorando tus penas y mirarte al espejo dici\u00e9ndote que ya no sirves. No eres t\u00fa, es tu ex quien han escogido otro lugar como nido.<\/p>\n<p>Si por todos los medios has intentado retenerlo, debieras considerar que ha llegado la hora de pasar p\u00e1gina y salir adelante como muchas personas que a\u00fan con su coraz\u00f3n a pedazos son capaces de recogerlos y volver a re-comenzar sus vidas.<\/p>\n<p><strong>10 consejos para salir adelante despu\u00e9s de la separaci\u00f3n:<br \/><\/strong><\/p>\n<ol>\n<li><strong>No mendigues el amor,<\/strong>&nbsp;eso baja tu autoestima.<\/li>\n<li><strong>Amar es un acto voluntario,<\/strong>&nbsp;no obligatorio, nadie es propiedad de nadie, somos libres de elegir.<\/li>\n<li><strong>No llores por algo que se fue,<\/strong>&nbsp;seguro que no era para ti, piensa positivo.<\/li>\n<li><strong>No obligues<\/strong>&nbsp;a nadie a estar junto a otra por l\u00e1stima, eso es lo peor que podemos hacer.<\/li>\n<li>A la vuelta de la esquina siempre&nbsp;<strong>podr\u00e1s encontrar a alguien<\/strong>&nbsp;como t\u00fa, y buscando a alguien a quien amar.<\/li>\n<li>No te angusties con sentimientos de&nbsp;<strong>culpabilidad<\/strong>, no la tienes.&nbsp;Su amor no era fiel ni digno de confianza.<\/li>\n<li><strong>M\u00edrate,<\/strong>&nbsp;eres guapa, tienes inteligencia, dos manos\u2026 no te escondas, sal a la luz que todos los d\u00edas hay sorpresas en nuestras vidas.<\/li>\n<li><strong>\u00c1rmate de valor<\/strong>&nbsp;y haz cosas interesantes, cambia de look, no para volver a conquistarle sino para ti misma, porque si vuelve s\u00f3lo ser\u00e1 por sexo no por amor.<\/li>\n<li><strong>Eres m\u00e1s que un objeto,<\/strong>&nbsp;eres una maravillosa mujer, si no te supo valorar, \u00e9l se lo pierde, ten la seguridad que es as\u00ed.<\/li>\n<li><strong>Nunca<\/strong>&nbsp;las segundas partes fueron mejores, cuando te dejan porque ya no te aman \u00bfqu\u00e9 te hace suponer que el amor volver\u00e1?<\/li>\n<\/ol>\n<p>Y por \u00faltimo,&nbsp;<strong>nunca hay que culparse del fin de la relaci\u00f3n,<\/strong>&nbsp;es una cuesti\u00f3n de dos y lo \u00fanico que puedo asegurar es que el amor que no se cuida se desgasta.&nbsp;<em>El amor es igual que las flores, requieren de constantes cuidados y mimos, pero cuando mueren y se secan no hay agua que las levante.&nbsp;<\/em>Creo que no es sano seguir en ese circulo vicioso, rompe con tus cadenas y sal a la vida, a ver otros colores, otras vivencias\u2026 No te apagues, ciertamente tendr\u00e1s tu tiempo de tristeza, claro que s\u00ed, pero nada es eterno, ni siquiera el dolor que produce un amor. El tiempo siempre hace lo suyo y se empieza a vivir mejor y en forma saludable, conf\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando decidimos unir nuestra vida con la de quien ocupa todo nuestro coraz\u00f3n y con quien hemos hecho planes, pensamos que ser\u00e1 un amor para toda la vida. \u00bfPero qu\u00e9 entendemos por eso de&nbsp;\u201ctoda la vida\u201d?&nbsp;Creemos que pasaremos toda la vida juntos, comparti\u00e9ndolo todo hasta llegar a viejos\u2026 pero los a\u00f1os tienen muchos efectos y tambi\u00e9n consecuencias.<\/p>\n","protected":false},"author":3,"featured_media":17376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17377"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17376"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}