{"id":17581,"date":"2012-05-29T19:30:42","date_gmt":"2012-05-29T23:30:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/enrique-iglesias-renuncio-a-la-herencia-de-su-padre-julio-i\/"},"modified":"2012-05-29T19:30:42","modified_gmt":"2012-05-29T23:30:42","slug":"enrique-iglesias-renuncio-a-la-herencia-de-su-padre-julio-i","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/enrique-iglesias-renuncio-a-la-herencia-de-su-padre-julio-i\/","title":{"rendered":"Enrique Iglesias renunci\u00f3 a la herencia de su padre Julio I."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17580\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_get65646578898990w5e4.jpg\" width=\"619\" height=\"464\" alt=\"get65646578898990w5e4\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_get65646578898990w5e4.jpg 619w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_get65646578898990w5e4-300x224.jpg 300w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/>Es bien sabido que&nbsp;<a href=\"http:\/\/www.terra.com\/musica\/artistas\/e\/enriqueiglesias\/\">Enrique Iglesias<\/a>&nbsp;y Julio Iglesias, no se pueden ver ni en pintura. Tan grande ha sido su distanciamiento que no sostienen una conversaci\u00f3n ni por tel\u00e9fono.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>Lo curioso es que Julio Iglesias ha decidido heredar a su familia en vida, y Enrique ya dijo que no quer\u00eda recibir nada de su padre.<\/strong><o:p><\/o:p><\/p>\n<p>Julio que goza el t\u00edtulo del cantante m\u00e1s vendedor en espa\u00f1ol, con 300 millones de discos. Y con una fortuna valorada en $5.200 millones de d\u00f3lares en el a\u00f1o 2009. Fue muy distante con Enrique cuando comenz\u00f3 su carrera como cantante.<o:p><\/o:p><\/p>\n<p><strong>\u00abSu relaci\u00f3n con su padre nunca fue de las mejores, pasan a\u00f1os sin hablarse, ni por tel\u00e9fono. Enrique siente que forj\u00f3 su carrera sin la ayuda de \u00e9l\u00bb,&nbsp;<\/strong>asegur\u00f3 una fuente cercana a&nbsp;<a href=\"http:\/\/www.terra.com\/musica\/artistas\/e\/enriqueiglesias\/\">Enrique<\/a>.<o:p><\/o:p><\/p>\n<p>Al parece Julio sent\u00eda que su hijo solo ten\u00eda \u00e9xito gracias a su apellido. Por su parte,&nbsp;<a href=\"http:\/\/www.terra.com\/musica\/artistas\/e\/enriqueiglesias\/\">Enrique<\/a>&nbsp;ya hace parte de los 20 artistas con mayores ventas de discos en espa\u00f1ol y se encamina a hacer una gira con&nbsp;<a href=\"http:\/\/www.terra.com\/musica\/artistas\/j\/jenniferlopez\/\">Jennifer L\u00f3pez<\/a>.<o:p><\/o:p><\/p>\n<p>Por lo que no est\u00e1 interesado en las atrayentes propiedades de su padre que incluyen desde la tercera parte de Punta Cana en Rep\u00fablica Dominicana, incluido el aeropuerto, hasta una finca de 230 hect\u00e1reas en las Colinas de Marbella, donde se ve la costa africana. Aviones, autos y una cava hacen parte del patrimonio al que Enrique habr\u00eda renunciado tajantemente.<o:p><\/o:p><\/p>\n<p>\u00bfEst\u00e1s de acuerdo con la decisi\u00f3n de Enrique de renunciar a la herencia de su padre?<\/p>\n<p><a href=\"http:\/\/entretenimiento.terra.com\/chismes\/enrique-iglesias-renuncio-a-la-herencia-de-su-padre-julio-i,e3e91657fa997310VgnVCM4000009bcceb0aRCRD.html\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es bien sabido que&nbsp;Enrique Iglesias&nbsp;y Julio Iglesias, no se pueden ver ni en pintura. Tan grande ha sido su distanciamiento que no sostienen una conversaci\u00f3n ni por tel\u00e9fono.<\/p>\n","protected":false},"author":3,"featured_media":17580,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17581"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17580"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}