{"id":17754,"date":"2012-06-06T13:19:59","date_gmt":"2012-06-06T17:19:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-nuevo-protocolo-de-internet-ipv6-se-estrena-en-todo-el-mundo\/"},"modified":"2012-06-06T13:19:59","modified_gmt":"2012-06-06T17:19:59","slug":"el-nuevo-protocolo-de-internet-ipv6-se-estrena-en-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-nuevo-protocolo-de-internet-ipv6-se-estrena-en-todo-el-mundo\/","title":{"rendered":"El nuevo protocolo de Internet IPv6 se estrena en todo el mundo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17753\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_El-nuevo-protocolo-de-Internet-IPv6-se-estrena-en-todo-el-mundo.jpg\" width=\"600\" height=\"450\" alt=\"El-nuevo-protocolo-de-Internet-IPv6-se-estrena-en-todo-el-mundo\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_El-nuevo-protocolo-de-Internet-IPv6-se-estrena-en-todo-el-mundo.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_El-nuevo-protocolo-de-Internet-IPv6-se-estrena-en-todo-el-mundo-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>M\u00e1s de 2.500 proveedores de contenido web, 50 operadoras de telecomunicaciones y m\u00faltiples fabricantes de equipos de networking participan en el lanzamiento mundial de IPv6, una acci\u00f3n promovida por el organismo Internet Society (ISOC) para dar el salto definitivo a una nueva Internet.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El protocolo de Internet actual, IPv4, ha permitido el explosivo crecimiento que ha experimentado Internet en sus tres d\u00e9cadas de existencia. No obstante, los m\u00e1s de 4.000 millones de direcciones que tiene no han sido suficientes para satisfacer las demandas del mercado. Por ello se ha tenido que actualizar este protocolo con una nueva versi\u00f3n, IPv6, que ofrecer\u00e1 trillones de direcciones por cada persona en el planeta. Este \u00faltimo extiende la longitud de la direcci\u00f3n IP de 32 a 128 bits, aumentando de forma considerable el n\u00famero de direcciones IP disponibles. As\u00ed, se pasa de 4.295 millones de direcciones IP con el protocolo IPv4 a m\u00e1s de 340 sextillones de direcciones IP con el IPv6 (un sextill\u00f3n: 1.036). Esto permitir\u00e1 dar respuesta a la demanda que se espera de tr\u00e1fico IP global, que crece exponencialmente sobre todo por el auge del acceso a la Red a trav\u00e9s de dispositivos personales como smartphones y tablets.<\/p>\n<p>Compa\u00f1\u00edas como Google, Facebook, Cisco, Telef\u00f3nica, BT, D-Link y AT&amp;T, entre muchas otras participan en el World IPv6 Launch para dar el empuj\u00f3n definitivo al despliegue global del nuevo protocolo.<\/p>\n<p>Destaca especialmente en Espa\u00f1a la participaci\u00f3n de Telef\u00f3nica. La operadora participa en el IPv6 Launch Day con los primeros accesos piloto a sus redes de banda ancha fija y m\u00f3vil. Asimismo, ha ampliado los dominios web corporativos con IPv6 en Europa y Latinoam\u00e9rica.<\/p>\n<p>En este sentido, la operadora se adelanta a buena parte de los operadores en ambas regiones mediante despliegues de banda ancha fija en Espa\u00f1a y Per\u00fa y de banda ancha m\u00f3vil en M\u00e9xico. A partir del 6 de junio, el n\u00famero de accesos de estos despliegues ir\u00e1 creciendo hasta alcanzar el objetivo del 1% marcado por ISOC.<\/p>\n<p>Telef\u00f3nica I+D contribuye tambi\u00e9n con m\u00e1s usuarios reales en forma de puestos de trabajo al incorporar trabajadores de su centro en el parque tecnol\u00f3gico de Boecillo en Valladolid (Espa\u00f1a), que se suman a los del parque tecnol\u00f3gico de Walqa en Arag\u00f3n que ya participaron en 2011.<\/p>\n<p>La generalizaci\u00f3n de la disponibilidad de accesos IPv6 a las redes de Telef\u00f3nica se ir\u00e1 produciendo a lo largo del 2013 y a\u00f1os sucesivos, dependiendo de las previsiones de agotamiento del espacio de direcciones p\u00fablicas IPv4, diferentes por regi\u00f3n y pa\u00edses en los que opera.<\/p>\n<p>Adem\u00e1s, Telef\u00f3nica y Red.es est\u00e1n colaborando en el pr\u00f3ximo lanzamiento del CPD (Centro de Proceso de Datos y Servicios) \u00b4FI-WARE\u00b4, la mayor plataforma europea para experimentaci\u00f3n de servicios de Internet del Futuro, co-financiada por la Comisi\u00f3n Europea, que contar\u00e1 con soporte IPv6 desde el primer momento.<\/p>\n<p>Por su parte, Cisco har\u00e1, desde hoy, que su web www.cisco.com tenga el soporte de IPv6 activado por defecto indefinidamente, al igual que la gama de routers Linksys E-series para el hogar. No obstante, seg\u00fan Pilar Santamar\u00eda, directora de Desarrollo de Negocio para Borderless Networks en la regi\u00f3n Sur de Europa de Cisco \u201ca\u00fan queda mucho camino por recorrer. Aunque un importante n\u00famero de p\u00e1ginas web con una gran cantidad de tr\u00e1fico corran sobre IPv6 y muchos dispositivos sean compatibles por defecto, es necesario realizar una migraci\u00f3n paulatina hasta que podamos abandonar definitivamente el protocolo IPv4, por lo que el resto de empresas y proveedores de servicios y contenido deben sumarse a la migraci\u00f3n cuanto antes\u201d.<\/p>\n<p><a href=\"http:\/\/www.idg.es\/cio\/IPv6-se-estrena-en-todo-el-mundo\/doc122822-actualidad.htm\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 2.500 proveedores de contenido web, 50 operadoras de telecomunicaciones y m\u00faltiples fabricantes de equipos de networking participan en el lanzamiento mundial de IPv6, una acci\u00f3n promovida por el organismo Internet Society (ISOC) para dar el salto definitivo a una nueva Internet.<\/p>\n","protected":false},"author":3,"featured_media":17753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17754"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17753"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}