{"id":17929,"date":"2012-06-13T16:21:09","date_gmt":"2012-06-13T20:21:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/juegos-de-lucha-juegos-de-naves-juegos-de-disparos-ipor-que-se-encoge-la-ropa\/"},"modified":"2012-06-13T16:21:09","modified_gmt":"2012-06-13T20:21:09","slug":"juegos-de-lucha-juegos-de-naves-juegos-de-disparos-ipor-que-se-encoge-la-ropa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/juegos-de-lucha-juegos-de-naves-juegos-de-disparos-ipor-que-se-encoge-la-ropa\/","title":{"rendered":"\u00bfPor qu\u00e9 se encoge la ropa?"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17928\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_ropacolgada4657857965.jpg\" width=\"585\" height=\"390\" alt=\"ropacolgada4657857965\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_ropacolgada4657857965.jpg 585w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_ropacolgada4657857965-300x199.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>Lo habr\u00e1s escuchado en casa, tal vez despu\u00e9s de que tus padres saquen la ropa de la lavadora: \u00a1se ha encogido la camiseta! \u00a1Este jersey es m\u00e1s peque\u00f1o que antes! \u00a1los pantalones parecen de tu hermano peque\u00f1o! La ropa, espacielmante la de algod\u00f3n, puede encogerse cuando la lavas a temperatura templada.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Hay muchos tejidos que, para convertirse en ropa, son tensionados al m\u00e1ximo para que tengan la forma que se desea. As\u00ed se consiguen los polos, las camisas o los pantalones que tenemos. Sin embargo, al secarse despu\u00e9s de ser mojados, pierden esa tensi\u00f3n y se vuelven m\u00e1s cortos.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Cuando se le aplica una temperatura de entre 30 y 40 grados al algod\u00f3n, ya sea lav\u00e1ndola o planch\u00e1ndola al vapor, se encogen los tejidos, o m\u00e1s bien vuelven a su tama\u00f1o natural, m\u00e1s destensado. Lo mismo sucede con la lana, que siempre se encoge tras el primer lavado.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Esto ocurre con m\u00e1s raz\u00f3n todav\u00eda cuando usamos una secadora. Las secadoras le dan mucha temperatura a los tejidos y lo hacen muy r\u00e1pidamente. Si pudi\u00e9remos mirar con un microscopio, ver\u00edamos que los hilos est\u00e1n formados por part\u00edculas peque\u00e1s de un material llamado celulosa. Cuando lo mojamos, el agua une a la celulosa, pero si se seca de golpe, las fibras de celulosa no encuentran c\u00f3mo volver a unirse. Por eso es recomendable evitar lavar con agua caliente y s\u00ed con agua fr\u00eda.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.pequejuegos.com\/noticia-119374-446.html\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo habr\u00e1s escuchado en casa, tal vez despu\u00e9s de que tus padres saquen la ropa de la lavadora: \u00a1se ha encogido la camiseta! \u00a1Este jersey es m\u00e1s peque\u00f1o que antes! \u00a1los pantalones parecen de tu hermano peque\u00f1o! La ropa, espacielmante la de algod\u00f3n, puede encogerse cuando la lavas a temperatura templada.<\/p>\n","protected":false},"author":3,"featured_media":17928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-17929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17929"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17928"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}