{"id":17937,"date":"2012-06-13T20:42:58","date_gmt":"2012-06-14T00:42:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/fiestas-de-san-antonio-en-sosua-ver-fotos-y-video\/"},"modified":"2012-06-13T20:42:58","modified_gmt":"2012-06-14T00:42:58","slug":"fiestas-de-san-antonio-en-sosua-ver-fotos-y-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fiestas-de-san-antonio-en-sosua-ver-fotos-y-video\/","title":{"rendered":"Fiestas de San Antonio en Sos\u00faa [VER FOTOS]"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17936\" style=\"float: left;\" alt=\"resized_IMG_9514\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_resized_IMG_9514.jpg\" width=\"640\" height=\"426\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_resized_IMG_9514.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_resized_IMG_9514-300x199.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Los Charamicos, Sos\u00faa.- En el marco de las festividades patronales del municipio de Sos\u00faa, este d\u00eda 13 de junio, conmemoraci\u00f3n del d\u00eda de San Antonio, Patrono de este municipio fue celebrada una misa en la persona misma del Obispo de la Di\u00f3cesis de Puerto Plata, Monse\u00f1or Julio C\u00e9sar Corniel Amaro, ante la presencia de autoridades civiles y militaresy una gran multitud de fieles cat\u00f3licos.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Durante la misa de commemoraci\u00f3n la alcaldesa de Sos\u00faa, licenciada Ilana Neumann entreg\u00f3 junto a la concejal Angela de Jes\u00fas un pergamino a Monse\u00f1or Corniel Amaro en la que le declara como Hu\u00e9sped Distinguido del Municipio de Sos\u00faa.<\/p>\n<p>&nbsp;<object width=\"568\" height=\"335\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157630126979078%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157630126979078%2F&amp;set_id=72157630126979078&amp;jump_to=\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" \/><embed width=\"568\" height=\"335\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.flickr.com\/apps\/slideshow\/show.swf?v=109615\" flashvars=\"offsite=true&amp;lang=es-us&amp;page_show_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157630126979078%2Fshow%2F&amp;page_show_back_url=%2Fphotos%2Fsosuaonlinefull%2Fsets%2F72157630126979078%2F&amp;set_id=72157630126979078&amp;jump_to=\" allowFullScreen=\"true\"\/><\/object><\/p>\n<p>Al terminarla eucarist\u00eda hubo un desfile por las calles principales del pueblo con la banda de m\u00fasica del Comando Aereo Norte encabenzandole, mientras detr\u00e1s marchaban al ritmo de la banda los sacerdotes, presidentes de asamblea y feligreses, adem\u00e1s de la Alcaldesa y varios empleados municipales.<\/p>\n<p>Finalizando el acto ceremonial el Padre Bernardo V\u00e1squez destac\u00f3 el nombre de las festividades con el Lema \u00abTodos Unidos por Sos\u00faa\u00bb haciendo un llamado al trabajo en unidad por el bien del municipio.<\/p>\n<p> &gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Charamicos, Sos\u00faa.- En el marco de las festividades patronales del municipio de Sos\u00faa, este d\u00eda 13 de junio, conmemoraci\u00f3n del d\u00eda de San Antonio, Patrono de este municipio fue celebrada una misa en la persona misma del Obispo de la Di\u00f3cesis de Puerto Plata, Monse\u00f1or Julio C\u00e9sar Corniel Amaro, ante la presencia de autoridades civiles y militaresy una gran multitud de fieles cat\u00f3licos.<\/p>\n","protected":false},"author":3,"featured_media":17936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-17937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=17937"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/17937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17936"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=17937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=17937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=17937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}