{"id":18108,"date":"2012-06-21T15:55:07","date_gmt":"2012-06-21T19:55:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/windows-phone-8-renovacion-total-apostando-por-el-futuro-y-olvidando-el-pasado\/"},"modified":"2012-06-21T15:55:07","modified_gmt":"2012-06-21T19:55:07","slug":"windows-phone-8-renovacion-total-apostando-por-el-futuro-y-olvidando-el-pasado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/windows-phone-8-renovacion-total-apostando-por-el-futuro-y-olvidando-el-pasado\/","title":{"rendered":"Windows Phone 8, renovaci\u00f3n total apostando por el futuro y olvidando el pasado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18107\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_windowsphone8reface.jpg\" width=\"530\" height=\"298\" alt=\"windowsphone8reface\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_windowsphone8reface.jpg 530w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_windowsphone8reface-300x168.jpg 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/>El evento de ayer de&nbsp;<strong>Microsoft&nbsp;<\/strong>ha dejado un muy buen sabor de boca sobre el<strong>&nbsp;futuro de los smartphones con Windows Phone<\/strong>, ofreciendo un sistema operativo que va a poner en un serio aprieto la hegemon\u00eda de Android e iOS. Pero tambi\u00e9n lleva un toque amargo, que supondr\u00e1 el romper con lo anterior y que ning\u00fan tel\u00e9fono actual sea compatible con \u00e9l.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Windows Phone 7 supuso un cambio externo y de interfaz realmente radical con respecto a versiones anteriores, pero en su interior segu\u00eda basado en el arcaico Windows CE.<\/p>\n<p><strong>Con Apollo, Windows CE dice adi\u00f3s para siempre<\/strong>. La fragmentaci\u00f3n se disminuye enormemente y ahora ordenadores, tablets y smartphones comparten un mismo n\u00facleo,&nbsp;<strong>Windows NT<\/strong>. Esto permite una compatibilidad sin precedentes, aunque no ser\u00e1 directa y requerir\u00e1 unos cambios m\u00ednimos para cada plataforma.<\/p>\n<p>Pero esto ha obligado tambi\u00e9n a tomar una decisi\u00f3n, cuanto menos controvertida. Ning\u00fan tel\u00e9fono con WP7 o Mango, todos los actuales, podr\u00e1n actualizarse a Apollo. S\u00f3lo podr\u00e1n hacerlo a Windows Phone 7.8, que tendr\u00e1 mejoras menores pero que no ser\u00e1 compatible con las nuevas aplicaciones que surjan.<\/p>\n<p>De esta forma, Microsoft quiere acabar radicalmente con la fragmentaci\u00f3n a base de mobbing, en el que WP7 desparezca en breve debido al poco inter\u00e9s que tendr\u00e1 para los desarrolladores, ya que frente a \u00e9l tendr\u00e1n la posibilidad de crear aplicaciones multiplataforma.&nbsp;Aunque las aplicaciones que ya funcionaban en WP7 tambi\u00e9n lo har\u00e1n en WP8.<\/p>\n<p>Pero esta muestra de total deslealtad por parte de Microsoft&nbsp;a sus clientes,&nbsp;<strong>marcando cualquier smartphone Windows actual como obsoleto en unos meses<\/strong>, supuestamente se hace por un bien mayor. Adem\u00e1s prometen un m\u00ednimo de soporte para los nuevos terminales de 18 meses con actualizaciones en l\u00ednea.<\/p>\n<p>\u00bfEra necesario tomar esta decisi\u00f3n dr\u00e1stica para volver Windows Phone m\u00e1s competitivo y mostrar que la unificaci\u00f3n de plataformas en un sistema es el futuro? \u00bfSer\u00e1 esto un punto y aparte o veremos el mismo proceder en un futuro Windows 9?<\/p>\n<p><a href=\"http:\/\/www.gizmodo.es\/2012\/06\/21\/windows-phone-8-renovacion-total-apostando-por-el-futuro-y-olvidando-el-pasado.html\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento de ayer de&nbsp;Microsoft&nbsp;ha dejado un muy buen sabor de boca sobre el&nbsp;futuro de los smartphones con Windows Phone, ofreciendo un sistema operativo que va a poner en un serio aprieto la hegemon\u00eda de Android e iOS. Pero tambi\u00e9n lleva un toque amargo, que supondr\u00e1 el romper con lo anterior y que ning\u00fan tel\u00e9fono actual sea compatible con \u00e9l.<\/p>\n","protected":false},"author":3,"featured_media":18107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18108"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18107"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}