{"id":18114,"date":"2012-06-21T16:11:17","date_gmt":"2012-06-21T20:11:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/era-digital-idesaparecera-el-libro-impreso\/"},"modified":"2012-06-21T16:11:17","modified_gmt":"2012-06-21T20:11:17","slug":"era-digital-idesaparecera-el-libro-impreso","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/era-digital-idesaparecera-el-libro-impreso\/","title":{"rendered":"Era digital \u00a1Desaparecer\u00e1 el libro impreso!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-18113\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_libros-electrnicosssss435678.jpg\" width=\"237\" height=\"213\" alt=\"libros-electrnicosssss435678\" class=\"caption\" style=\"float: left;\" \/>Por primera vez en Estados Unidos la venta de libros digitales super\u00f3 en ganancias a la de los libros impresos, los llamados e-books o<strong>&nbsp;libros electr\u00f3nicos<\/strong>&nbsp;ya alcanzan el 30% de la venta de libros dado el mayor acceso que existe en la actualidad a dispositivos electr\u00f3nicos o lectores de libros digitales (eBook), que hacen de la lectura digital una tendencia cada vez m\u00e1s masiva y proyectan con m\u00e1s claridad la desaparici\u00f3n del libro f\u00edsico o impreso ya que la transmisi\u00f3n y la forma en la que compartiremos el conocimiento en el futuro ser\u00e1 de forma digital; por Internet, eBook, videos, multimedia, etc.<\/p>\n<p>  <!--more-->  <\/p>\n<p>He vivido la extraordinaria experiencia del uso del libro digital, libro electr\u00f3nico o eBook, que no es m\u00e1s que un libro convertido en un formato de archivo digital, donde el texto y las im\u00e1genes del mismo pueden manejarse muy f\u00e1cilmente por medio de computadoras y lectores de libros electr\u00f3nicos, que permiten leer un libro digitalizado con el mismo dise\u00f1o, color e intensidad de luz de su preferencia, ampliar las letras, buscar significados de palabras y hasta incluso si se cansa de leer, escuchar pl\u00e1cidamente como le van leyendo el libro.<\/p>\n<p>Esa contundente realidad del libro electr\u00f3nico, me ha hecho convencerme de que en un tiempo no especificado podr\u00e1 el libro electr\u00f3nico sustituir al libro impreso en papel, as\u00ed como las rocas dejaron de ser el medio donde las primeras civilizaciones plasmaron el alfabeto al preferir el Papiro, que luego evoluciona hasta el papel que conocemos hoy en d\u00eda, que gracias al desarrollo de la imprenta de Johannes Gutenberg, ha permitido la masificaci\u00f3n del lenguaje humano y ha convertido al libro impreso en el medio masivo de entrar en contacto con el conocimiento. Algo que a mi entender ha comenzado a cambiar en esta era digital, donde el mayor c\u00famulo de conocimiento humano est\u00e1 en formato digital, en grandes computadores (servidores) que almacenan la inmensidad de informaci\u00f3n que hay en la Internet, a trav\u00e9s de buscadores como Google. Muy diferente a lo que pasaba hasta finales del siglo XX donde el conocimiento humano reposaba en libros impresos. Es por ello que, as\u00ed como el peri\u00f3dico impreso ha perdido terreno frente al peri\u00f3dico digital en pa\u00edses del primer mundo, estoy convencido de que el libro electr\u00f3nico sustituir\u00e1 al libro impreso y por lo tanto desaparecer\u00e1, aun sea dentro de 100 a\u00f1os.<\/p>\n<p><a href=\"http:\/\/www.diariolibre.com\/noticias\/2012\/06\/21\/i340920_tecnologia-telecomunicaciones.html\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por primera vez en Estados Unidos la venta de libros digitales super\u00f3 en ganancias a la de los libros impresos, los llamados e-books o&nbsp;libros electr\u00f3nicos&nbsp;ya alcanzan el 30% de la venta de libros dado el mayor acceso que existe en la actualidad a dispositivos electr\u00f3nicos o lectores de libros digitales (eBook), que hacen de la lectura digital una tendencia cada vez m\u00e1s masiva y proyectan con m\u00e1s claridad la desaparici\u00f3n del libro f\u00edsico o impreso ya que la transmisi\u00f3n y la forma en la que compartiremos el conocimiento en el futuro ser\u00e1 de forma digital; por Internet, eBook, videos, multimedia, etc.<\/p>\n","protected":false},"author":3,"featured_media":18113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-18114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=18114"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/18114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/18113"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=18114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=18114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=18114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}